{"id":1491,"date":"2019-10-16T16:14:43","date_gmt":"2019-10-16T16:14:43","guid":{"rendered":"https:\/\/the7.io\/company\/?page_id=1491"},"modified":"2025-02-10T15:32:19","modified_gmt":"2025-02-10T21:32:19","slug":"blog","status":"publish","type":"page","link":"https:\/\/fss.gob.gt\/es\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column css=\u00bb.vc_custom_1575296582826{padding-bottom: 30px !important;}\u00bb]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on.classic-layout-list article {\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on.classic-layout-list article:first-of-type {\n  margin-top: 0;\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.classic-layout-list.mode-list .post-entry-content {\n  width: calc(100% - );\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.classic-layout-list.mode-list .no-img .post-entry-content {\n  width: 100%;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .filter-bg-decoration .filter-categories a.act {\n  color: #fff;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on:not(.mode-masonry) article {\n  margin-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-thumbnail-wrap {\n  padding: 0px 0px 0px 0px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.enable-bg-rollover .post-thumbnail-rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n  color: #ffffff;\n}\n.bottom-overlap-layout-list.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico {\n  margin-top: -72px;\n}\n.gradient-overlay-layout-list.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico,\n.content-rollover-layout-list.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico {\n  margin: 0 0 10px;\n}\n.content-align-center.gradient-overlay-layout-list.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico,\n.content-align-center.content-rollover-layout-list.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico {\n  margin: 0 auto 10px;\n}\n.dt-icon-bg-on.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico > span,\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico:before {\n  font-size: 32px;\n  line-height: 44px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico > span,\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .gallery-zoom-ico:before {\n  color: #ffffff;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-title,\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.owl-carousel .entry-title {\n  margin-bottom: 10px;\n  font-size: 34px;\n  line-height: 44px;\n  font-weight: bold;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-meta {\n  margin-bottom: 15px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-meta * {\n  font-size: 14px;\n  line-height: 24px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .portfolio-categories {\n  margin-bottom: 15px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-excerpt {\n  margin-bottom: 10px;\n  font-size: 16px;\n  line-height: 28px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.centered-layout-list) .post-entry-content {\n  padding: 25px 30px 30px 30px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.centered-layout-list):not(.content-bg-on):not(.mode-list) .no-img .post-entry-content {\n  padding: 0;\n}\n@media screen and (max-width: ) {\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f article {\n    -ms-flex-flow: column nowrap;\n    flex-flow: column nowrap;\n    margin-top: 20px;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on article {\n    border: none;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.content-bg-on.centered-layout-list article {\n    padding: 0;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.blog-shortcode.dividers-on article,\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on.classic-layout-list article {\n    margin-top: 20px;\n    padding: 0;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.blog-shortcode.dividers-on article:first-of-type,\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.dividers-on.classic-layout-list article:first-of-type {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-entry-content {\n    width: 100%;\n    margin: 0;\n    top: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-thumbnail-wrap {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-entry-content:after {\n    display: none;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .project-even .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.centered-layout-list .post-thumbnail-wrap {\n    -ms-flex-order: 0;\n    order: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.centered-layout-list .post-entry-title-content {\n    -ms-flex-order: 1;\n    order: 1;\n    width: 100%;\n    padding: 20px 20px 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.centered-layout-list .post-entry-content {\n    -ms-flex-order: 2;\n    order: 2;\n    padding-top: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .fancy-categories {\n    top: 10px;\n    left: 10px;\n    bottom: auto;\n    right: auto;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .fancy-date a {\n    top: 10px;\n    right: 10px;\n    left: auto;\n    bottom: auto;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-entry-content {\n    padding: 20px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-title {\n    margin: 3px 0 5px;\n    font-size: 20px;\n    line-height: 26px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-meta {\n    margin: 5px 0 5px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .entry-excerpt {\n    margin: 15px 0 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-details {\n    margin: 5px 0 10px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f .post-details.details-type-link {\n    margin-bottom: 2px;\n  }\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid {\n  grid-row-gap: 30px;\n  grid-column-gap: 30px;\n  grid-template-columns: repeat(auto-fill,minmax(,1fr));\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid,\n.no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid {\n  display: flex;\n  flex-flow: row wrap;\n  margin: -15px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid .wf-cell,\n.no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f:not(.resize-by-browser-width) .dt-css-grid .wf-cell {\n  flex: 1 0 ;\n  max-width: 100%;\n  padding: 15px;\n  box-sizing: border-box;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid {\n  grid-template-columns: repeat(1,1fr);\n  grid-template-rows: auto;\n  grid-column-gap: 30px;\n  grid-row-gap: 30px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid {\n  margin: -15px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell {\n  width: 100%;\n  padding: 15px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n  width: calc(100%) * 2;\n}\n.blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width:not(.centered-layout-list):not(.content-bg-on) .dt-css-grid {\n  grid-row-gap: 0px;\n}\n@media screen and (max-width: 1199px) {\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(1,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 100%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(100%)*2;\n  }\n}\n@media screen and (max-width: 991px) {\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(1,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 100%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(100%)*2;\n  }\n}\n@media screen and (max-width: 767px) {\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(1,1fr);\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .double-width {\n    grid-column: span 1;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 100%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(100%)*2;\n  }\n}\n<\/style><div class=\"blog-shortcode blog-masonry-shortcode-id-d9f10a7f387213f7ea183fb4c6f35f8f mode-grid classic-layout-list content-bg-on jquery-filter vertical-fancy-style dt-css-grid-wrap dt-icon-bg-off resize-by-browser-width loading-effect-none description-under-image \" data-padding=\"15px\" data-cur-page=\"1\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-desktop-columns-num=\"1\" data-v-tablet-columns-num=\"1\" data-h-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-width=\"0px\" data-columns=\"0\"><div class=\"dt-css-grid\" ><div class=\"visible wf-cell\" data-post-id=\"8149\" data-date=\"2026-06-08T16:40:59-06:00\" data-name=\"Inauguran puente que esper\u00f3 m\u00e1s de 16 a\u00f1os la poblaci\u00f3n de El J\u00edcaro\"><article class=\"post project-odd visible post-8149 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones category-20\" data-name=\"Inauguran puente que esper\u00f3 m\u00e1s de 16 a\u00f1os la poblaci\u00f3n de El J\u00edcaro\" data-date=\"2026-06-08T16:40:59-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t<span class=\"fancy-categories\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" rel=\"category tag\" style=\"background-color:#;color:#;\">Noticias<\/a><\/span>\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/06\/08\/inauguran-puente-que-espero-mas-de-16-anos-la-poblacion-de-el-jicaro\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img fetchpriority=\"high\" decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20495&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/06\/image-1-990x495.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/06\/image-1-990x495.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/06\/image-1-1440x720.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 495\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"495\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/06\/08\/inauguran-puente-que-espero-mas-de-16-anos-la-poblacion-de-el-jicaro\/\" title=\"Inauguran puente que esper\u00f3 m\u00e1s de 16 a\u00f1os la poblaci\u00f3n de El J\u00edcaro\" rel=\"bookmark\">Inauguran puente que esper\u00f3 m\u00e1s de 16 a\u00f1os la poblaci\u00f3n de El J\u00edcaro<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2026\/06\/08\/\" title=\"4:40 pm\" class=\"data-link\" rel=\"bookmark\"><time class=\"entry-date updated\" datetime=\"2026-06-08T16:40:59-06:00\">junio 8, 2026<\/time><\/a><\/div>\n\t<div class=\"entry-excerpt\"><p>Con la participaci\u00f3n de autoridades del estado, representantes del Congreso de la Rep\u00fablica, autoridades municipales, del Fondo Social de Solidaridad (FSS) y vecinos de la comunidad, fue inaugurado el nuevo puente de ingreso a El J\u00edcaro, El Progreso, una obra esperada por m\u00e1s de 16 a\u00f1os. La infraestructura, construida sobre el r\u00edo Motagua, cuenta con&hellip;<\/p>\n<\/div>\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/06\/08\/inauguran-puente-que-espero-mas-de-16-anos-la-poblacion-de-el-jicaro\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Inauguran puente que esper\u00f3 m\u00e1s de 16 a\u00f1os la poblaci\u00f3n de El J\u00edcaro\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><\/div>[\/vc_column][vc_column]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on.classic-layout-list article {\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on.classic-layout-list article:first-of-type {\n  margin-top: 0;\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.classic-layout-list.mode-list .post-entry-content {\n  width: calc(100% - );\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.classic-layout-list.mode-list .no-img .post-entry-content {\n  width: 100%;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .filter-bg-decoration .filter-categories a.act {\n  color: #fff;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on:not(.mode-masonry) article {\n  margin-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n  padding-top: 0;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-thumbnail-wrap {\n  padding: 0px 0px 0px 0px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.enable-bg-rollover .post-thumbnail-rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n  color: #ffffff;\n}\n.bottom-overlap-layout-list.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico {\n  margin-top: -72px;\n}\n.gradient-overlay-layout-list.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico,\n.content-rollover-layout-list.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico {\n  margin: 0 0 10px;\n}\n.content-align-center.gradient-overlay-layout-list.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico,\n.content-align-center.content-rollover-layout-list.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico {\n  margin: 0 auto 10px;\n}\n.dt-icon-bg-on.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico > span,\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico:before {\n  font-size: 32px;\n  line-height: 44px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico > span,\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .gallery-zoom-ico:before {\n  color: #ffffff;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-title,\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.owl-carousel .entry-title {\n  margin-bottom: 10px;\n  font-size: 20px;\n  line-height: 30px;\n  font-weight: bold;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-meta {\n  margin-bottom: 20px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-meta * {\n  font-size: 14px;\n  line-height: 24px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .portfolio-categories {\n  margin-bottom: 20px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-excerpt {\n  margin-bottom: 5px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.centered-layout-list) .post-entry-content {\n  padding: 25px 30px 30px 30px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.centered-layout-list):not(.content-bg-on):not(.mode-list) .no-img .post-entry-content {\n  padding: 0;\n}\n@media screen and (max-width: ) {\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 article {\n    -ms-flex-flow: column nowrap;\n    flex-flow: column nowrap;\n    margin-top: 20px;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on article {\n    border: none;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.content-bg-on.centered-layout-list article {\n    padding: 0;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.blog-shortcode.dividers-on article,\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on.classic-layout-list article {\n    margin-top: 20px;\n    padding: 0;\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.blog-shortcode.dividers-on article:first-of-type,\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.dividers-on.classic-layout-list article:first-of-type {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-entry-content {\n    width: 100%;\n    margin: 0;\n    top: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-thumbnail-wrap {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-entry-content:after {\n    display: none;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .project-even .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.centered-layout-list .post-thumbnail-wrap {\n    -ms-flex-order: 0;\n    order: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.centered-layout-list .post-entry-title-content {\n    -ms-flex-order: 1;\n    order: 1;\n    width: 100%;\n    padding: 20px 20px 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.centered-layout-list .post-entry-content {\n    -ms-flex-order: 2;\n    order: 2;\n    padding-top: 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .fancy-categories {\n    top: 10px;\n    left: 10px;\n    bottom: auto;\n    right: auto;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .fancy-date a {\n    top: 10px;\n    right: 10px;\n    left: auto;\n    bottom: auto;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-entry-content {\n    padding: 20px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-title {\n    margin: 3px 0 5px;\n    font-size: 20px;\n    line-height: 26px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-meta {\n    margin: 5px 0 5px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .entry-excerpt {\n    margin: 15px 0 0;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-details {\n    margin: 5px 0 10px;\n  }\n  #page .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 .post-details.details-type-link {\n    margin-bottom: 2px;\n  }\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid {\n  grid-row-gap: 60px;\n  grid-column-gap: 60px;\n  grid-template-columns: repeat(auto-fill,minmax(,1fr));\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid,\n.no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid {\n  display: flex;\n  flex-flow: row wrap;\n  margin: -30px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid .wf-cell,\n.no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687:not(.resize-by-browser-width) .dt-css-grid .wf-cell {\n  flex: 1 0 ;\n  max-width: 100%;\n  padding: 30px;\n  box-sizing: border-box;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid {\n  grid-template-columns: repeat(2,1fr);\n  grid-template-rows: auto;\n  grid-column-gap: 60px;\n  grid-row-gap: 60px;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid {\n  margin: -30px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell {\n  width: 50%;\n  padding: 30px;\n}\n.cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n  width: calc(50%) * 2;\n}\n.blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width:not(.centered-layout-list):not(.content-bg-on) .dt-css-grid {\n  grid-row-gap: 30px;\n}\n@media screen and (max-width: 1199px) {\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(2,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 50%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(50%)*2;\n  }\n}\n@media screen and (max-width: 991px) {\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(1,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 100%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(100%)*2;\n  }\n}\n@media screen and (max-width: 767px) {\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(1,1fr);\n  }\n  .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .double-width {\n    grid-column: span 1;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 100%;\n  }\n  .cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .blog-shortcode.blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(100%)*2;\n  }\n}\n<\/style><div class=\"blog-shortcode blog-masonry-shortcode-id-bdaf4ab3d29c3ef8626859bfcc716687 mode-grid classic-layout-list content-bg-on jquery-filter vertical-fancy-style content-align-center dt-css-grid-wrap dt-icon-bg-off resize-by-browser-width loading-effect-none description-under-image \" data-padding=\"30px\" data-cur-page=\"1\" data-post-limit=\"6\" data-pagination-mode=\"load-more\" aria-live=\"assertive\" data-desktop-columns-num=\"2\" data-v-tablet-columns-num=\"1\" data-h-tablet-columns-num=\"2\" data-phone-columns-num=\"1\" data-width=\"0px\" data-columns=\"0\"><div class=\"dt-css-grid\" ><div class=\"visible wf-cell\" data-post-id=\"8108\" data-date=\"2026-05-25T15:36:36-06:00\" data-name=\"Carretera en Balany\u00e1 impulsa la producci\u00f3n y mejora la movilidad en la comunidad\"><article class=\"post project-odd visible post-8108 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Carretera en Balany\u00e1 impulsa la producci\u00f3n y mejora la movilidad en la comunidad\" data-date=\"2026-05-25T15:36:36-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/25\/carretera-en-balanya-impulsa-la-produccion-y-mejora-la-movilidad-en-la-comunidad\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-13-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-13-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-13-1438x897.jpeg 1438w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/25\/carretera-en-balanya-impulsa-la-produccion-y-mejora-la-movilidad-en-la-comunidad\/\" title=\"Carretera en Balany\u00e1 impulsa la producci\u00f3n y mejora la movilidad en la comunidad\" rel=\"bookmark\">Carretera en Balany\u00e1 impulsa la producci\u00f3n y mejora la movilidad en la comunidad<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/25\/carretera-en-balanya-impulsa-la-produccion-y-mejora-la-movilidad-en-la-comunidad\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Carretera en Balany\u00e1 impulsa la producci\u00f3n y mejora la movilidad en la comunidad\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"8116\" data-date=\"2026-05-19T16:04:19-06:00\" data-name=\"Finalizan trabajos de mejoramiento en camino rural de San Pedro Yepocapa\"><article class=\"post project-odd visible post-8116 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Finalizan trabajos de mejoramiento en camino rural de San Pedro Yepocapa\" data-date=\"2026-05-19T16:04:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/19\/finalizan-trabajos-de-mejoramiento-en-camino-rural-de-san-pedro-yepocapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-19-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-19-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-19-1438x897.jpeg 1438w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/19\/finalizan-trabajos-de-mejoramiento-en-camino-rural-de-san-pedro-yepocapa\/\" title=\"Finalizan trabajos de mejoramiento en camino rural de San Pedro Yepocapa\" rel=\"bookmark\">Finalizan trabajos de mejoramiento en camino rural de San Pedro Yepocapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/19\/finalizan-trabajos-de-mejoramiento-en-camino-rural-de-san-pedro-yepocapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Finalizan trabajos de mejoramiento en camino rural de San Pedro Yepocapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"8124\" data-date=\"2026-05-16T16:09:42-06:00\" data-name=\"Finaliza fundici\u00f3n de rampa en el Paso a Desnivel de la Calzada Roosevelt\"><article class=\"post project-odd visible post-8124 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-guatemala tag-noticias tag-operaciones category-20 description-off\" data-name=\"Finaliza fundici\u00f3n de rampa en el Paso a Desnivel de la Calzada Roosevelt\" data-date=\"2026-05-16T16:09:42-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/16\/finaliza-fundicion-de-rampa-en-el-paso-a-desnivel-de-la-calzada-roosevelt\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-25-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-25-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-25-1297x810.jpeg 1297w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/16\/finaliza-fundicion-de-rampa-en-el-paso-a-desnivel-de-la-calzada-roosevelt\/\" title=\"Finaliza fundici\u00f3n de rampa en el Paso a Desnivel de la Calzada Roosevelt\" rel=\"bookmark\">Finaliza fundici\u00f3n de rampa en el Paso a Desnivel de la Calzada Roosevelt<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/16\/finaliza-fundicion-de-rampa-en-el-paso-a-desnivel-de-la-calzada-roosevelt\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Finaliza fundici\u00f3n de rampa en el Paso a Desnivel de la Calzada Roosevelt\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"8130\" data-date=\"2026-05-12T16:18:22-06:00\" data-name=\"El Gobierno de Guatemala impulsa el desarrollo del norte del pa\u00eds\"><article class=\"post project-odd visible post-8130 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"El Gobierno de Guatemala impulsa el desarrollo del norte del pa\u00eds\" data-date=\"2026-05-12T16:18:22-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/12\/el-gobierno-de-guatemala-impulsa-el-desarrollo-del-norte-del-pais\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-30-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-30-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-30-1279x798.jpeg 1279w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/12\/el-gobierno-de-guatemala-impulsa-el-desarrollo-del-norte-del-pais\/\" title=\"El Gobierno de Guatemala impulsa el desarrollo del norte del pa\u00eds\" rel=\"bookmark\">El Gobierno de Guatemala impulsa el desarrollo del norte del pa\u00eds<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/12\/el-gobierno-de-guatemala-impulsa-el-desarrollo-del-norte-del-pais\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El Gobierno de Guatemala impulsa el desarrollo del norte del pa\u00eds\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"8069\" data-date=\"2026-05-02T16:16:57-06:00\" data-name=\"FSS realiza dotaci\u00f3n de materiales en Aldea Pacorral, Tecp\u00e1n Guatemala\"><article class=\"post project-odd visible post-8069 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-noticias category-20 description-off\" data-name=\"FSS realiza dotaci\u00f3n de materiales en Aldea Pacorral, Tecp\u00e1n Guatemala\" data-date=\"2026-05-02T16:16:57-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/02\/fss-realiza-dotacion-de-materiales-en-aldea-pacorral-tecpan-guatemala\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-1-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/02\/fss-realiza-dotacion-de-materiales-en-aldea-pacorral-tecpan-guatemala\/\" title=\"FSS realiza dotaci\u00f3n de materiales en Aldea Pacorral, Tecp\u00e1n Guatemala\" rel=\"bookmark\">FSS realiza dotaci\u00f3n de materiales en Aldea Pacorral, Tecp\u00e1n Guatemala<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/05\/02\/fss-realiza-dotacion-de-materiales-en-aldea-pacorral-tecpan-guatemala\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about FSS realiza dotaci\u00f3n de materiales en Aldea Pacorral, Tecp\u00e1n Guatemala\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"8060\" data-date=\"2026-04-29T16:06:00-06:00\" data-name=\"Capacitaci\u00f3n en Comunicaci\u00f3n Asertiva: trabajando mejor juntos\"><article class=\"post project-odd visible post-8060 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Capacitaci\u00f3n en Comunicaci\u00f3n Asertiva: trabajando mejor juntos\" data-date=\"2026-04-29T16:06:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/29\/capacitacion-en-comunicacion-asertiva-trabajando-mejor-juntos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-4-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-4-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/05\/image-4-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/29\/capacitacion-en-comunicacion-asertiva-trabajando-mejor-juntos\/\" title=\"Capacitaci\u00f3n en Comunicaci\u00f3n Asertiva: trabajando mejor juntos\" rel=\"bookmark\">Capacitaci\u00f3n en Comunicaci\u00f3n Asertiva: trabajando mejor juntos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/29\/capacitacion-en-comunicacion-asertiva-trabajando-mejor-juntos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Capacitaci\u00f3n en Comunicaci\u00f3n Asertiva: trabajando mejor juntos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"8042\" data-date=\"2026-04-20T15:48:06-06:00\" data-name=\"Impulsamos el desarrollo de la Zona Reina a trav\u00e9s del mantenimiento vial\"><article class=\"post project-odd visible post-8042 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-quiche tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"Impulsamos el desarrollo de la Zona Reina a trav\u00e9s del mantenimiento vial\" data-date=\"2026-04-20T15:48:06-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/20\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-15-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-15-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-15-1440x899.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/20\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas\/\" title=\"Impulsamos el desarrollo de la Zona Reina a trav\u00e9s del mantenimiento vial\" rel=\"bookmark\">Impulsamos el desarrollo de la Zona Reina a trav\u00e9s del mantenimiento vial<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/20\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Impulsamos el desarrollo de la Zona Reina a trav\u00e9s del mantenimiento vial\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"8058\" data-date=\"2026-04-14T16:51:33-06:00\" data-name=\"Inician mejoramiento de camino rural en Pachalum que beneficiar\u00e1 a m\u00e1s de 14 mil personas\"><article class=\"post project-odd visible post-8058 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-operaciones tag-quiche category-20 description-off\" data-name=\"Inician mejoramiento de camino rural en Pachalum que beneficiar\u00e1 a m\u00e1s de 14 mil personas\" data-date=\"2026-04-14T16:51:33-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/14\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-11-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-11-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-11-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/14\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas-2\/\" title=\"Inician mejoramiento de camino rural en Pachalum que beneficiar\u00e1 a m\u00e1s de 14 mil personas\" rel=\"bookmark\">Inician mejoramiento de camino rural en Pachalum que beneficiar\u00e1 a m\u00e1s de 14 mil personas<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/04\/14\/inician-mejoramiento-de-camino-rural-en-pachalum-que-beneficiara-a-mas-de-14-mil-personas-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Inician mejoramiento de camino rural en Pachalum que beneficiar\u00e1 a m\u00e1s de 14 mil personas\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7963\" data-date=\"2026-03-21T11:19:28-06:00\" data-name=\"Inician trabajos de mejoramiento vial en Nuevo Texcuaco, La Gomera\"><article class=\"post project-odd visible post-7963 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-escuintla tag-noticias tag-operaciones category-20 description-off\" data-name=\"Inician trabajos de mejoramiento vial en Nuevo Texcuaco, La Gomera\" data-date=\"2026-03-21T11:19:28-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/03\/21\/inician-trabajos-de-mejoramiento-vial-en-nuevo-texcuaco-la-gomera\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20900%20561&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/03\/image-2-900x561.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/03\/image-2-900x561.jpeg 900w\" loading=\"eager\" style=\"--ratio: 900 \/ 561\" sizes=\"(max-width: 900px) 100vw, 900px\" alt=\"\" title=\"image\" width=\"900\" height=\"561\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/03\/21\/inician-trabajos-de-mejoramiento-vial-en-nuevo-texcuaco-la-gomera\/\" title=\"Inician trabajos de mejoramiento vial en Nuevo Texcuaco, La Gomera\" rel=\"bookmark\">Inician trabajos de mejoramiento vial en Nuevo Texcuaco, La Gomera<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/03\/21\/inician-trabajos-de-mejoramiento-vial-en-nuevo-texcuaco-la-gomera\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Inician trabajos de mejoramiento vial en Nuevo Texcuaco, La Gomera\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"8015\" data-date=\"2026-01-29T14:51:56-06:00\" data-name=\"Mejores caminos rurales para el trabajo diario de las familias de San Pedro Jocopilas\"><article class=\"post project-odd visible post-8015 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-quiche tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"Mejores caminos rurales para el trabajo diario de las familias de San Pedro Jocopilas\" data-date=\"2026-01-29T14:51:56-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/29\/mejores-caminos-rurales-para-el-trabajo-diario-de-las-familias-de-san-pedro-jocopilas\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-4-990x619.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-4-990x619.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-4-1362x852.jpeg 1362w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/29\/mejores-caminos-rurales-para-el-trabajo-diario-de-las-familias-de-san-pedro-jocopilas\/\" title=\"Mejores caminos rurales para el trabajo diario de las familias de San Pedro Jocopilas\" rel=\"bookmark\">Mejores caminos rurales para el trabajo diario de las familias de San Pedro Jocopilas<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/29\/mejores-caminos-rurales-para-el-trabajo-diario-de-las-familias-de-san-pedro-jocopilas\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejores caminos rurales para el trabajo diario de las familias de San Pedro Jocopilas\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"8008\" data-date=\"2026-01-26T14:38:50-06:00\" data-name=\"Los trabajos actuales se concentran en la rampa de ingreso del puente de El J\u00edcaro\"><article class=\"post project-odd visible post-8008 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Los trabajos actuales se concentran en la rampa de ingreso del puente de El J\u00edcaro\" data-date=\"2026-01-26T14:38:50-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/26\/los-trabajos-actuales-se-concentran-en-la-rampa-de-ingreso-del-puente-de-el-jicaro\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/04\/image-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/26\/los-trabajos-actuales-se-concentran-en-la-rampa-de-ingreso-del-puente-de-el-jicaro\/\" title=\"Los trabajos actuales se concentran en la rampa de ingreso del puente de El J\u00edcaro\" rel=\"bookmark\">Los trabajos actuales se concentran en la rampa de ingreso del puente de El J\u00edcaro<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/26\/los-trabajos-actuales-se-concentran-en-la-rampa-de-ingreso-del-puente-de-el-jicaro\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Los trabajos actuales se concentran en la rampa de ingreso del puente de El J\u00edcaro\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7907\" data-date=\"2026-01-02T16:21:26-06:00\" data-name=\"Paso a desnivel de la Calzada Roosevelt muestra avances s\u00f3lidos tras reactivaci\u00f3n de trabajos\"><article class=\"post project-odd visible post-7907 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-guatemala tag-noticias tag-operaciones category-20 description-off\" data-name=\"Paso a desnivel de la Calzada Roosevelt muestra avances s\u00f3lidos tras reactivaci\u00f3n de trabajos\" data-date=\"2026-01-02T16:21:26-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/02\/paso-a-desnivel-de-la-calzada-roosevelt-muestra-avances-solidos-tras-reactivacion-de-trabajos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20449&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/01\/image-2-720x449.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2026\/01\/image-2-720x449.jpeg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 449\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"image\" width=\"720\" height=\"449\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/02\/paso-a-desnivel-de-la-calzada-roosevelt-muestra-avances-solidos-tras-reactivacion-de-trabajos\/\" title=\"Paso a desnivel de la Calzada Roosevelt muestra avances s\u00f3lidos tras reactivaci\u00f3n de trabajos\" rel=\"bookmark\">Paso a desnivel de la Calzada Roosevelt muestra avances s\u00f3lidos tras reactivaci\u00f3n de trabajos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2026\/01\/02\/paso-a-desnivel-de-la-calzada-roosevelt-muestra-avances-solidos-tras-reactivacion-de-trabajos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Paso a desnivel de la Calzada Roosevelt muestra avances s\u00f3lidos tras reactivaci\u00f3n de trabajos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7855\" data-date=\"2025-12-08T16:37:11-06:00\" data-name=\"CIV trabaja con autoridades locales y poblaci\u00f3n para desarrollar proyectos en Quich\u00e9\"><article class=\"post project-odd visible post-7855 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-quiche category-20 description-off\" data-name=\"CIV trabaja con autoridades locales y poblaci\u00f3n para desarrollar proyectos en Quich\u00e9\" data-date=\"2025-12-08T16:37:11-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/08\/civ-trabaja-con-autoridades-locales-y-poblacion-para-desarrollar-proyectos-en-quiche\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-24-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-24-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-24-1441x900.jpeg 1441w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/08\/civ-trabaja-con-autoridades-locales-y-poblacion-para-desarrollar-proyectos-en-quiche\/\" title=\"CIV trabaja con autoridades locales y poblaci\u00f3n para desarrollar proyectos en Quich\u00e9\" rel=\"bookmark\">CIV trabaja con autoridades locales y poblaci\u00f3n para desarrollar proyectos en Quich\u00e9<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/08\/civ-trabaja-con-autoridades-locales-y-poblacion-para-desarrollar-proyectos-en-quiche\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about CIV trabaja con autoridades locales y poblaci\u00f3n para desarrollar proyectos en Quich\u00e9\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7832\" data-date=\"2025-12-04T10:35:24-06:00\" data-name=\"Carretera en Santa Cruz Balany\u00e1 impulsa el desarrollo agr\u00edcola y beneficia a m\u00e1s de 10 mil vecinos\"><article class=\"post project-odd visible post-7832 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chimaltenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Carretera en Santa Cruz Balany\u00e1 impulsa el desarrollo agr\u00edcola y beneficia a m\u00e1s de 10 mil vecinos\" data-date=\"2025-12-04T10:35:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/04\/carretera-en-santa-cruz-balanya-impulsa-el-desarrollo-agricola-y-beneficia-a-mas-de-10-mil-vecinos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-7-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-7-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-7-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/04\/carretera-en-santa-cruz-balanya-impulsa-el-desarrollo-agricola-y-beneficia-a-mas-de-10-mil-vecinos\/\" title=\"Carretera en Santa Cruz Balany\u00e1 impulsa el desarrollo agr\u00edcola y beneficia a m\u00e1s de 10 mil vecinos\" rel=\"bookmark\">Carretera en Santa Cruz Balany\u00e1 impulsa el desarrollo agr\u00edcola y beneficia a m\u00e1s de 10 mil vecinos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/12\/04\/carretera-en-santa-cruz-balanya-impulsa-el-desarrollo-agricola-y-beneficia-a-mas-de-10-mil-vecinos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Carretera en Santa Cruz Balany\u00e1 impulsa el desarrollo agr\u00edcola y beneficia a m\u00e1s de 10 mil vecinos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7825\" data-date=\"2025-11-27T14:48:29-06:00\" data-name=\"Avanza el mejoramiento vial que transformar\u00e1 la vida de m\u00e1s de 91 mil vecinos en Escuintla\"><article class=\"post project-odd visible post-7825 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-escuintla tag-noticias category-20 description-off\" data-name=\"Avanza el mejoramiento vial que transformar\u00e1 la vida de m\u00e1s de 91 mil vecinos en Escuintla\" data-date=\"2025-11-27T14:48:29-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/27\/avanza-el-mejoramiento-vial-que-transformara-la-vida-de-mas-de-91-mil-vecinos-en-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/27\/avanza-el-mejoramiento-vial-que-transformara-la-vida-de-mas-de-91-mil-vecinos-en-escuintla\/\" title=\"Avanza el mejoramiento vial que transformar\u00e1 la vida de m\u00e1s de 91 mil vecinos en Escuintla\" rel=\"bookmark\">Avanza el mejoramiento vial que transformar\u00e1 la vida de m\u00e1s de 91 mil vecinos en Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/27\/avanza-el-mejoramiento-vial-que-transformara-la-vida-de-mas-de-91-mil-vecinos-en-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanza el mejoramiento vial que transformar\u00e1 la vida de m\u00e1s de 91 mil vecinos en Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7840\" data-date=\"2025-11-21T14:10:24-06:00\" data-name=\"Autoridades impulsan coordinaci\u00f3n para proyectos comunitarios en Alta Verapaz\"><article class=\"post project-odd visible post-7840 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-alta-verapaz tag-chimaltenango tag-noticias category-20 description-off\" data-name=\"Autoridades impulsan coordinaci\u00f3n para proyectos comunitarios en Alta Verapaz\" data-date=\"2025-11-21T14:10:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/21\/autoridades-impulsan-coordinacion-para-proyectos-comunitarios-en-alta-verapaz\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-12-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-12-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-12-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/21\/autoridades-impulsan-coordinacion-para-proyectos-comunitarios-en-alta-verapaz\/\" title=\"Autoridades impulsan coordinaci\u00f3n para proyectos comunitarios en Alta Verapaz\" rel=\"bookmark\">Autoridades impulsan coordinaci\u00f3n para proyectos comunitarios en Alta Verapaz<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/21\/autoridades-impulsan-coordinacion-para-proyectos-comunitarios-en-alta-verapaz\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Autoridades impulsan coordinaci\u00f3n para proyectos comunitarios en Alta Verapaz\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7849\" data-date=\"2025-11-11T15:38:40-06:00\" data-name=\"Avanza la construcci\u00f3n de la nueva carretera en Pasaco, Jutiapa\"><article class=\"post project-odd visible post-7849 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-jutiapa tag-noticias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"Avanza la construcci\u00f3n de la nueva carretera en Pasaco, Jutiapa\" data-date=\"2025-11-11T15:38:40-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/11\/avanza-la-construccion-de-la-nueva-carretera-en-pasaco-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-19-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-19-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/12\/image-19-1063x664.jpeg 1063w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/11\/avanza-la-construccion-de-la-nueva-carretera-en-pasaco-jutiapa\/\" title=\"Avanza la construcci\u00f3n de la nueva carretera en Pasaco, Jutiapa\" rel=\"bookmark\">Avanza la construcci\u00f3n de la nueva carretera en Pasaco, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/11\/11\/avanza-la-construccion-de-la-nueva-carretera-en-pasaco-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanza la construcci\u00f3n de la nueva carretera en Pasaco, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7716\" data-date=\"2025-08-09T17:08:06-06:00\" data-name=\"\u00a1San Pedro Necta, Huehuetenango, avanza!\"><article class=\"post project-odd visible post-7716 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-huehuetenango tag-noticias category-20 description-off\" data-name=\"\u00a1San Pedro Necta, Huehuetenango, avanza!\" data-date=\"2025-08-09T17:08:06-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/san-pedro-necta-huehuetenango-avanza-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20512%20319&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-8-512x319.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-8-512x319.jpeg 512w\" loading=\"eager\" style=\"--ratio: 512 \/ 319\" sizes=\"(max-width: 512px) 100vw, 512px\" alt=\"\" title=\"image\" width=\"512\" height=\"319\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/san-pedro-necta-huehuetenango-avanza-2\/\" title=\"\u00a1San Pedro Necta, Huehuetenango, avanza!\" rel=\"bookmark\">\u00a1San Pedro Necta, Huehuetenango, avanza!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/san-pedro-necta-huehuetenango-avanza-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1San Pedro Necta, Huehuetenango, avanza!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7710\" data-date=\"2025-08-09T17:00:36-06:00\" data-name=\"Extorsiones detiene el desarrollo de las comunidades en Chimaltenango\"><article class=\"post project-odd visible post-7710 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-coordinador tag-noticias category-20 description-off\" data-name=\"Extorsiones detiene el desarrollo de las comunidades en Chimaltenango\" data-date=\"2025-08-09T17:00:36-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/extorsiones-detiene-el-desarrollo-de-las-comunidades-en-chimaltenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-4-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-4-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-4-1200x749.jpeg 1200w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/extorsiones-detiene-el-desarrollo-de-las-comunidades-en-chimaltenango\/\" title=\"Extorsiones detiene el desarrollo de las comunidades en Chimaltenango\" rel=\"bookmark\">Extorsiones detiene el desarrollo de las comunidades en Chimaltenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/09\/extorsiones-detiene-el-desarrollo-de-las-comunidades-en-chimaltenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Extorsiones detiene el desarrollo de las comunidades en Chimaltenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7702\" data-date=\"2025-08-08T17:03:20-06:00\" data-name=\"\u00a1San Pedro N\u00e9cta, Huehuetenango, avanza!\"><article class=\"post project-odd visible post-7702 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-huehuetenango tag-noticias tag-supervision category-20 description-off\" data-name=\"\u00a1San Pedro N\u00e9cta, Huehuetenango, avanza!\" data-date=\"2025-08-08T17:03:20-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/08\/san-pedro-necta-huehuetenango-avanza\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-2-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-2-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/08\/image-2-1152x719.jpeg 1152w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/08\/san-pedro-necta-huehuetenango-avanza\/\" title=\"\u00a1San Pedro N\u00e9cta, Huehuetenango, avanza!\" rel=\"bookmark\">\u00a1San Pedro N\u00e9cta, Huehuetenango, avanza!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/08\/08\/san-pedro-necta-huehuetenango-avanza\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1San Pedro N\u00e9cta, Huehuetenango, avanza!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7694\" data-date=\"2025-07-23T17:08:09-06:00\" data-name=\"Fortaleciendo capacidades para un mejor servicio\"><article class=\"post project-odd visible post-7694 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Fortaleciendo capacidades para un mejor servicio\" data-date=\"2025-07-23T17:08:09-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/fortaleciendo-capacidades-para-un-mejor-servicio\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-6-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-6-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-6-1200x749.jpeg 1200w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/fortaleciendo-capacidades-para-un-mejor-servicio\/\" title=\"Fortaleciendo capacidades para un mejor servicio\" rel=\"bookmark\">Fortaleciendo capacidades para un mejor servicio<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/fortaleciendo-capacidades-para-un-mejor-servicio\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Fortaleciendo capacidades para un mejor servicio\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7691\" data-date=\"2025-07-23T16:56:58-06:00\" data-name=\"M\u00e1s Conectividad en Pasaco\"><article class=\"post project-odd visible post-7691 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-jutiapa tag-noticias category-20 description-off\" data-name=\"M\u00e1s Conectividad en Pasaco\" data-date=\"2025-07-23T16:56:58-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/mas-conectividad-en-pasaco\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20512%20319&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-4-512x319.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-4-512x319.jpeg 512w\" loading=\"eager\" style=\"--ratio: 512 \/ 319\" sizes=\"(max-width: 512px) 100vw, 512px\" alt=\"\" title=\"image\" width=\"512\" height=\"319\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/mas-conectividad-en-pasaco\/\" title=\"M\u00e1s Conectividad en Pasaco\" rel=\"bookmark\">M\u00e1s Conectividad en Pasaco<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/23\/mas-conectividad-en-pasaco\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about M\u00e1s Conectividad en Pasaco\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7673\" data-date=\"2025-07-17T18:30:09-06:00\" data-name=\"\u00a1Manos a la obra en Pasaco, Jutiapa!\"><article class=\"post project-odd visible post-7673 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias category-20 description-off\" data-name=\"\u00a1Manos a la obra en Pasaco, Jutiapa!\" data-date=\"2025-07-17T18:30:09-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/17\/manos-a-la-obra-en-pasaco-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/17\/manos-a-la-obra-en-pasaco-jutiapa\/\" title=\"\u00a1Manos a la obra en Pasaco, Jutiapa!\" rel=\"bookmark\">\u00a1Manos a la obra en Pasaco, Jutiapa!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/17\/manos-a-la-obra-en-pasaco-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Manos a la obra en Pasaco, Jutiapa!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7679\" data-date=\"2025-07-08T18:35:34-06:00\" data-name=\"\u00a1As\u00ed se vive el cambio en El Tejar!\"><article class=\"post project-odd visible post-7679 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias category-20 description-off\" data-name=\"\u00a1As\u00ed se vive el cambio en El Tejar!\" data-date=\"2025-07-08T18:35:34-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/asi-se-vive-el-cambio-en-el-tejar\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20512%20319&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-2-512x319.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-2-512x319.jpeg 512w\" loading=\"eager\" style=\"--ratio: 512 \/ 319\" sizes=\"(max-width: 512px) 100vw, 512px\" alt=\"\" title=\"image\" width=\"512\" height=\"319\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/asi-se-vive-el-cambio-en-el-tejar\/\" title=\"\u00a1As\u00ed se vive el cambio en El Tejar!\" rel=\"bookmark\">\u00a1As\u00ed se vive el cambio en El Tejar!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/asi-se-vive-el-cambio-en-el-tejar\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1As\u00ed se vive el cambio en El Tejar!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7676\" data-date=\"2025-07-08T18:33:26-06:00\" data-name=\"Mejoras en El Tejar, Chimaltenango\"><article class=\"post project-odd visible post-7676 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-disenos tag-noticias category-20 description-off\" data-name=\"Mejoras en El Tejar, Chimaltenango\" data-date=\"2025-07-08T18:33:26-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/mejoras-en-el-tejar-chimaltenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20512%20319&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-1-512x319.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-1-512x319.jpeg 512w\" loading=\"eager\" style=\"--ratio: 512 \/ 319\" sizes=\"(max-width: 512px) 100vw, 512px\" alt=\"\" title=\"image\" width=\"512\" height=\"319\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/mejoras-en-el-tejar-chimaltenango\/\" title=\"Mejoras en El Tejar, Chimaltenango\" rel=\"bookmark\">Mejoras en El Tejar, Chimaltenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/08\/mejoras-en-el-tejar-chimaltenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoras en El Tejar, Chimaltenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7682\" data-date=\"2025-07-05T18:37:53-06:00\" data-name=\"Renovaci\u00f3n total en El Tejar\"><article class=\"post project-odd visible post-7682 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias category-20 description-off\" data-name=\"Renovaci\u00f3n total en El Tejar\" data-date=\"2025-07-05T18:37:53-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/05\/renovacion-total-en-el-tejar\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20512%20319&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-3-512x319.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/07\/image-3-512x319.jpeg 512w\" loading=\"eager\" style=\"--ratio: 512 \/ 319\" sizes=\"(max-width: 512px) 100vw, 512px\" alt=\"\" title=\"image\" width=\"512\" height=\"319\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/05\/renovacion-total-en-el-tejar\/\" title=\"Renovaci\u00f3n total en El Tejar\" rel=\"bookmark\">Renovaci\u00f3n total en El Tejar<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/07\/05\/renovacion-total-en-el-tejar\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Renovaci\u00f3n total en El Tejar\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7571\" data-date=\"2025-04-15T09:44:43-06:00\" data-name=\"Conectividad y Progreso en Chuarrancho\"><article class=\"post project-odd visible post-7571 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-guatemala tag-noticias category-20 description-off\" data-name=\"Conectividad y Progreso en Chuarrancho\" data-date=\"2025-04-15T09:44:43-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/15\/conectividad-y-progreso-en-chuarrancho\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-3-600x374.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-3-600x374.jpeg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"image\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/15\/conectividad-y-progreso-en-chuarrancho\/\" title=\"Conectividad y Progreso en Chuarrancho\" rel=\"bookmark\">Conectividad y Progreso en Chuarrancho<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/15\/conectividad-y-progreso-en-chuarrancho\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Conectividad y Progreso en Chuarrancho\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7568\" data-date=\"2025-04-14T09:38:30-06:00\" data-name=\"Antes de Salir, Que Haya Seguridad en Tu Casa\"><article class=\"post project-odd visible post-7568 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos category-20 description-off\" data-name=\"Antes de Salir, Que Haya Seguridad en Tu Casa\" data-date=\"2025-04-14T09:38:30-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/14\/antes-de-salir-que-haya-seguridad-en-tu-casa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-2-600x374.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-2-600x374.jpeg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"image\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/14\/antes-de-salir-que-haya-seguridad-en-tu-casa\/\" title=\"Antes de Salir, Que Haya Seguridad en Tu Casa\" rel=\"bookmark\">Antes de Salir, Que Haya Seguridad en Tu Casa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/14\/antes-de-salir-que-haya-seguridad-en-tu-casa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Antes de Salir, Que Haya Seguridad en Tu Casa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7565\" data-date=\"2025-04-13T09:35:26-06:00\" data-name=\"Revisa Tu Veh\u00edculo\"><article class=\"post project-odd visible post-7565 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos category-20 description-off\" data-name=\"Revisa Tu Veh\u00edculo\" data-date=\"2025-04-13T09:35:26-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/13\/revisa-tu-vehiculo\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-1-600x374.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-1-600x374.jpeg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"image\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/13\/revisa-tu-vehiculo\/\" title=\"Revisa Tu Veh\u00edculo\" rel=\"bookmark\">Revisa Tu Veh\u00edculo<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/13\/revisa-tu-vehiculo\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Revisa Tu Veh\u00edculo\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7562\" data-date=\"2025-04-12T09:32:03-06:00\" data-name=\"Impulsamos el Desarrollo en Chuarrancho\"><article class=\"post project-odd visible post-7562 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-guatemala tag-noticias category-20 description-off\" data-name=\"Impulsamos el Desarrollo en Chuarrancho\" data-date=\"2025-04-12T09:32:03-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/12\/impulsamos-el-desarrollo-en-chuarrancho\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-600x374.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/image-600x374.jpeg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"image\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/12\/impulsamos-el-desarrollo-en-chuarrancho\/\" title=\"Impulsamos el Desarrollo en Chuarrancho\" rel=\"bookmark\">Impulsamos el Desarrollo en Chuarrancho<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/12\/impulsamos-el-desarrollo-en-chuarrancho\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Impulsamos el Desarrollo en Chuarrancho\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7543\" data-date=\"2025-04-10T11:08:44-06:00\" data-name=\"Conectamos oportunidades en Baja Verapaz\"><article class=\"post project-odd visible post-7543 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-guatemala tag-noticias category-20 description-off\" data-name=\"Conectamos oportunidades en Baja Verapaz\" data-date=\"2025-04-10T11:08:44-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/10\/conectamos-oportunidades-en-baja-verapaz\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.18.33-AM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.18.33-AM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.18.33-AM-1080x674.jpeg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-04-10 at 10.18.33 AM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/10\/conectamos-oportunidades-en-baja-verapaz\/\" title=\"Conectamos oportunidades en Baja Verapaz\" rel=\"bookmark\">Conectamos oportunidades en Baja Verapaz<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/10\/conectamos-oportunidades-en-baja-verapaz\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Conectamos oportunidades en Baja Verapaz\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7548\" data-date=\"2025-04-08T11:09:53-06:00\" data-name=\"Autoridades y vecinos dan seguimiento a proyecto de reposici\u00f3n de puente en El J\u00edcaro\"><article class=\"post project-odd visible post-7548 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-el-progreso tag-noticias category-20 description-off\" data-name=\"Autoridades y vecinos dan seguimiento a proyecto de reposici\u00f3n de puente en El J\u00edcaro\" data-date=\"2025-04-08T11:09:53-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/08\/autoridades-y-vecinos-dan-seguimiento-a-proyecto-de-reposicion-de-puente-en-el-jicaro\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.21.59-AM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.21.59-AM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.21.59-AM-1440x898.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-04-10 at 10.21.59 AM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/08\/autoridades-y-vecinos-dan-seguimiento-a-proyecto-de-reposicion-de-puente-en-el-jicaro\/\" title=\"Autoridades y vecinos dan seguimiento a proyecto de reposici\u00f3n de puente en El J\u00edcaro\" rel=\"bookmark\">Autoridades y vecinos dan seguimiento a proyecto de reposici\u00f3n de puente en El J\u00edcaro<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/08\/autoridades-y-vecinos-dan-seguimiento-a-proyecto-de-reposicion-de-puente-en-el-jicaro\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Autoridades y vecinos dan seguimiento a proyecto de reposici\u00f3n de puente en El J\u00edcaro\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7553\" data-date=\"2025-04-07T11:17:19-06:00\" data-name=\"\u00a1El Progreso Avanza sobre ruedas!\"><article class=\"post project-odd visible post-7553 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-el-progreso tag-noticias category-20 description-off\" data-name=\"\u00a1El Progreso Avanza sobre ruedas!\" data-date=\"2025-04-07T11:17:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/07\/el-progreso-avanza-sobre-ruedas\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.22.41-AM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.22.41-AM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.22.41-AM-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-04-10 at 10.22.41 AM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/07\/el-progreso-avanza-sobre-ruedas\/\" title=\"\u00a1El Progreso Avanza sobre ruedas!\" rel=\"bookmark\">\u00a1El Progreso Avanza sobre ruedas!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/07\/el-progreso-avanza-sobre-ruedas\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1El Progreso Avanza sobre ruedas!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7554\" data-date=\"2025-04-02T11:37:02-06:00\" data-name=\"Trabajamos para una mejor infraestructura en Jutiapa\"><article class=\"post project-odd visible post-7554 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias category-20 description-off\" data-name=\"Trabajamos para una mejor infraestructura en Jutiapa\" data-date=\"2025-04-02T11:37:02-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/02\/trabajamos-para-una-mejor-infraestructura-en-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.28.17-AM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.28.17-AM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.28.17-AM-1279x798.jpeg 1279w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-04-10 at 10.28.17 AM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/02\/trabajamos-para-una-mejor-infraestructura-en-jutiapa\/\" title=\"Trabajamos para una mejor infraestructura en Jutiapa\" rel=\"bookmark\">Trabajamos para una mejor infraestructura en Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/02\/trabajamos-para-una-mejor-infraestructura-en-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Trabajamos para una mejor infraestructura en Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7559\" data-date=\"2025-04-01T11:40:09-06:00\" data-name=\"Mejor Camino, Mejor Futuro en Jutiapa\"><article class=\"post project-odd visible post-7559 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias category-20 description-off\" data-name=\"Mejor Camino, Mejor Futuro en Jutiapa\" data-date=\"2025-04-01T11:40:09-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/01\/mejor-camino-mejor-futuro-en-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.29.28-AM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.29.28-AM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-10-at-10.29.28-AM-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-04-10 at 10.29.28 AM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/01\/mejor-camino-mejor-futuro-en-jutiapa\/\" title=\"Mejor Camino, Mejor Futuro en Jutiapa\" rel=\"bookmark\">Mejor Camino, Mejor Futuro en Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/04\/01\/mejor-camino-mejor-futuro-en-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejor Camino, Mejor Futuro en Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7412\" data-date=\"2025-03-06T16:14:11-06:00\" data-name=\"Construimos desarrollo en Chiquimula\"><article class=\"post project-odd visible post-7412 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chiquimula tag-disenos tag-noticias category-20 description-off\" data-name=\"Construimos desarrollo en Chiquimula\" data-date=\"2025-03-06T16:14:11-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/03\/06\/construimos-desarrollo-en-chiquimula\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-3-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-3-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-3-1080x674.jpeg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/03\/06\/construimos-desarrollo-en-chiquimula\/\" title=\"Construimos desarrollo en Chiquimula\" rel=\"bookmark\">Construimos desarrollo en Chiquimula<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/03\/06\/construimos-desarrollo-en-chiquimula\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Construimos desarrollo en Chiquimula\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7406\" data-date=\"2025-02-25T13:43:48-06:00\" data-name=\"Reuni\u00f3n para garantizar la continuidad de proyecto en El Progreso\"><article class=\"post project-odd visible post-7406 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-el-progreso tag-noticias category-20 description-off\" data-name=\"Reuni\u00f3n para garantizar la continuidad de proyecto en El Progreso\" data-date=\"2025-02-25T13:43:48-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/25\/reunion-para-garantizar-la-continuidad-de-proyecto-en-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/03\/image-1-1440x898.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/25\/reunion-para-garantizar-la-continuidad-de-proyecto-en-el-progreso\/\" title=\"Reuni\u00f3n para garantizar la continuidad de proyecto en El Progreso\" rel=\"bookmark\">Reuni\u00f3n para garantizar la continuidad de proyecto en El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/25\/reunion-para-garantizar-la-continuidad-de-proyecto-en-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reuni\u00f3n para garantizar la continuidad de proyecto en El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7306\" data-date=\"2025-02-20T16:00:34-06:00\" data-name=\"Avanzan los trabajos de una carretera nueva en Balany\u00e1\"><article class=\"post project-odd visible post-7306 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenando tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan los trabajos de una carretera nueva en Balany\u00e1\" data-date=\"2025-02-20T16:00:34-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/20\/avanzan-los-trabajos-de-una-carretera-nueva-en-balanya\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-8-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-8-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-8-1279x798.jpeg 1279w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/20\/avanzan-los-trabajos-de-una-carretera-nueva-en-balanya\/\" title=\"Avanzan los trabajos de una carretera nueva en Balany\u00e1\" rel=\"bookmark\">Avanzan los trabajos de una carretera nueva en Balany\u00e1<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/20\/avanzan-los-trabajos-de-una-carretera-nueva-en-balanya\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan los trabajos de una carretera nueva en Balany\u00e1\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7300\" data-date=\"2025-02-18T15:53:23-06:00\" data-name=\"L\u00edderes de Jalapa son capacitados para gestionar proyectos en sus localidades\"><article class=\"post project-odd visible post-7300 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-jalapa tag-noticias category-20 description-off\" data-name=\"L\u00edderes de Jalapa son capacitados para gestionar proyectos en sus localidades\" data-date=\"2025-02-18T15:53:23-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/18\/lideres-de-jalapa-son-capacitados-para-gestionar-proyectos-en-sus-localidades\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-2-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-2-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-2-1440x898.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/18\/lideres-de-jalapa-son-capacitados-para-gestionar-proyectos-en-sus-localidades\/\" title=\"L\u00edderes de Jalapa son capacitados para gestionar proyectos en sus localidades\" rel=\"bookmark\">L\u00edderes de Jalapa son capacitados para gestionar proyectos en sus localidades<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/18\/lideres-de-jalapa-son-capacitados-para-gestionar-proyectos-en-sus-localidades\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about L\u00edderes de Jalapa son capacitados para gestionar proyectos en sus localidades\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7313\" data-date=\"2025-02-14T16:50:52-06:00\" data-name=\"Reuni\u00f3n administrativa con l\u00edderes en San Pedro Yepocapa\"><article class=\"post project-odd visible post-7313 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-cocodes tag-ejecutivo tag-noticias tag-operaciones tag-reuniones category-20 description-off\" data-name=\"Reuni\u00f3n administrativa con l\u00edderes en San Pedro Yepocapa\" data-date=\"2025-02-14T16:50:52-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/14\/reunion-administrativa-con-lideres-en-san-pedro-yepocapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-11-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-11-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-11-1440x898.jpeg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/14\/reunion-administrativa-con-lideres-en-san-pedro-yepocapa\/\" title=\"Reuni\u00f3n administrativa con l\u00edderes en San Pedro Yepocapa\" rel=\"bookmark\">Reuni\u00f3n administrativa con l\u00edderes en San Pedro Yepocapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/14\/reunion-administrativa-con-lideres-en-san-pedro-yepocapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reuni\u00f3n administrativa con l\u00edderes en San Pedro Yepocapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7325\" data-date=\"2025-02-13T17:03:56-06:00\" data-name=\"Se analizan proyectos para el desarrollo de la poblaci\u00f3n\"><article class=\"post project-odd visible post-7325 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-ejecutivo tag-noticias tag-reuniones category-20 description-off\" data-name=\"Se analizan proyectos para el desarrollo de la poblaci\u00f3n\" data-date=\"2025-02-13T17:03:56-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/se-analizan-proyectos-para-el-desarrollo-de-la-poblacion\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-17-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-17-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/image-17-1439x898.jpeg 1439w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/se-analizan-proyectos-para-el-desarrollo-de-la-poblacion\/\" title=\"Se analizan proyectos para el desarrollo de la poblaci\u00f3n\" rel=\"bookmark\">Se analizan proyectos para el desarrollo de la poblaci\u00f3n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/se-analizan-proyectos-para-el-desarrollo-de-la-poblacion\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Se analizan proyectos para el desarrollo de la poblaci\u00f3n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7319\" data-date=\"2025-02-13T16:58:52-06:00\" data-name=\"M\u00e1s de 13,600 personas beneficiadas con mejoras en 98.8 kil\u00f3metros de carreteras rurales en Sansare\"><article class=\"post project-odd visible post-7319 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-caminos-rurales tag-el-progreso tag-noticias tag-rutas-terciarias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"M\u00e1s de 13,600 personas beneficiadas con mejoras en 98.8 kil\u00f3metros de carreteras rurales en Sansare\" data-date=\"2025-02-13T16:58:52-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/mas-de-13600-personas-beneficiadas-con-mejoras-en-98-8-kilometros-de-carreteras-rurales-en-sansare\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-03-at-10.09.16-AM-2-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-03-at-10.09.16-AM-2-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-03-at-10.09.16-AM-2-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp Image 2025-02-03 at 10.09.16 AM (2)\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/mas-de-13600-personas-beneficiadas-con-mejoras-en-98-8-kilometros-de-carreteras-rurales-en-sansare\/\" title=\"M\u00e1s de 13,600 personas beneficiadas con mejoras en 98.8 kil\u00f3metros de carreteras rurales en Sansare\" rel=\"bookmark\">M\u00e1s de 13,600 personas beneficiadas con mejoras en 98.8 kil\u00f3metros de carreteras rurales en Sansare<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/13\/mas-de-13600-personas-beneficiadas-con-mejoras-en-98-8-kilometros-de-carreteras-rurales-en-sansare\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about M\u00e1s de 13,600 personas beneficiadas con mejoras en 98.8 kil\u00f3metros de carreteras rurales en Sansare\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7292\" data-date=\"2025-02-12T14:55:24-06:00\" data-name=\"Alcaldes de San Marcos se instruyen para solicitar nuevos proyectos de infraestructura\"><article class=\"post project-odd visible post-7292 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-noticias tag-san-marcos category-20 description-off\" data-name=\"Alcaldes de San Marcos se instruyen para solicitar nuevos proyectos de infraestructura\" data-date=\"2025-02-12T14:55:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/12\/alcaldes-de-san-marcos-se-instruyen-para-solicitar-nuevos-proyectos-de-infraestructura\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/479174660_18000879341735553_7114278782497743821_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/479174660_18000879341735553_7114278782497743821_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/479174660_18000879341735553_7114278782497743821_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"479174660_18000879341735553_7114278782497743821_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/12\/alcaldes-de-san-marcos-se-instruyen-para-solicitar-nuevos-proyectos-de-infraestructura\/\" title=\"Alcaldes de San Marcos se instruyen para solicitar nuevos proyectos de infraestructura\" rel=\"bookmark\">Alcaldes de San Marcos se instruyen para solicitar nuevos proyectos de infraestructura<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/12\/alcaldes-de-san-marcos-se-instruyen-para-solicitar-nuevos-proyectos-de-infraestructura\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Alcaldes de San Marcos se instruyen para solicitar nuevos proyectos de infraestructura\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7272\" data-date=\"2025-02-10T14:38:17-06:00\" data-name=\"M\u00e1s caminos rurales para mejorar la econom\u00eda de Jalapa\"><article class=\"post project-odd visible post-7272 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-caminos-rurales tag-jalapa tag-noticias tag-rutas-terciarias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"M\u00e1s caminos rurales para mejorar la econom\u00eda de Jalapa\" data-date=\"2025-02-10T14:38:17-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/10\/mas-caminos-rurales-para-mejorar-la-economia-de-jalapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed1-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"upscalemedia-transformed1\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/10\/mas-caminos-rurales-para-mejorar-la-economia-de-jalapa\/\" title=\"M\u00e1s caminos rurales para mejorar la econom\u00eda de Jalapa\" rel=\"bookmark\">M\u00e1s caminos rurales para mejorar la econom\u00eda de Jalapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/10\/mas-caminos-rurales-para-mejorar-la-economia-de-jalapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about M\u00e1s caminos rurales para mejorar la econom\u00eda de Jalapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7266\" data-date=\"2025-02-07T10:04:44-06:00\" data-name=\"Planificaci\u00f3n de Obras en San Marcos\"><article class=\"post project-odd visible post-7266 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-san-marcos category-20 description-off\" data-name=\"Planificaci\u00f3n de Obras en San Marcos\" data-date=\"2025-02-07T10:04:44-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/07\/planificacion-de-obras-en-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476613508_18000307472735553_809313366263297371_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476613508_18000307472735553_809313366263297371_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476613508_18000307472735553_809313366263297371_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476613508_18000307472735553_809313366263297371_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/07\/planificacion-de-obras-en-san-marcos\/\" title=\"Planificaci\u00f3n de Obras en San Marcos\" rel=\"bookmark\">Planificaci\u00f3n de Obras en San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/07\/planificacion-de-obras-en-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Planificaci\u00f3n de Obras en San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7253\" data-date=\"2025-02-06T09:30:43-06:00\" data-name=\"La Primera Cosecha - 21,729 beneficiados en Sipacapa\"><article class=\"post project-odd visible post-7253 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-noticias tag-san-marcos category-20 description-off\" data-name=\"La Primera Cosecha &#8211; 21,729 beneficiados en Sipacapa\" data-date=\"2025-02-06T09:30:43-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/06\/la-primera-cosecha-21729-beneficiados-en-sipacapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476312807_18000169304735553_6272033485869545178_n-600x374.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476312807_18000169304735553_6272033485869545178_n-600x374.jpg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"476312807_18000169304735553_6272033485869545178_n\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/06\/la-primera-cosecha-21729-beneficiados-en-sipacapa\/\" title=\"La Primera Cosecha &#8211; 21,729 beneficiados en Sipacapa\" rel=\"bookmark\">La Primera Cosecha &#8211; 21,729 beneficiados en Sipacapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/06\/la-primera-cosecha-21729-beneficiados-en-sipacapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Primera Cosecha &#8211; 21,729 beneficiados en Sipacapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7262\" data-date=\"2025-02-05T09:48:06-06:00\" data-name=\"La Primera Cosecha - 3.2 kms de mejoramiento de carretera en El J\u00edcaro\"><article class=\"post project-odd visible post-7262 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-disenos tag-el-progreso tag-noticias category-20 description-off\" data-name=\"La Primera Cosecha &#8211; 3.2 kms de mejoramiento de carretera en El J\u00edcaro\" data-date=\"2025-02-05T09:48:06-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/la-primera-cosecha-21729-beneficiados-en-sipacapa-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476443558_18000065828735553_4597809652575285074_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476443558_18000065828735553_4597809652575285074_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476443558_18000065828735553_4597809652575285074_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476443558_18000065828735553_4597809652575285074_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/la-primera-cosecha-21729-beneficiados-en-sipacapa-2\/\" title=\"La Primera Cosecha &#8211; 3.2 kms de mejoramiento de carretera en El J\u00edcaro\" rel=\"bookmark\">La Primera Cosecha &#8211; 3.2 kms de mejoramiento de carretera en El J\u00edcaro<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/la-primera-cosecha-21729-beneficiados-en-sipacapa-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Primera Cosecha &#8211; 3.2 kms de mejoramiento de carretera en El J\u00edcaro\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7256\" data-date=\"2025-02-05T09:37:19-06:00\" data-name=\"Mesa De Seguimiento Al Proyecto De Rehabilitaci\u00f3n Del Puente Vehicular Tobar\"><article class=\"post project-odd visible post-7256 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chiquimula tag-coordinadora tag-noticias category-20 description-off\" data-name=\"Mesa De Seguimiento Al Proyecto De Rehabilitaci\u00f3n Del Puente Vehicular Tobar\" data-date=\"2025-02-05T09:37:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/mesa-de-seguimiento-al-proyecto-de-rehabilitacion-del-puente-vehicular-tobar\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476459764_122162186816292480_7854998073558344437_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/mesa-de-seguimiento-al-proyecto-de-rehabilitacion-del-puente-vehicular-tobar\/\" title=\"Mesa De Seguimiento Al Proyecto De Rehabilitaci\u00f3n Del Puente Vehicular Tobar\" rel=\"bookmark\">Mesa De Seguimiento Al Proyecto De Rehabilitaci\u00f3n Del Puente Vehicular Tobar<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/05\/mesa-de-seguimiento-al-proyecto-de-rehabilitacion-del-puente-vehicular-tobar\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mesa De Seguimiento Al Proyecto De Rehabilitaci\u00f3n Del Puente Vehicular Tobar\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7194\" data-date=\"2025-02-04T17:42:05-06:00\" data-name=\"La Primera Cosecha - 4.2 kms trabajados en Huit\u00e1n\"><article class=\"post project-odd visible post-7194 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"La Primera Cosecha &#8211; 4.2 kms trabajados en Huit\u00e1n\" data-date=\"2025-02-04T17:42:05-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-primera-cosecha-4-2-kms-trabajados-en-huitan\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476309224_17999962682735553_3782622670637401935_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476309224_17999962682735553_3782622670637401935_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476309224_17999962682735553_3782622670637401935_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476309224_17999962682735553_3782622670637401935_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-primera-cosecha-4-2-kms-trabajados-en-huitan\/\" title=\"La Primera Cosecha &#8211; 4.2 kms trabajados en Huit\u00e1n\" rel=\"bookmark\">La Primera Cosecha &#8211; 4.2 kms trabajados en Huit\u00e1n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-primera-cosecha-4-2-kms-trabajados-en-huitan\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Primera Cosecha &#8211; 4.2 kms trabajados en Huit\u00e1n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7183\" data-date=\"2025-02-04T17:40:36-06:00\" data-name=\"La seguridad es lo m\u00e1s importante\"><article class=\"post project-odd visible post-7183 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"La seguridad es lo m\u00e1s importante\" data-date=\"2025-02-04T17:40:36-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-seguridad-es-lo-mas-importante\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476175736_17999952473735553_633200331604986081_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476175736_17999952473735553_633200331604986081_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476175736_17999952473735553_633200331604986081_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476175736_17999952473735553_633200331604986081_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-seguridad-es-lo-mas-importante\/\" title=\"La seguridad es lo m\u00e1s importante\" rel=\"bookmark\">La seguridad es lo m\u00e1s importante<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/la-seguridad-es-lo-mas-importante\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La seguridad es lo m\u00e1s importante\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7178\" data-date=\"2025-02-04T17:36:19-06:00\" data-name=\"El gobernador de San Marcos visita las oficinas del Fondo Social de Solidaridad\"><article class=\"post project-odd visible post-7178 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-noticias tag-san-marcos category-20 description-off\" data-name=\"El gobernador de San Marcos visita las oficinas del Fondo Social de Solidaridad\" data-date=\"2025-02-04T17:36:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/el-gobernador-de-san-marcos-visita-las-oficinas-del-fondo-social-de-solidaridad\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476459764_122162186816292480_7854998073558344437_n-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476459764_122162186816292480_7854998073558344437_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/el-gobernador-de-san-marcos-visita-las-oficinas-del-fondo-social-de-solidaridad\/\" title=\"El gobernador de San Marcos visita las oficinas del Fondo Social de Solidaridad\" rel=\"bookmark\">El gobernador de San Marcos visita las oficinas del Fondo Social de Solidaridad<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/04\/el-gobernador-de-san-marcos-visita-las-oficinas-del-fondo-social-de-solidaridad\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El gobernador de San Marcos visita las oficinas del Fondo Social de Solidaridad\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7120\" data-date=\"2025-02-03T15:08:43-06:00\" data-name=\"La Primera Cosecha - 124.6 en caminos rurales\"><article class=\"post project-odd visible post-7120 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"La Primera Cosecha &#8211; 124.6 en caminos rurales\" data-date=\"2025-02-03T15:08:43-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/03\/la-primera-cosecha-124-6-en-caminos-rurales\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476020545_17999812358735553_6210125715906062612_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476020545_17999812358735553_6210125715906062612_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/02\/476020545_17999812358735553_6210125715906062612_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"476020545_17999812358735553_6210125715906062612_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/03\/la-primera-cosecha-124-6-en-caminos-rurales\/\" title=\"La Primera Cosecha &#8211; 124.6 en caminos rurales\" rel=\"bookmark\">La Primera Cosecha &#8211; 124.6 en caminos rurales<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/02\/03\/la-primera-cosecha-124-6-en-caminos-rurales\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Primera Cosecha &#8211; 124.6 en caminos rurales\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7149\" data-date=\"2025-01-30T15:53:14-06:00\" data-name=\"D\u00eda nacional del Ingeniero\"><article class=\"post project-odd visible post-7149 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"D\u00eda nacional del Ingeniero\" data-date=\"2025-01-30T15:53:14-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/30\/dia-nacional-del-ingeniero\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475482222_17999365154735553_1255152683026005074_n-600x374.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475482222_17999365154735553_1255152683026005074_n-600x374.jpg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"475482222_17999365154735553_1255152683026005074_n\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/30\/dia-nacional-del-ingeniero\/\" title=\"D\u00eda nacional del Ingeniero\" rel=\"bookmark\">D\u00eda nacional del Ingeniero<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/30\/dia-nacional-del-ingeniero\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about D\u00eda nacional del Ingeniero\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7152\" data-date=\"2025-01-29T15:58:11-06:00\" data-name=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Luis Contreras\"><article class=\"post project-odd visible post-7152 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Luis Contreras\" data-date=\"2025-01-29T15:58:11-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/29\/arq-andrea-belteton-se-reunio-con-el-diputado-luis-contreras\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20374&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475336727_17999263178735553_869234759603825935_n-600x374.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475336727_17999263178735553_869234759603825935_n-600x374.jpg 600w\" loading=\"eager\" style=\"--ratio: 600 \/ 374\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"\" title=\"475336727_17999263178735553_869234759603825935_n\" width=\"600\" height=\"374\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/29\/arq-andrea-belteton-se-reunio-con-el-diputado-luis-contreras\/\" title=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Luis Contreras\" rel=\"bookmark\">Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Luis Contreras<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/29\/arq-andrea-belteton-se-reunio-con-el-diputado-luis-contreras\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Luis Contreras\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7158\" data-date=\"2025-01-28T16:22:51-06:00\" data-name=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Faver Salazar\"><article class=\"post project-odd visible post-7158 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-jalapa tag-noticias tag-operaciones category-20 description-off\" data-name=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Faver Salazar\" data-date=\"2025-01-28T16:22:51-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/28\/arq-andrea-belteton-se-reunio-con-el-diputado-faver-salazar\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475642804_17999193461735553_6434471943392676090_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475642804_17999193461735553_6434471943392676090_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475642804_17999193461735553_6434471943392676090_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"475642804_17999193461735553_6434471943392676090_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/28\/arq-andrea-belteton-se-reunio-con-el-diputado-faver-salazar\/\" title=\"Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Faver Salazar\" rel=\"bookmark\">Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Faver Salazar<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/28\/arq-andrea-belteton-se-reunio-con-el-diputado-faver-salazar\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Arq. Andrea Beltet\u00f3n se reuni\u00f3 con el diputado Faver Salazar\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7164\" data-date=\"2025-01-24T16:45:55-06:00\" data-name=\"Mesa de Trabajo con Alcald\u00eda de Xequemey\u00e1\"><article class=\"post project-odd visible post-7164 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinadora tag-noticias tag-totonicapan category-20 description-off\" data-name=\"Mesa de Trabajo con Alcald\u00eda de Xequemey\u00e1\" data-date=\"2025-01-24T16:45:55-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/mesa-de-trabajo-con-alcaldia-de-xequemeya\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/474633843_17998694777735553_6141392023146800400_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/474633843_17998694777735553_6141392023146800400_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/474633843_17998694777735553_6141392023146800400_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"474633843_17998694777735553_6141392023146800400_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/mesa-de-trabajo-con-alcaldia-de-xequemeya\/\" title=\"Mesa de Trabajo con Alcald\u00eda de Xequemey\u00e1\" rel=\"bookmark\">Mesa de Trabajo con Alcald\u00eda de Xequemey\u00e1<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/mesa-de-trabajo-con-alcaldia-de-xequemeya\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mesa de Trabajo con Alcald\u00eda de Xequemey\u00e1\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7162\" data-date=\"2025-01-24T16:44:55-06:00\" data-name=\"Gobernadora de Chimaltenango se re\u00fane con las autoridades del FSS\"><article class=\"post project-odd visible post-7162 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chimaltenango tag-coordinadora tag-noticias category-20 description-off\" data-name=\"Gobernadora de Chimaltenango se re\u00fane con las autoridades del FSS\" data-date=\"2025-01-24T16:44:55-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/gobernadora-de-chimaltenango-se-reune-con-las-autoridades-del-fss\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475020480_17998730354735553_1949769975337265488_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475020480_17998730354735553_1949769975337265488_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/475020480_17998730354735553_1949769975337265488_n-1439x898.jpg 1439w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"475020480_17998730354735553_1949769975337265488_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/gobernadora-de-chimaltenango-se-reune-con-las-autoridades-del-fss\/\" title=\"Gobernadora de Chimaltenango se re\u00fane con las autoridades del FSS\" rel=\"bookmark\">Gobernadora de Chimaltenango se re\u00fane con las autoridades del FSS<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/24\/gobernadora-de-chimaltenango-se-reune-con-las-autoridades-del-fss\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Gobernadora de Chimaltenango se re\u00fane con las autoridades del FSS\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6903\" data-date=\"2025-01-13T10:17:23-06:00\" data-name=\"La Primera Cosecha - Primer A\u00f1o de Gobierno no. 1\"><article class=\"post project-odd visible post-6903 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"La Primera Cosecha &#8211; Primer A\u00f1o de Gobierno no. 1\" data-date=\"2025-01-13T10:17:23-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/13\/la-primera-cosecha-primer-ano-de-gobierno-no-1\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471813744_122159255540292480_641862796379686392_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471813744_122159255540292480_641862796379686392_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471813744_122159255540292480_641862796379686392_n-1440x898.jpg 1440w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"471813744_122159255540292480_641862796379686392_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/13\/la-primera-cosecha-primer-ano-de-gobierno-no-1\/\" title=\"La Primera Cosecha &#8211; Primer A\u00f1o de Gobierno no. 1\" rel=\"bookmark\">La Primera Cosecha &#8211; Primer A\u00f1o de Gobierno no. 1<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2025\/01\/13\/la-primera-cosecha-primer-ano-de-gobierno-no-1\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Primera Cosecha &#8211; Primer A\u00f1o de Gobierno no. 1\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"7117\" data-date=\"2024-12-31T10:32:47-06:00\" data-name=\"\u00a1Feliz A\u00f1o Nuevo 2025!\"><article class=\"post project-odd visible post-7117 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"\u00a1Feliz A\u00f1o Nuevo 2025!\" data-date=\"2024-12-31T10:32:47-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/12\/31\/feliz-ano-nuevo-2025\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471244069_122157379106292480_6213928087118719901_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471244069_122157379106292480_6213928087118719901_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2025\/01\/471244069_122157379106292480_6213928087118719901_n-1080x674.jpg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"471244069_122157379106292480_6213928087118719901_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/12\/31\/feliz-ano-nuevo-2025\/\" title=\"\u00a1Feliz A\u00f1o Nuevo 2025!\" rel=\"bookmark\">\u00a1Feliz A\u00f1o Nuevo 2025!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/12\/31\/feliz-ano-nuevo-2025\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Feliz A\u00f1o Nuevo 2025!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6888\" data-date=\"2024-07-31T22:53:00-06:00\" data-name=\"Felicitaciones a Adriana Ruano\"><article class=\"post project-odd visible post-6888 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Felicitaciones a Adriana Ruano\" data-date=\"2024-07-31T22:53:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/felicitaciones-a-adriana-ruano\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20268%20168&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/descarga-268x168.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/descarga-268x168.jpg 268w\" loading=\"eager\" style=\"--ratio: 268 \/ 168\" sizes=\"(max-width: 268px) 100vw, 268px\" alt=\"\" title=\"descarga\" width=\"268\" height=\"168\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/felicitaciones-a-adriana-ruano\/\" title=\"Felicitaciones a Adriana Ruano\" rel=\"bookmark\">Felicitaciones a Adriana Ruano<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/felicitaciones-a-adriana-ruano\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Felicitaciones a Adriana Ruano\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6881\" data-date=\"2024-07-31T15:40:20-06:00\" data-name=\"Avanzan Trabajos en San Andr\u00e9s, Pet\u00e9n\"><article class=\"post project-odd visible post-6881 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Avanzan Trabajos en San Andr\u00e9s, Pet\u00e9n\" data-date=\"2024-07-31T15:40:20-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/avanzan-trabajos-en-san-andres-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/IMG_7770-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/IMG_7770-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/IMG_7770-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_7770\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/avanzan-trabajos-en-san-andres-peten\/\" title=\"Avanzan Trabajos en San Andr\u00e9s, Pet\u00e9n\" rel=\"bookmark\">Avanzan Trabajos en San Andr\u00e9s, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/31\/avanzan-trabajos-en-san-andres-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Trabajos en San Andr\u00e9s, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6897\" data-date=\"2024-07-30T12:57:00-06:00\" data-name=\"Felicitaciones a Jean Pierre Brol\"><article class=\"post project-odd visible post-6897 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Felicitaciones a Jean Pierre Brol\" data-date=\"2024-07-30T12:57:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/30\/felicitaciones-a-jean-pierre-brol\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/07\/brol-cog-01-scaled-990x618.webp\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/07\/brol-cog-01-scaled-990x618.webp 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/07\/brol-cog-01-scaled-1485x927.webp 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"brol-cog-01\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/30\/felicitaciones-a-jean-pierre-brol\/\" title=\"Felicitaciones a Jean Pierre Brol\" rel=\"bookmark\">Felicitaciones a Jean Pierre Brol<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/07\/30\/felicitaciones-a-jean-pierre-brol\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Felicitaciones a Jean Pierre Brol\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6825\" data-date=\"2024-06-11T15:17:29-06:00\" data-name=\"Avanzan Trabajos en San Pedro Necta, Huehuetenango\"><article class=\"post project-odd visible post-6825 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan Trabajos en San Pedro Necta, Huehuetenango\" data-date=\"2024-06-11T15:17:29-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/11\/avanzan-trabajos-en-san-pedro-necta-huehuetenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0741-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0741-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0741-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/11\/avanzan-trabajos-en-san-pedro-necta-huehuetenango\/\" title=\"Avanzan Trabajos en San Pedro Necta, Huehuetenango\" rel=\"bookmark\">Avanzan Trabajos en San Pedro Necta, Huehuetenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/11\/avanzan-trabajos-en-san-pedro-necta-huehuetenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Trabajos en San Pedro Necta, Huehuetenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6818\" data-date=\"2024-06-04T15:14:51-06:00\" data-name=\"Avanzan Trabajos de puente en El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-6818 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan Trabajos de puente en El J\u00edcaro, El Progreso\" data-date=\"2024-06-04T15:14:51-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/04\/avanzan-trabajos-de-puente-en-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_6217-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_6217-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_6217-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_6217\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/04\/avanzan-trabajos-de-puente-en-el-jicaro-el-progreso\/\" title=\"Avanzan Trabajos de puente en El J\u00edcaro, El Progreso\" rel=\"bookmark\">Avanzan Trabajos de puente en El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/06\/04\/avanzan-trabajos-de-puente-en-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Trabajos de puente en El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6812\" data-date=\"2024-05-28T15:11:39-06:00\" data-name=\"Avanzan Trabajos en Aldea Las Ovejas, El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-6812 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan Trabajos en Aldea Las Ovejas, El J\u00edcaro, El Progreso\" data-date=\"2024-05-28T15:11:39-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/28\/avanzan-trabajos-en-aldea-las-ovejas-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0626-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0626-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/DJI_0626-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/28\/avanzan-trabajos-en-aldea-las-ovejas-el-jicaro-el-progreso\/\" title=\"Avanzan Trabajos en Aldea Las Ovejas, El J\u00edcaro, El Progreso\" rel=\"bookmark\">Avanzan Trabajos en Aldea Las Ovejas, El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/28\/avanzan-trabajos-en-aldea-las-ovejas-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Trabajos en Aldea Las Ovejas, El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6801\" data-date=\"2024-05-21T14:54:02-06:00\" data-name=\"Avanzan trabajos en el Aeropuerto Internacional La Aurora\"><article class=\"post project-odd visible post-6801 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-guatemala tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan trabajos en el Aeropuerto Internacional La Aurora\" data-date=\"2024-05-21T14:54:02-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/21\/avanzan-trabajos-en-el-aeropuerto-internacional-la-aurora\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5409-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5409-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5409-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_5409\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/21\/avanzan-trabajos-en-el-aeropuerto-internacional-la-aurora\/\" title=\"Avanzan trabajos en el Aeropuerto Internacional La Aurora\" rel=\"bookmark\">Avanzan trabajos en el Aeropuerto Internacional La Aurora<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/21\/avanzan-trabajos-en-el-aeropuerto-internacional-la-aurora\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan trabajos en el Aeropuerto Internacional La Aurora\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6904\" data-date=\"2024-05-16T10:26:47-06:00\" data-name=\"Decreto 5-2021\"><article class=\"post project-odd visible post-6904 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Decreto 5-2021\" data-date=\"2024-05-16T10:26:47-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/16\/decreto-5-2021\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20905%20565&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/decreto-5-2021-905x565.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/08\/decreto-5-2021-905x565.png 905w\" loading=\"eager\" style=\"--ratio: 905 \/ 565\" sizes=\"(max-width: 905px) 100vw, 905px\" alt=\"\" title=\"decreto 5-2021\" width=\"905\" height=\"565\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/16\/decreto-5-2021\/\" title=\"Decreto 5-2021\" rel=\"bookmark\">Decreto 5-2021<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/16\/decreto-5-2021\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Decreto 5-2021\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6806\" data-date=\"2024-05-13T15:07:08-06:00\" data-name=\"Avanzan Los Trabajos En La Carretera De La Cabecera Municipal De Chiquimula\"><article class=\"post project-odd visible post-6806 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chiquimula tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan Los Trabajos En La Carretera De La Cabecera Municipal De Chiquimula\" data-date=\"2024-05-13T15:07:08-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/13\/avanzan-los-trabajos-en-la-carretera-de-la-cabecera-municipal-de-chiquimula\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5816-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5816-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/06\/IMG_5816-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_5816\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/13\/avanzan-los-trabajos-en-la-carretera-de-la-cabecera-municipal-de-chiquimula\/\" title=\"Avanzan Los Trabajos En La Carretera De La Cabecera Municipal De Chiquimula\" rel=\"bookmark\">Avanzan Los Trabajos En La Carretera De La Cabecera Municipal De Chiquimula<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/05\/13\/avanzan-los-trabajos-en-la-carretera-de-la-cabecera-municipal-de-chiquimula\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Los Trabajos En La Carretera De La Cabecera Municipal De Chiquimula\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6733\" data-date=\"2024-04-19T16:13:45-06:00\" data-name=\"Avanzan trabajos en torre de control del Aeropuerto San Jos\u00e9, Escuintla\"><article class=\"post project-odd visible post-6733 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-escuintla tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avanzan trabajos en torre de control del Aeropuerto San Jos\u00e9, Escuintla\" data-date=\"2024-04-19T16:13:45-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/19\/avanzan-trabajos-en-torre-de-control-del-aeropuerto-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/DJI_0395-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/DJI_0395-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/DJI_0395-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/19\/avanzan-trabajos-en-torre-de-control-del-aeropuerto-san-jose-escuintla\/\" title=\"Avanzan trabajos en torre de control del Aeropuerto San Jos\u00e9, Escuintla\" rel=\"bookmark\">Avanzan trabajos en torre de control del Aeropuerto San Jos\u00e9, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/19\/avanzan-trabajos-en-torre-de-control-del-aeropuerto-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan trabajos en torre de control del Aeropuerto San Jos\u00e9, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6724\" data-date=\"2024-04-18T17:07:53-06:00\" data-name=\"Avanza trabajos en puente vehicular en Sipacapa, San Marcos\"><article class=\"post project-odd visible post-6724 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Avanza trabajos en puente vehicular en Sipacapa, San Marcos\" data-date=\"2024-04-18T17:07:53-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-sipacapa-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4069-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4069-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4069-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_4069\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-sipacapa-san-marcos\/\" title=\"Avanza trabajos en puente vehicular en Sipacapa, San Marcos\" rel=\"bookmark\">Avanza trabajos en puente vehicular en Sipacapa, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-sipacapa-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanza trabajos en puente vehicular en Sipacapa, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6715\" data-date=\"2024-04-18T15:56:12-06:00\" data-name=\"Avanza trabajos en puente vehicular en Catarina, San Marcos\"><article class=\"post project-odd visible post-6715 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Avanza trabajos en puente vehicular en Catarina, San Marcos\" data-date=\"2024-04-18T15:56:12-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-catarina-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4224-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4224-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_4224-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_4224\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-catarina-san-marcos\/\" title=\"Avanza trabajos en puente vehicular en Catarina, San Marcos\" rel=\"bookmark\">Avanza trabajos en puente vehicular en Catarina, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanza-trabajos-en-puente-vehicular-en-catarina-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanza trabajos en puente vehicular en Catarina, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6708\" data-date=\"2024-04-18T15:38:05-06:00\" data-name=\"Avanzan Trabajos en Carreteras de Sansare, El Progreso\"><article class=\"post project-odd visible post-6708 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-el-progreso tag-noticias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"Avanzan Trabajos en Carreteras de Sansare, El Progreso\" data-date=\"2024-04-18T15:38:05-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanzan-trabajos-en-carreteras-de-sansare-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_3561-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_3561-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/04\/IMG_3561-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_3561\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanzan-trabajos-en-carreteras-de-sansare-el-progreso\/\" title=\"Avanzan Trabajos en Carreteras de Sansare, El Progreso\" rel=\"bookmark\">Avanzan Trabajos en Carreteras de Sansare, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/04\/18\/avanzan-trabajos-en-carreteras-de-sansare-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan Trabajos en Carreteras de Sansare, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6656\" data-date=\"2024-03-19T16:16:45-06:00\" data-name=\"La Unidad de Convoyes Regionales trabaja en las carreteras municipales de San Antonio La Paz, El Progreso\"><article class=\"post project-odd visible post-6656 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"La Unidad de Convoyes Regionales trabaja en las carreteras municipales de San Antonio La Paz, El Progreso\" data-date=\"2024-03-19T16:16:45-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/03\/19\/la-unidad-de-convoyes-regionales-trabaja-en-las-carreteras-municipales-de-san-antonio-la-paz-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/03\/IMG_3660-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/03\/IMG_3660-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/03\/IMG_3660-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_3660\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/03\/19\/la-unidad-de-convoyes-regionales-trabaja-en-las-carreteras-municipales-de-san-antonio-la-paz-el-progreso\/\" title=\"La Unidad de Convoyes Regionales trabaja en las carreteras municipales de San Antonio La Paz, El Progreso\" rel=\"bookmark\">La Unidad de Convoyes Regionales trabaja en las carreteras municipales de San Antonio La Paz, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/03\/19\/la-unidad-de-convoyes-regionales-trabaja-en-las-carreteras-municipales-de-san-antonio-la-paz-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Unidad de Convoyes Regionales trabaja en las carreteras municipales de San Antonio La Paz, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6580\" data-date=\"2024-02-23T15:24:54-06:00\" data-name=\"Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora\"><article class=\"post project-odd visible post-6580 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias tag-operaciones category-20 description-off\" data-name=\"Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora\" data-date=\"2024-02-23T15:24:54-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/23\/supervision-de-mejoramiento-en-la-pista-de-taxeo-del-aeropuerto-internacional-la-aurora\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20449&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-7-720x449.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-7-720x449.png 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 449\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"image-7\" width=\"720\" height=\"449\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/23\/supervision-de-mejoramiento-en-la-pista-de-taxeo-del-aeropuerto-internacional-la-aurora\/\" title=\"Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora\" rel=\"bookmark\">Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/23\/supervision-de-mejoramiento-en-la-pista-de-taxeo-del-aeropuerto-internacional-la-aurora\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6447\" data-date=\"2024-02-06T11:39:16-06:00\" data-name=\"Ministra hace supervisi\u00f3n del Paso a Desnivel Av. Petapa y 53 Calle\"><article class=\"post project-odd visible post-6447 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias tag-operaciones category-20 description-off\" data-name=\"Ministra hace supervisi\u00f3n del Paso a Desnivel Av. Petapa y 53 Calle\" data-date=\"2024-02-06T11:39:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/06\/ministra-hace-supervision-del-paso-a-desnivel-av-petapa-y-53-calle\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-3-990x618.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-3-990x618.png 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-3-1485x927.png 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"image-3\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/06\/ministra-hace-supervision-del-paso-a-desnivel-av-petapa-y-53-calle\/\" title=\"Ministra hace supervisi\u00f3n del Paso a Desnivel Av. Petapa y 53 Calle\" rel=\"bookmark\">Ministra hace supervisi\u00f3n del Paso a Desnivel Av. Petapa y 53 Calle<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/02\/06\/ministra-hace-supervision-del-paso-a-desnivel-av-petapa-y-53-calle\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Ministra hace supervisi\u00f3n del Paso a Desnivel Av. Petapa y 53 Calle\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6442\" data-date=\"2024-01-25T17:07:02-06:00\" data-name=\"CIV Suspende la entrega de la Autopista Pal\u00edn-Escuintla\"><article class=\"post project-odd visible post-6442 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias category-20 description-off\" data-name=\"CIV Suspende la entrega de la Autopista Pal\u00edn-Escuintla\" data-date=\"2024-01-25T17:07:02-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/civ-suspende-la-entrega-de-la-autopista-palin-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20498%20311&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-8-498x311.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-8-498x311.png 498w\" loading=\"eager\" style=\"--ratio: 498 \/ 311\" sizes=\"(max-width: 498px) 100vw, 498px\" alt=\"\" title=\"image-8\" width=\"498\" height=\"311\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/civ-suspende-la-entrega-de-la-autopista-palin-escuintla\/\" title=\"CIV Suspende la entrega de la Autopista Pal\u00edn-Escuintla\" rel=\"bookmark\">CIV Suspende la entrega de la Autopista Pal\u00edn-Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/civ-suspende-la-entrega-de-la-autopista-palin-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about CIV Suspende la entrega de la Autopista Pal\u00edn-Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6435\" data-date=\"2024-01-25T16:30:07-06:00\" data-name=\"Nueva Ministra muestra avances en rescate de la instituci\u00f3n a una semana de gesti\u00f3n\"><article class=\"post project-odd visible post-6435 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias category-20 description-off\" data-name=\"Nueva Ministra muestra avances en rescate de la instituci\u00f3n a una semana de gesti\u00f3n\" data-date=\"2024-01-25T16:30:07-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/nueva-ministra-muestra-avances-en-rescate-de-la-institucion-a-una-semana-de-gestion\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20522%20326&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-6-522x326.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-6-522x326.png 522w\" loading=\"eager\" style=\"--ratio: 522 \/ 326\" sizes=\"(max-width: 522px) 100vw, 522px\" alt=\"\" title=\"image-6\" width=\"522\" height=\"326\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/nueva-ministra-muestra-avances-en-rescate-de-la-institucion-a-una-semana-de-gestion\/\" title=\"Nueva Ministra muestra avances en rescate de la instituci\u00f3n a una semana de gesti\u00f3n\" rel=\"bookmark\">Nueva Ministra muestra avances en rescate de la instituci\u00f3n a una semana de gesti\u00f3n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/nueva-ministra-muestra-avances-en-rescate-de-la-institucion-a-una-semana-de-gestion\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Nueva Ministra muestra avances en rescate de la instituci\u00f3n a una semana de gesti\u00f3n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6429\" data-date=\"2024-01-25T16:25:28-06:00\" data-name=\"Detectan micr\u00f3fonos ocultos en veh\u00edculos asignados a Ministra\"><article class=\"post project-odd visible post-6429 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-civ tag-noticias category-20 description-off\" data-name=\"Detectan micr\u00f3fonos ocultos en veh\u00edculos asignados a Ministra\" data-date=\"2024-01-25T16:25:28-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/detectan-microfonos-ocultos-en-vehiculos-asignados-a-ministra\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20769%20480&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-3-769x480.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-3-769x480.png 769w\" loading=\"eager\" style=\"--ratio: 769 \/ 480\" sizes=\"(max-width: 769px) 100vw, 769px\" alt=\"\" title=\"image-3\" width=\"769\" height=\"480\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/detectan-microfonos-ocultos-en-vehiculos-asignados-a-ministra\/\" title=\"Detectan micr\u00f3fonos ocultos en veh\u00edculos asignados a Ministra\" rel=\"bookmark\">Detectan micr\u00f3fonos ocultos en veh\u00edculos asignados a Ministra<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/25\/detectan-microfonos-ocultos-en-vehiculos-asignados-a-ministra\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Detectan micr\u00f3fonos ocultos en veh\u00edculos asignados a Ministra\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6424\" data-date=\"2024-01-16T16:11:12-06:00\" data-name=\"\u00a1Nueva Ministra de Comunicaciones!\"><article class=\"post project-odd visible post-6424 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"\u00a1Nueva Ministra de Comunicaciones!\" data-date=\"2024-01-16T16:11:12-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/16\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20809%20506&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-809x506.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-809x506.png 809w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/01\/image-810x506.png 810w\" loading=\"eager\" style=\"--ratio: 809 \/ 506\" sizes=\"(max-width: 809px) 100vw, 809px\" alt=\"\" title=\"image\" width=\"809\" height=\"506\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/16\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos-2\/\" title=\"\u00a1Nueva Ministra de Comunicaciones!\" rel=\"bookmark\">\u00a1Nueva Ministra de Comunicaciones!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2024\/01\/16\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Nueva Ministra de Comunicaciones!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6276\" data-date=\"2023-12-11T15:09:50-06:00\" data-name=\"El Fondo Social de Solidaridad informa a los guatemaltecos\"><article class=\"post project-odd visible post-6276 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-comuincados category-20 description-off\" data-name=\"El Fondo Social de Solidaridad informa a los guatemaltecos\" data-date=\"2023-12-11T15:09:50-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/11\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20449&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/410260212_741919391312641_657279502796314091_n-720x449.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/410260212_741919391312641_657279502796314091_n-720x449.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 449\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"410260212_741919391312641_657279502796314091_n\" width=\"720\" height=\"449\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/11\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos\/\" title=\"El Fondo Social de Solidaridad informa a los guatemaltecos\" rel=\"bookmark\">El Fondo Social de Solidaridad informa a los guatemaltecos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/11\/el-fondo-social-de-solidaridad-informa-a-los-guatemaltecos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El Fondo Social de Solidaridad informa a los guatemaltecos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6269\" data-date=\"2023-12-08T12:39:06-06:00\" data-name=\"Descanse en paz Diego Fernando Men\u00e9ndez Hern\u00e1ndez\"><article class=\"post project-odd visible post-6269 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-esquelas category-20 description-off\" data-name=\"Descanse en paz Diego Fernando Men\u00e9ndez Hern\u00e1ndez\" data-date=\"2023-12-08T12:39:06-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/08\/6269\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/8-12-2023-990x619.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/8-12-2023-990x619.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/8-12-2023-1406x879.jpg 1406w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"8-12-2023\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/08\/6269\/\" title=\"Descanse en paz Diego Fernando Men\u00e9ndez Hern\u00e1ndez\" rel=\"bookmark\">Descanse en paz Diego Fernando Men\u00e9ndez Hern\u00e1ndez<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/08\/6269\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Descanse en paz Diego Fernando Men\u00e9ndez Hern\u00e1ndez\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6014\" data-date=\"2023-12-05T18:13:18-06:00\" data-name=\"Seguimos con m\u00e1s avances en el Aeropuerto Internacional Mundo Maya,  Flores, Pet\u00e9n\"><article class=\"post project-odd visible post-6014 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-aeropuerto tag-carretera tag-flores tag-mundo-maya tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Seguimos con m\u00e1s avances en el Aeropuerto Internacional Mundo Maya,  Flores, Pet\u00e9n\" data-date=\"2023-12-05T18:13:18-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/05\/seguimos-con-mas-avances-en-el-aeropuerto-internacional-mundo-maya-flores-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20792%20494&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/05-12-2023-1-792x494.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/12\/05-12-2023-1-792x494.jpg 792w\" loading=\"eager\" style=\"--ratio: 792 \/ 494\" sizes=\"(max-width: 792px) 100vw, 792px\" alt=\"\" title=\"05-12-2023-1\" width=\"792\" height=\"494\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/05\/seguimos-con-mas-avances-en-el-aeropuerto-internacional-mundo-maya-flores-peten\/\" title=\"Seguimos con m\u00e1s avances en el Aeropuerto Internacional Mundo Maya,  Flores, Pet\u00e9n\" rel=\"bookmark\">Seguimos con m\u00e1s avances en el Aeropuerto Internacional Mundo Maya,  Flores, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/12\/05\/seguimos-con-mas-avances-en-el-aeropuerto-internacional-mundo-maya-flores-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Seguimos con m\u00e1s avances en el Aeropuerto Internacional Mundo Maya,  Flores, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"6003\" data-date=\"2023-11-29T09:45:47-06:00\" data-name=\"Mejoramiento de carretera en en San Benito-Santa Rita, San Benito, Pet\u00e9n.\"><article class=\"post project-odd visible post-6003 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carretera tag-noticias tag-operaciones tag-peten tag-reposicion tag-san-benito tag-santa-rita category-20 description-off\" data-name=\"Mejoramiento de carretera en en San Benito-Santa Rita, San Benito, Pet\u00e9n.\" data-date=\"2023-11-29T09:45:47-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/29\/mejoramiento-de-carretera-en-en-san-benito-santa-rita-san-benito-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/29-11-2023-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/29-11-2023-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/29-11-2023-1007x629.jpg 1007w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"29-11-2023\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/29\/mejoramiento-de-carretera-en-en-san-benito-santa-rita-san-benito-peten\/\" title=\"Mejoramiento de carretera en en San Benito-Santa Rita, San Benito, Pet\u00e9n.\" rel=\"bookmark\">Mejoramiento de carretera en en San Benito-Santa Rita, San Benito, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/29\/mejoramiento-de-carretera-en-en-san-benito-santa-rita-san-benito-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento de carretera en en San Benito-Santa Rita, San Benito, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5971\" data-date=\"2023-11-23T09:17:59-06:00\" data-name=\"Reposici\u00f3n del puente vehicular en El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-5971 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-jicaro tag-el-progreso tag-noticias tag-operaciones tag-puente-vehicular tag-reposicion category-20 description-off\" data-name=\"Reposici\u00f3n del puente vehicular en El J\u00edcaro, El Progreso\" data-date=\"2023-11-23T09:17:59-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/23\/reposicion-del-puente-vehicular-en-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/23-11-23-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/23-11-23-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/23-11-23-1007x629.jpg 1007w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"23-11-23\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/23\/reposicion-del-puente-vehicular-en-el-jicaro-el-progreso\/\" title=\"Reposici\u00f3n del puente vehicular en El J\u00edcaro, El Progreso\" rel=\"bookmark\">Reposici\u00f3n del puente vehicular en El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/23\/reposicion-del-puente-vehicular-en-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reposici\u00f3n del puente vehicular en El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5953\" data-date=\"2023-11-16T13:35:27-06:00\" data-name=\"Seguimos trabajando en reposici\u00f3n del puente vehicular El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-5953 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-jicaro tag-el-progreso tag-noticias tag-operaciones tag-puente-vehicular tag-reposicion category-20 description-off\" data-name=\"Seguimos trabajando en reposici\u00f3n del puente vehicular El J\u00edcaro, El Progreso\" data-date=\"2023-11-16T13:35:27-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/16\/seguimos-trabajando-en-el-puente-vehicular-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20893%20558&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/16-11-23-1-893x558.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/16-11-23-1-893x558.jpg 893w\" loading=\"eager\" style=\"--ratio: 893 \/ 558\" sizes=\"(max-width: 893px) 100vw, 893px\" alt=\"\" title=\"16-11-23\" width=\"893\" height=\"558\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/16\/seguimos-trabajando-en-el-puente-vehicular-el-jicaro-el-progreso\/\" title=\"Seguimos trabajando en reposici\u00f3n del puente vehicular El J\u00edcaro, El Progreso\" rel=\"bookmark\">Seguimos trabajando en reposici\u00f3n del puente vehicular El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/16\/seguimos-trabajando-en-el-puente-vehicular-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Seguimos trabajando en reposici\u00f3n del puente vehicular El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5948\" data-date=\"2023-11-13T16:31:01-06:00\" data-name=\"Mejoramiento en carretera; El Progreso, Jutiapa\"><article class=\"post project-odd visible post-5948 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-jutiapa tag-noticias tag-operaciones category-20 description-off\" data-name=\"Mejoramiento en carretera; El Progreso, Jutiapa\" data-date=\"2023-11-13T16:31:01-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/13\/mejoramiento-en-carretera-el-progreso-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/13-11-23-1-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/13-11-23-1-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/11\/13-11-23-1-1199x748.jpg 1199w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"13-11-23\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/13\/mejoramiento-en-carretera-el-progreso-jutiapa\/\" title=\"Mejoramiento en carretera; El Progreso, Jutiapa\" rel=\"bookmark\">Mejoramiento en carretera; El Progreso, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/11\/13\/mejoramiento-en-carretera-el-progreso-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento en carretera; El Progreso, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5918\" data-date=\"2023-10-17T09:23:12-06:00\" data-name=\"Avances en Flores, Pet\u00e9n.\"><article class=\"post project-odd visible post-5918 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-flores tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Avances en Flores, Pet\u00e9n.\" data-date=\"2023-10-17T09:23:12-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-flores-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20899%20561&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/14-10-2023-899x561.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/14-10-2023-899x561.jpg 899w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/14-10-2023-900x561.jpg 900w\" loading=\"eager\" style=\"--ratio: 899 \/ 561\" sizes=\"(max-width: 899px) 100vw, 899px\" alt=\"\" title=\"14-10-2023\" width=\"899\" height=\"561\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-flores-peten\/\" title=\"Avances en Flores, Pet\u00e9n.\" rel=\"bookmark\">Avances en Flores, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-flores-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avances en Flores, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5913\" data-date=\"2023-10-17T09:13:41-06:00\" data-name=\"Mejoramiento en Chuarrancho\"><article class=\"post project-odd visible post-5913 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-chuarrancho tag-guatemala tag-noticias tag-operaciones category-20 description-off\" data-name=\"Mejoramiento en Chuarrancho\" data-date=\"2023-10-17T09:13:41-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-chucarrancho\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/25-10-23-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/25-10-23-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/25-10-23-1025x639.jpg 1025w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"25-10-23\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-chucarrancho\/\" title=\"Mejoramiento en Chuarrancho\" rel=\"bookmark\">Mejoramiento en Chuarrancho<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-en-chucarrancho\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento en Chuarrancho\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5909\" data-date=\"2023-10-17T09:07:11-06:00\" data-name=\"Los avances contin\u00faan en Pet\u00e9n\"><article class=\"post project-odd visible post-5909 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-operaciones tag-peten tag-san-benito tag-santa-rita category-20 description-off\" data-name=\"Los avances contin\u00faan en Pet\u00e9n\" data-date=\"2023-10-17T09:07:11-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-de-carretera-en-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/05-10-23-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/05-10-23-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/10\/05-10-23-999x623.jpg 999w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"05-10-23\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-de-carretera-en-peten\/\" title=\"Los avances contin\u00faan en Pet\u00e9n\" rel=\"bookmark\">Los avances contin\u00faan en Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/10\/17\/mejoramiento-de-carretera-en-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Los avances contin\u00faan en Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5898\" data-date=\"2023-09-28T13:05:41-06:00\" data-name=\"Mejoramiento de carretera en aldeas de Chiquimulilla, Santa Rosa\"><article class=\"post project-odd visible post-5898 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-aldea-la-comba tag-aldea-la-vina tag-chiquimulilla tag-noticias tag-operaciones tag-pueblo-la-reforma tag-santa-rosa category-20 description-off\" data-name=\"Mejoramiento de carretera en aldeas de Chiquimulilla, Santa Rosa\" data-date=\"2023-09-28T13:05:41-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/28\/mejoramiento-de-carretera-en-aldeas-de-chiquimulilla-santa-rosa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/28-09-2023-1-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/28-09-2023-1-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/28-09-2023-1-1153x720.jpg 1153w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"28-09-2023\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/28\/mejoramiento-de-carretera-en-aldeas-de-chiquimulilla-santa-rosa\/\" title=\"Mejoramiento de carretera en aldeas de Chiquimulilla, Santa Rosa\" rel=\"bookmark\">Mejoramiento de carretera en aldeas de Chiquimulilla, Santa Rosa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/28\/mejoramiento-de-carretera-en-aldeas-de-chiquimulilla-santa-rosa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento de carretera en aldeas de Chiquimulilla, Santa Rosa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5893\" data-date=\"2023-09-27T11:04:16-06:00\" data-name=\"Avances en el mejoramiento carretera El Progreso, Jutiapa\"><article class=\"post project-odd visible post-5893 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-jutiapa tag-noticias tag-operaciones category-20 description-off\" data-name=\"Avances en el mejoramiento carretera El Progreso, Jutiapa\" data-date=\"2023-09-27T11:04:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/27\/avances-en-el-mejoramiento-en-carretera-el-progreso-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/383833313_699222562248991_6335314645459042093_n-990x619.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/383833313_699222562248991_6335314645459042093_n-990x619.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/383833313_699222562248991_6335314645459042093_n-1197x748.jpg 1197w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"383833313_699222562248991_6335314645459042093_n\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/27\/avances-en-el-mejoramiento-en-carretera-el-progreso-jutiapa\/\" title=\"Avances en el mejoramiento carretera El Progreso, Jutiapa\" rel=\"bookmark\">Avances en el mejoramiento carretera El Progreso, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/27\/avances-en-el-mejoramiento-en-carretera-el-progreso-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avances en el mejoramiento carretera El Progreso, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5889\" data-date=\"2023-09-26T13:19:33-06:00\" data-name=\"Construcci\u00f3n Paso a desnivel, Calzada Roosevelt\"><article class=\"post project-odd visible post-5889 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-calzada-roosevelt tag-noticias tag-operaciones tag-zona-11 category-20 description-off\" data-name=\"Construcci\u00f3n Paso a desnivel, Calzada Roosevelt\" data-date=\"2023-09-26T13:19:33-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/26\/construccion-paso-a-desnivel-calzada-roosevelt\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/26-09-2023-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/26-09-2023-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/26-09-2023-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"26-09-2023\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/26\/construccion-paso-a-desnivel-calzada-roosevelt\/\" title=\"Construcci\u00f3n Paso a desnivel, Calzada Roosevelt\" rel=\"bookmark\">Construcci\u00f3n Paso a desnivel, Calzada Roosevelt<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/26\/construccion-paso-a-desnivel-calzada-roosevelt\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Construcci\u00f3n Paso a desnivel, Calzada Roosevelt\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5884\" data-date=\"2023-09-22T13:40:37-06:00\" data-name=\"Mejoramiento en el Aeropuerto de San Jos\u00e9, Escuintla\"><article class=\"post project-odd visible post-5884 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-aeropuerto tag-escuintla tag-noticias tag-operaciones tag-san-jose category-20 description-off\" data-name=\"Mejoramiento en el Aeropuerto de San Jos\u00e9, Escuintla\" data-date=\"2023-09-22T13:40:37-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/22\/mejoramiento-en-el-aeropuerto-de-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20749%20468&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/22-09-2023-749x468.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/22-09-2023-749x468.jpg 749w\" loading=\"eager\" style=\"--ratio: 749 \/ 468\" sizes=\"(max-width: 749px) 100vw, 749px\" alt=\"\" title=\"22-09-2023\" width=\"749\" height=\"468\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/22\/mejoramiento-en-el-aeropuerto-de-san-jose-escuintla\/\" title=\"Mejoramiento en el Aeropuerto de San Jos\u00e9, Escuintla\" rel=\"bookmark\">Mejoramiento en el Aeropuerto de San Jos\u00e9, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/22\/mejoramiento-en-el-aeropuerto-de-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento en el Aeropuerto de San Jos\u00e9, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5880\" data-date=\"2023-09-21T10:31:20-06:00\" data-name=\"Contin\u00faan los trabajos en el Aeropuerto de San Jos\u00e9, Escuintla\"><article class=\"post project-odd visible post-5880 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-aeropuerto tag-escuintla tag-noticias tag-operaciones tag-san-jose category-20 description-off\" data-name=\"Contin\u00faan los trabajos en el Aeropuerto de San Jos\u00e9, Escuintla\" data-date=\"2023-09-21T10:31:20-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/21\/continuan-los-trabajos-en-el-aeropuerto-de-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-19-at-4.42.39-PM-PARA-BANNER-scaled-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-19-at-4.42.39-PM-PARA-BANNER-scaled-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-19-at-4.42.39-PM-PARA-BANNER-scaled-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/21\/continuan-los-trabajos-en-el-aeropuerto-de-san-jose-escuintla\/\" title=\"Contin\u00faan los trabajos en el Aeropuerto de San Jos\u00e9, Escuintla\" rel=\"bookmark\">Contin\u00faan los trabajos en el Aeropuerto de San Jos\u00e9, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/21\/continuan-los-trabajos-en-el-aeropuerto-de-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Contin\u00faan los trabajos en el Aeropuerto de San Jos\u00e9, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5869\" data-date=\"2023-09-20T10:24:48-06:00\" data-name=\"Puente vehicular en El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-5869 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-jicaro tag-el-progreso tag-noticias tag-operaciones tag-puente-vehicular-2 category-20 description-off\" data-name=\"Puente vehicular en El J\u00edcaro, El Progreso\" data-date=\"2023-09-20T10:24:48-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/20\/puente-vehicular-en-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG_5546-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG_5546-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG_5546-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG_5546\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/20\/puente-vehicular-en-el-jicaro-el-progreso\/\" title=\"Puente vehicular en El J\u00edcaro, El Progreso\" rel=\"bookmark\">Puente vehicular en El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/20\/puente-vehicular-en-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Puente vehicular en El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5832\" data-date=\"2023-09-12T11:10:14-06:00\" data-name=\"Construcci\u00f3n de puente en Sipacapa, San Marcos\"><article class=\"post project-odd visible post-5832 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-aldea-queca tag-caserio-agua-caliente tag-noticias tag-operaciones tag-puente-vehicular tag-san-marcos tag-sipacapa category-20 description-off\" data-name=\"Construcci\u00f3n de puente en Sipacapa, San Marcos\" data-date=\"2023-09-12T11:10:14-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/12\/construccion-de-puente-en-sipacapa-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG-20230912-WA0000-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG-20230912-WA0000-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/IMG-20230912-WA0000-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"IMG-20230912-WA0000\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/12\/construccion-de-puente-en-sipacapa-san-marcos\/\" title=\"Construcci\u00f3n de puente en Sipacapa, San Marcos\" rel=\"bookmark\">Construcci\u00f3n de puente en Sipacapa, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/12\/construccion-de-puente-en-sipacapa-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Construcci\u00f3n de puente en Sipacapa, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5819\" data-date=\"2023-09-08T13:13:20-06:00\" data-name=\"Progreso en carretera de San Francisco, Pet\u00e9n\"><article class=\"post project-odd visible post-5819 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-operaciones tag-peten tag-san-francisco tag-tecun-uman category-20 description-off\" data-name=\"Progreso en carretera de San Francisco, Pet\u00e9n\" data-date=\"2023-09-08T13:13:20-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/08\/progreso-en-carretera-de-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/08-09-2023-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/08-09-2023-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/08-09-2023-1248x779.jpg 1248w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"08-09-2023\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/08\/progreso-en-carretera-de-san-francisco-peten\/\" title=\"Progreso en carretera de San Francisco, Pet\u00e9n\" rel=\"bookmark\">Progreso en carretera de San Francisco, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/08\/progreso-en-carretera-de-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Progreso en carretera de San Francisco, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5815\" data-date=\"2023-09-07T16:20:37-06:00\" data-name=\"Trabajos en El Progreso Jutiapa\"><article class=\"post project-odd visible post-5815 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-jutiapa tag-operaciones category-20 description-off\" data-name=\"Trabajos en El Progreso Jutiapa\" data-date=\"2023-09-07T16:20:37-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/trabajos-en-el-progreso-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-1-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-1-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-1-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"07-09-2023-1\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/trabajos-en-el-progreso-jutiapa\/\" title=\"Trabajos en El Progreso Jutiapa\" rel=\"bookmark\">Trabajos en El Progreso Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/trabajos-en-el-progreso-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Trabajos en El Progreso Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5810\" data-date=\"2023-09-07T16:07:19-06:00\" data-name=\"Avances en Huit\u00e1n\"><article class=\"post project-odd visible post-5810 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-huitan tag-operaciones tag-quetzaltenango category-20 description-off\" data-name=\"Avances en Huit\u00e1n\" data-date=\"2023-09-07T16:07:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/avances-en-huitan\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/09\/07-09-2023-1196x746.jpg 1196w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"07-09-2023\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/avances-en-huitan\/\" title=\"Avances en Huit\u00e1n\" rel=\"bookmark\">Avances en Huit\u00e1n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/09\/07\/avances-en-huitan\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avances en Huit\u00e1n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5540\" data-date=\"2023-06-22T11:33:47-06:00\" data-name=\"COMUNICADO\"><article class=\"post project-odd visible no-img post-5540 type-post status-publish format-standard hentry category-uncategorized tag-noticias category-1 description-off\" data-name=\"COMUNICADO\" data-date=\"2023-06-22T11:33:47-06:00\">\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/22\/comunicado\/\" title=\"COMUNICADO\" rel=\"bookmark\">COMUNICADO<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/uncategorized\/\" >Uncategorized<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/22\/comunicado\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about COMUNICADO\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5533\" data-date=\"2023-06-20T17:08:54-06:00\" data-name=\"Reporte De Acciones | Santa Rosa\"><article class=\"post project-odd visible post-5533 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-santa-rosa category-20 description-off\" data-name=\"Reporte De Acciones | Santa Rosa\" data-date=\"2023-06-20T17:08:54-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-santa-rosa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20922%20576&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/355358526_643743797796868_1583145916149199445_n-922x576.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/355358526_643743797796868_1583145916149199445_n-922x576.jpg 922w\" loading=\"eager\" style=\"--ratio: 922 \/ 576\" sizes=\"(max-width: 922px) 100vw, 922px\" alt=\"\" title=\"355358526_643743797796868_1583145916149199445_n\" width=\"922\" height=\"576\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-santa-rosa\/\" title=\"Reporte De Acciones | Santa Rosa\" rel=\"bookmark\">Reporte De Acciones | Santa Rosa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-santa-rosa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Santa Rosa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5527\" data-date=\"2023-06-20T16:59:38-06:00\" data-name=\"Reporte De Acciones | El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-5527 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | El J\u00edcaro, El Progreso\" data-date=\"2023-06-20T16:59:38-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-el-jicaro-el-progreso-3\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20922%20576&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/355358526_643743797796868_1583145916149199445_n-922x576.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/355358526_643743797796868_1583145916149199445_n-922x576.jpg 922w\" loading=\"eager\" style=\"--ratio: 922 \/ 576\" sizes=\"(max-width: 922px) 100vw, 922px\" alt=\"\" title=\"355358526_643743797796868_1583145916149199445_n\" width=\"922\" height=\"576\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-el-jicaro-el-progreso-3\/\" title=\"Reporte De Acciones | El J\u00edcaro, El Progreso\" rel=\"bookmark\">Reporte De Acciones | El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-el-jicaro-el-progreso-3\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5518\" data-date=\"2023-06-20T15:31:19-06:00\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\"><article class=\"post project-odd visible post-5518 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chiquimula tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" data-date=\"2023-06-20T15:31:19-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-camotan-chiquimula-3\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20777%20486&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/352670690_643230447848203_1719276405281346880_n-777x486.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/352670690_643230447848203_1719276405281346880_n-777x486.jpg 777w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/06\/352670690_643230447848203_1719276405281346880_n-776x486.jpg 776w\" loading=\"eager\" style=\"--ratio: 777 \/ 486\" sizes=\"(max-width: 777px) 100vw, 777px\" alt=\"\" title=\"352670690_643230447848203_1719276405281346880_n\" width=\"777\" height=\"486\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-camotan-chiquimula-3\/\" title=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" rel=\"bookmark\">Reporte De Acciones | Camot\u00e1n, Chiquimula<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/06\/20\/reporte-de-acciones-camotan-chiquimula-3\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Camot\u00e1n, Chiquimula\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5339\" data-date=\"2023-05-31T17:03:43-06:00\" data-name=\"Reporte De Acciones | El Progreso, Jutiapa\"><article class=\"post project-odd visible post-5339 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chiquimula tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | El Progreso, Jutiapa\" data-date=\"2023-05-31T17:03:43-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/350486230_280492854416104_4535544707454646094_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/350486230_280492854416104_4535544707454646094_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"350486230_280492854416104_4535544707454646094_n\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa-2\/\" title=\"Reporte De Acciones | El Progreso, Jutiapa\" rel=\"bookmark\">Reporte De Acciones | El Progreso, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | El Progreso, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5332\" data-date=\"2023-05-31T16:59:30-06:00\" data-name=\"Reporte De Acciones | El Progreso, Jutiapa\"><article class=\"post project-odd visible post-5332 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-jutiapa tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | El Progreso, Jutiapa\" data-date=\"2023-05-31T16:59:30-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349848839_250373020774474_349154939830611085_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349848839_250373020774474_349154939830611085_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349848839_250373020774474_349154939830611085_n-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"349848839_250373020774474_349154939830611085_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa\/\" title=\"Reporte De Acciones | El Progreso, Jutiapa\" rel=\"bookmark\">Reporte De Acciones | El Progreso, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/31\/reporte-de-acciones-el-progreso-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | El Progreso, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5325\" data-date=\"2023-05-29T16:07:39-06:00\" data-name=\"Reporte De Acciones | Ixchiguan, San Marcos\"><article class=\"post project-odd visible post-5325 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Reporte De Acciones | Ixchiguan, San Marcos\" data-date=\"2023-05-29T16:07:39-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/29\/reporte-de-acciones-ixchiguan-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349577522_9345277208877652_6446373754504105079_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349577522_9345277208877652_6446373754504105079_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/349577522_9345277208877652_6446373754504105079_n-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"349577522_9345277208877652_6446373754504105079_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/29\/reporte-de-acciones-ixchiguan-san-marcos\/\" title=\"Reporte De Acciones | Ixchiguan, San Marcos\" rel=\"bookmark\">Reporte De Acciones | Ixchiguan, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/29\/reporte-de-acciones-ixchiguan-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Ixchiguan, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5319\" data-date=\"2023-05-25T20:49:07-06:00\" data-name=\"Reporte De Acciones | Catarina, San Marcos\"><article class=\"post project-odd visible post-5319 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Reporte De Acciones | Catarina, San Marcos\" data-date=\"2023-05-25T20:49:07-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/25\/reporte-de-acciones-catarina-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1685047304437-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1685047304437-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1685047304437-1080x674.jpg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"FB_IMG_1685047304437\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/25\/reporte-de-acciones-catarina-san-marcos\/\" title=\"Reporte De Acciones | Catarina, San Marcos\" rel=\"bookmark\">Reporte De Acciones | Catarina, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/25\/reporte-de-acciones-catarina-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Catarina, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5313\" data-date=\"2023-05-24T21:22:57-06:00\" data-name=\"Reporte De Acciones | San Pedro Necta, Huehuetenango\"><article class=\"post project-odd visible post-5313 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-huehuetenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | San Pedro Necta, Huehuetenango\" data-date=\"2023-05-24T21:22:57-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/24\/reporte-de-acciones-san-pedro-necta-huehuetenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/348847981_2249441685263731_5391983622271358941_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/348847981_2249441685263731_5391983622271358941_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"348847981_2249441685263731_5391983622271358941_n\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/24\/reporte-de-acciones-san-pedro-necta-huehuetenango\/\" title=\"Reporte De Acciones | San Pedro Necta, Huehuetenango\" rel=\"bookmark\">Reporte De Acciones | San Pedro Necta, Huehuetenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/24\/reporte-de-acciones-san-pedro-necta-huehuetenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | San Pedro Necta, Huehuetenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5284\" data-date=\"2023-05-19T16:52:44-06:00\" data-name=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\"><article class=\"post project-odd visible post-5284 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\" data-date=\"2023-05-19T16:52:44-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/19\/reporte-de-acciones-aldea-sacpuy-san-andres-peten-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1684514146213-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1684514146213-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1684514146213-1080x674.jpg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"FB_IMG_1684514146213\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/19\/reporte-de-acciones-aldea-sacpuy-san-andres-peten-2\/\" title=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/19\/reporte-de-acciones-aldea-sacpuy-san-andres-peten-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5278\" data-date=\"2023-05-18T17:15:29-06:00\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\"><article class=\"post project-odd visible post-5278 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chiquimula tag-guatemala tag-noticias category-20 description-off\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" data-date=\"2023-05-18T17:15:29-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/18\/reporte-de-acciones-camotan-chiquimula-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1684429554384-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/FB_IMG_1684429554384-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"FB_IMG_1684429554384\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/18\/reporte-de-acciones-camotan-chiquimula-2\/\" title=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" rel=\"bookmark\">Reporte De Acciones | Camot\u00e1n, Chiquimula<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/18\/reporte-de-acciones-camotan-chiquimula-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Camot\u00e1n, Chiquimula\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5271\" data-date=\"2023-05-16T17:58:07-06:00\" data-name=\"Reporte De Acciones | Chiquimulilla, Santa Rosa\"><article class=\"post project-odd visible post-5271 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-guatemala tag-noticias tag-santa-rosa category-20 description-off\" data-name=\"Reporte De Acciones | Chiquimulilla, Santa Rosa\" data-date=\"2023-05-16T17:58:07-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/16\/reporte-de-acciones-chiquimulilla-santa-rosa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/347103729_201058666170462_136621123625905376_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/347103729_201058666170462_136621123625905376_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/347103729_201058666170462_136621123625905376_n-1089x679.jpg 1089w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"347103729_201058666170462_136621123625905376_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/16\/reporte-de-acciones-chiquimulilla-santa-rosa\/\" title=\"Reporte De Acciones | Chiquimulilla, Santa Rosa\" rel=\"bookmark\">Reporte De Acciones | Chiquimulilla, Santa Rosa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/16\/reporte-de-acciones-chiquimulilla-santa-rosa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Chiquimulilla, Santa Rosa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5265\" data-date=\"2023-05-15T21:35:01-06:00\" data-name=\"Reporte De Acciones | Chuarrancho, Guatemala\"><article class=\"post project-odd visible post-5265 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-guatemala tag-noticias category-20 description-off\" data-name=\"Reporte De Acciones | Chuarrancho, Guatemala\" data-date=\"2023-05-15T21:35:01-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/15\/reporte-de-acciones-melchor-de-mencos-peten-3\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/346644752_198106799717616_3268394849639126881_n-990x619.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/346644752_198106799717616_3268394849639126881_n-990x619.jpg 990w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"346644752_198106799717616_3268394849639126881_n\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/15\/reporte-de-acciones-melchor-de-mencos-peten-3\/\" title=\"Reporte De Acciones | Chuarrancho, Guatemala\" rel=\"bookmark\">Reporte De Acciones | Chuarrancho, Guatemala<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/15\/reporte-de-acciones-melchor-de-mencos-peten-3\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Chuarrancho, Guatemala\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5255\" data-date=\"2023-05-08T23:11:41-06:00\" data-name=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\"><article class=\"post project-odd visible post-5255 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\" data-date=\"2023-05-08T23:11:41-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-melchor-de-mencos-peten-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345433683_535193538830144_277927098992387358_n-990x619.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345433683_535193538830144_277927098992387358_n-990x619.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345433683_535193538830144_277927098992387358_n-1107x692.jpg 1107w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"345433683_535193538830144_277927098992387358_n\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-melchor-de-mencos-peten-2\/\" title=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | Melchor de Mencos, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-melchor-de-mencos-peten-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5249\" data-date=\"2023-05-08T18:30:43-06:00\" data-name=\"Reporte De Acciones | Chimaltenango, Chimaltenango\"><article class=\"post project-odd visible post-5249 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chimaltenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | Chimaltenango, Chimaltenango\" data-date=\"2023-05-08T18:30:43-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-chimaltenango-chimaltenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345301538_1382104919032116_3035835974845382601_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345301538_1382104919032116_3035835974845382601_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/345301538_1382104919032116_3035835974845382601_n-1377x859.jpg 1377w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"345301538_1382104919032116_3035835974845382601_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-chimaltenango-chimaltenango\/\" title=\"Reporte De Acciones | Chimaltenango, Chimaltenango\" rel=\"bookmark\">Reporte De Acciones | Chimaltenango, Chimaltenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/08\/reporte-de-acciones-chimaltenango-chimaltenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Chimaltenango, Chimaltenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5243\" data-date=\"2023-05-04T22:55:26-06:00\" data-name=\"Reporte De Acciones | San Jos\u00e9, Escuintla\"><article class=\"post project-odd visible post-5243 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-escuintla tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | San Jos\u00e9, Escuintla\" data-date=\"2023-05-04T22:55:26-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/04\/reporte-de-acciones-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/344881539_505950238274275_5818656371744260534_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/344881539_505950238274275_5818656371744260534_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"344881539_505950238274275_5818656371744260534_n\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/04\/reporte-de-acciones-san-jose-escuintla\/\" title=\"Reporte De Acciones | San Jos\u00e9, Escuintla\" rel=\"bookmark\">Reporte De Acciones | San Jos\u00e9, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/04\/reporte-de-acciones-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | San Jos\u00e9, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5237\" data-date=\"2023-05-03T23:06:24-06:00\" data-name=\"Reporte De Acciones | Sanarate, El Progreso\"><article class=\"post project-odd visible post-5237 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | Sanarate, El Progreso\" data-date=\"2023-05-03T23:06:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/03\/reporte-de-acciones-sanarate-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20716%20446&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/344817397_206743978781028_4226512252132966325_n-716x446.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/344817397_206743978781028_4226512252132966325_n-716x446.jpg 716w\" loading=\"eager\" style=\"--ratio: 716 \/ 446\" sizes=\"(max-width: 716px) 100vw, 716px\" alt=\"\" title=\"344817397_206743978781028_4226512252132966325_n\" width=\"716\" height=\"446\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/03\/reporte-de-acciones-sanarate-el-progreso\/\" title=\"Reporte De Acciones | Sanarate, El Progreso\" rel=\"bookmark\">Reporte De Acciones | Sanarate, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/03\/reporte-de-acciones-sanarate-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Sanarate, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5231\" data-date=\"2023-05-02T23:02:58-06:00\" data-name=\"Reporte De Acciones | El Jicaro, El Progreso\"><article class=\"post project-odd visible post-5231 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-el-progreso tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | El Jicaro, El Progreso\" data-date=\"2023-05-02T23:02:58-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/02\/reporte-de-acciones-el-jicaro-el-progreso-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-02-at-4.17.34-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-02-at-4.17.34-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-02-at-4.17.34-PM-1089x679.jpeg 1089w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2023-05-02-at-4.17.34-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/02\/reporte-de-acciones-el-jicaro-el-progreso-2\/\" title=\"Reporte De Acciones | El Jicaro, El Progreso\" rel=\"bookmark\">Reporte De Acciones | El Jicaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/05\/02\/reporte-de-acciones-el-jicaro-el-progreso-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | El Jicaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5225\" data-date=\"2023-04-27T22:26:47-06:00\" data-name=\"Reporte De Acciones | San Jos\u00e9, Escuintla | Muro Perimetral\"><article class=\"post project-odd visible post-5225 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-escuintla tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | San Jos\u00e9, Escuintla | Muro Perimetral\" data-date=\"2023-04-27T22:26:47-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/27\/reporte-de-acciones-san-jose-escuintla-muro-perimetral\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20893%20558&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/344087413_988145755458061_4615653876435410837_n-893x558.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/344087413_988145755458061_4615653876435410837_n-893x558.jpg 893w\" loading=\"eager\" style=\"--ratio: 893 \/ 558\" sizes=\"(max-width: 893px) 100vw, 893px\" alt=\"\" title=\"344087413_988145755458061_4615653876435410837_n\" width=\"893\" height=\"558\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/27\/reporte-de-acciones-san-jose-escuintla-muro-perimetral\/\" title=\"Reporte De Acciones | San Jos\u00e9, Escuintla | Muro Perimetral\" rel=\"bookmark\">Reporte De Acciones | San Jos\u00e9, Escuintla | Muro Perimetral<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/27\/reporte-de-acciones-san-jose-escuintla-muro-perimetral\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | San Jos\u00e9, Escuintla | Muro Perimetral\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5219\" data-date=\"2023-04-25T23:59:36-06:00\" data-name=\"Reporte De Acciones | Sipacapa, San Marcos\"><article class=\"post project-odd visible post-5219 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-san-marcos category-20 description-off\" data-name=\"Reporte De Acciones | Sipacapa, San Marcos\" data-date=\"2023-04-25T23:59:36-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/25\/reporte-de-acciones-sipacapa-san-marcos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20780%20487&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682466406161-780x487.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682466406161-780x487.jpg 780w\" loading=\"eager\" style=\"--ratio: 780 \/ 487\" sizes=\"(max-width: 780px) 100vw, 780px\" alt=\"\" title=\"FB_IMG_1682466406161\" width=\"780\" height=\"487\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/25\/reporte-de-acciones-sipacapa-san-marcos\/\" title=\"Reporte De Acciones | Sipacapa, San Marcos\" rel=\"bookmark\">Reporte De Acciones | Sipacapa, San Marcos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/25\/reporte-de-acciones-sipacapa-san-marcos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Sipacapa, San Marcos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5195\" data-date=\"2023-04-24T23:47:57-06:00\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\"><article class=\"post project-odd visible post-5195 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chiquimula tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" data-date=\"2023-04-24T23:47:57-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-camotan-chiquimula\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20972%20607&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682379791192-972x607.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682379791192-972x607.jpg 972w\" loading=\"eager\" style=\"--ratio: 972 \/ 607\" sizes=\"(max-width: 972px) 100vw, 972px\" alt=\"\" title=\"FB_IMG_1682379791192\" width=\"972\" height=\"607\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-camotan-chiquimula\/\" title=\"Reporte De Acciones | Camot\u00e1n, Chiquimula\" rel=\"bookmark\">Reporte De Acciones | Camot\u00e1n, Chiquimula<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-camotan-chiquimula\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Camot\u00e1n, Chiquimula\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5181\" data-date=\"2023-04-24T23:38:17-06:00\" data-name=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\"><article class=\"post project-odd visible post-5181 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\" data-date=\"2023-04-24T23:38:17-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-melchor-de-mencos-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20729%20455&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682373185603-729x455.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/FB_IMG_1682373185603-729x455.jpg 729w\" loading=\"eager\" style=\"--ratio: 729 \/ 455\" sizes=\"(max-width: 729px) 100vw, 729px\" alt=\"\" title=\"FB_IMG_1682373185603\" width=\"729\" height=\"455\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-melchor-de-mencos-peten\/\" title=\"Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | Melchor de Mencos, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/24\/reporte-de-acciones-melchor-de-mencos-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Melchor de Mencos, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5152\" data-date=\"2023-04-18T22:18:24-06:00\" data-name=\"Reporte De Acciones | Comapa, Jutiapa\"><article class=\"post project-odd visible post-5152 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-jutiapa tag-noticias tag-operaciones category-20 description-off\" data-name=\"Reporte De Acciones | Comapa, Jutiapa\" data-date=\"2023-04-18T22:18:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/18\/reporte-de-acciones-comapa-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230414_114802-comprimido-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230414_114802-comprimido-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230414_114802-comprimido-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"PSX_20230414_114802 comprimido\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/18\/reporte-de-acciones-comapa-jutiapa\/\" title=\"Reporte De Acciones | Comapa, Jutiapa\" rel=\"bookmark\">Reporte De Acciones | Comapa, Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/18\/reporte-de-acciones-comapa-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Comapa, Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5134\" data-date=\"2023-04-13T19:25:25-06:00\" data-name=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\"><article class=\"post project-odd visible post-5134 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\" data-date=\"2023-04-13T19:25:25-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/13\/reporte-de-acciones-aldea-sacpuy-san-andres-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230331_173349_comprimida-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230331_173349_comprimida-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230331_173349_comprimida-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/13\/reporte-de-acciones-aldea-sacpuy-san-andres-peten\/\" title=\"Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/13\/reporte-de-acciones-aldea-sacpuy-san-andres-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Aldea Sacpuy, San Andr\u00e9s, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5074\" data-date=\"2023-04-09T19:42:37-06:00\" data-name=\"Semana Santa\"><article class=\"post project-odd visible post-5074 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-carreteras tag-noticias tag-operaciones category-20 description-off\" data-name=\"Semana Santa\" data-date=\"2023-04-09T19:42:37-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/09\/semana-santa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20863%20540&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Portada-863x540.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Portada-863x540.jpg 863w\" loading=\"eager\" style=\"--ratio: 863 \/ 540\" sizes=\"(max-width: 863px) 100vw, 863px\" alt=\"\" title=\"Portada\" width=\"863\" height=\"540\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/09\/semana-santa\/\" title=\"Semana Santa\" rel=\"bookmark\">Semana Santa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/09\/semana-santa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Semana Santa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5080\" data-date=\"2023-04-05T08:23:00-06:00\" data-name=\"Recomendaciones Para Semana Santa\"><article class=\"post project-odd visible post-5080 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-carreteras tag-noticias tag-operaciones category-20 description-off\" data-name=\"Recomendaciones Para Semana Santa\" data-date=\"2023-04-05T08:23:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/05\/semana-santa-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20526%20328&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/339892121_1307151569875931_8475875651692868001_n-526x328.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/339892121_1307151569875931_8475875651692868001_n-526x328.jpg 526w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/339892121_1307151569875931_8475875651692868001_n-526x329.jpg 526w\" loading=\"eager\" style=\"--ratio: 526 \/ 328\" sizes=\"(max-width: 526px) 100vw, 526px\" alt=\"\" title=\"339892121_1307151569875931_8475875651692868001_n\" width=\"526\" height=\"328\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/05\/semana-santa-2\/\" title=\"Recomendaciones Para Semana Santa\" rel=\"bookmark\">Recomendaciones Para Semana Santa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/05\/semana-santa-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Recomendaciones Para Semana Santa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5085\" data-date=\"2023-04-03T20:27:16-06:00\" data-name=\"Decanse en paz Eduardo Espina Flori\u00e1n\"><article class=\"post project-odd visible post-5085 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-esquelas category-20 description-off\" data-name=\"Decanse en paz Eduardo Espina Flori\u00e1n\" data-date=\"2023-04-03T20:27:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/03\/decanse-en-paz-eduardo-espina-florian\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20809%20506&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Eduardo-Espina-Florian-809x506.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Eduardo-Espina-Florian-809x506.jpg 809w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Eduardo-Espina-Florian-810x506.jpg 810w\" loading=\"eager\" style=\"--ratio: 809 \/ 506\" sizes=\"(max-width: 809px) 100vw, 809px\" alt=\"\" title=\"Eduardo-Espina-Florian\" width=\"809\" height=\"506\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/03\/decanse-en-paz-eduardo-espina-florian\/\" title=\"Decanse en paz Eduardo Espina Flori\u00e1n\" rel=\"bookmark\">Decanse en paz Eduardo Espina Flori\u00e1n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/03\/decanse-en-paz-eduardo-espina-florian\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/03\/decanse-en-paz-eduardo-espina-florian\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Decanse en paz Eduardo Espina Flori\u00e1n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5099\" data-date=\"2023-04-01T20:32:21-06:00\" data-name=\"Reporte De Acciones | Flores Pet\u00e9n\"><article class=\"post project-odd visible post-5099 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | Flores Pet\u00e9n\" data-date=\"2023-04-01T20:32:21-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/01\/reporte-de-acciones-flores-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0998-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0998-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0998-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/01\/reporte-de-acciones-flores-peten\/\" title=\"Reporte De Acciones | Flores Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | Flores Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/04\/01\/reporte-de-acciones-flores-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Flores Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5107\" data-date=\"2023-03-31T14:58:12-06:00\" data-name=\"Reporte De Acciones | San Francisco, Pet\u00e9n.\"><article class=\"post project-odd visible post-5107 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | San Francisco, Pet\u00e9n.\" data-date=\"2023-03-31T14:58:12-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/31\/reporte-de-acciones-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230330_135040-comprimido-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230330_135040-comprimido-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230330_135040-comprimido-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/31\/reporte-de-acciones-san-francisco-peten\/\" title=\"Reporte De Acciones | San Francisco, Pet\u00e9n.\" rel=\"bookmark\">Reporte De Acciones | San Francisco, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/31\/reporte-de-acciones-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | San Francisco, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5115\" data-date=\"2023-03-30T15:38:20-06:00\" data-name=\"Reporte De Acciones | San Benito, Pet\u00e9n\"><article class=\"post project-odd visible post-5115 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-operaciones tag-peten category-20 description-off\" data-name=\"Reporte De Acciones | San Benito, Pet\u00e9n\" data-date=\"2023-03-30T15:38:20-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/30\/reporte-de-acciones-san-benito-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0862-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0862-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0862-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/30\/reporte-de-acciones-san-benito-peten\/\" title=\"Reporte De Acciones | San Benito, Pet\u00e9n\" rel=\"bookmark\">Reporte De Acciones | San Benito, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/30\/reporte-de-acciones-san-benito-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | San Benito, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5123\" data-date=\"2023-03-28T17:42:26-06:00\" data-name=\"Decanse en paz Zoila Aminta Carantes D\u00e1rila de Urruela\"><article class=\"post project-odd visible post-5123 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-esquelas category-20 description-off\" data-name=\"Decanse en paz Zoila Aminta Carantes D\u00e1rila de Urruela\" data-date=\"2023-03-28T17:42:26-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/28\/decanse-en-paz-zoila-aminta-carantes-darila-de-urruela\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20809%20506&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Zoila-809x506.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Zoila-809x506.jpg 809w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/Zoila-810x506.jpg 810w\" loading=\"eager\" style=\"--ratio: 809 \/ 506\" sizes=\"(max-width: 809px) 100vw, 809px\" alt=\"\" title=\"Zoila\" width=\"809\" height=\"506\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/28\/decanse-en-paz-zoila-aminta-carantes-darila-de-urruela\/\" title=\"Decanse en paz Zoila Aminta Carantes D\u00e1rila de Urruela\" rel=\"bookmark\">Decanse en paz Zoila Aminta Carantes D\u00e1rila de Urruela<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/28\/decanse-en-paz-zoila-aminta-carantes-darila-de-urruela\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/28\/decanse-en-paz-zoila-aminta-carantes-darila-de-urruela\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Decanse en paz Zoila Aminta Carantes D\u00e1rila de Urruela\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5143\" data-date=\"2023-03-23T22:07:25-06:00\" data-name=\"Reporte De Acciones | Tototonicap\u00e1n\"><article class=\"post project-odd visible post-5143 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-unidad-de-convoyes-regionales category-20 description-off\" data-name=\"Reporte De Acciones | Tototonicap\u00e1n\" data-date=\"2023-03-23T22:07:25-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/23\/reporte-de-acciones-tototonicapan\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0645-scaled-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0645-scaled-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/DJI_0645-scaled-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/23\/reporte-de-acciones-tototonicapan\/\" title=\"Reporte De Acciones | Tototonicap\u00e1n\" rel=\"bookmark\">Reporte De Acciones | Tototonicap\u00e1n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/23\/reporte-de-acciones-tototonicapan\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | Tototonicap\u00e1n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"5126\" data-date=\"2023-03-20T18:37:27-06:00\" data-name=\"Reporte De Acciones | El J\u00edcaro, El Progreso\"><article class=\"post project-odd visible post-5126 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-el-progreso tag-noticias tag-operaciones tag-puentes category-20 description-off\" data-name=\"Reporte De Acciones | El J\u00edcaro, El Progreso\" data-date=\"2023-03-20T18:37:27-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/20\/reporte-de-acciones-el-jicaro-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230321_130542_comprimida-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230321_130542_comprimida-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/04\/PSX_20230321_130542_comprimida-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"default\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/20\/reporte-de-acciones-el-jicaro-el-progreso\/\" title=\"Reporte De Acciones | El J\u00edcaro, El Progreso\" rel=\"bookmark\">Reporte De Acciones | El J\u00edcaro, El Progreso<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/03\/20\/reporte-de-acciones-el-jicaro-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Reporte De Acciones | El J\u00edcaro, El Progreso\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4937\" data-date=\"2023-01-27T16:01:16-06:00\" data-name=\"Continuan los trabajos en Chimaltenango, Chimaltenango\"><article class=\"post project-odd visible post-4937 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-chimaltenango tag-noticias tag-operaciones category-20 description-off\" data-name=\"Continuan los trabajos en Chimaltenango, Chimaltenango\" data-date=\"2023-01-27T16:01:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/27\/continuan-los-trabajos-en-chimaltenango-chimaltenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-1441x900.jpg 1441w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"2\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/27\/continuan-los-trabajos-en-chimaltenango-chimaltenango\/\" title=\"Continuan los trabajos en Chimaltenango, Chimaltenango\" rel=\"bookmark\">Continuan los trabajos en Chimaltenango, Chimaltenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/27\/continuan-los-trabajos-en-chimaltenango-chimaltenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continuan los trabajos en Chimaltenango, Chimaltenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4913\" data-date=\"2023-01-18T22:49:17-06:00\" data-name=\"\u00a1Inicio de trabajos en Carretera CA-13 Aeropuerto Internacional Mundo Maya!\"><article class=\"post project-odd visible post-4913 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias tag-peten category-20 description-off\" data-name=\"\u00a1Inicio de trabajos en Carretera CA-13 Aeropuerto Internacional Mundo Maya!\" data-date=\"2023-01-18T22:49:17-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/inicio-de-trabajos-en-carretera-ca-13-aeropuerto-internacional-mundo-maya\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/326046796_732305721752963_6712215754640315030_n-1-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/326046796_732305721752963_6712215754640315030_n-1-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"326046796_732305721752963_6712215754640315030_n-1\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/inicio-de-trabajos-en-carretera-ca-13-aeropuerto-internacional-mundo-maya\/\" title=\"\u00a1Inicio de trabajos en Carretera CA-13 Aeropuerto Internacional Mundo Maya!\" rel=\"bookmark\">\u00a1Inicio de trabajos en Carretera CA-13 Aeropuerto Internacional Mundo Maya!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/inicio-de-trabajos-en-carretera-ca-13-aeropuerto-internacional-mundo-maya\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Inicio de trabajos en Carretera CA-13 Aeropuerto Internacional Mundo Maya!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4900\" data-date=\"2023-01-18T21:35:58-06:00\" data-name=\"Avances en el mejoramiento de carretera en Melchor de Mencos, Pet\u00e9n.\"><article class=\"post project-odd visible post-4900 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-operaciones tag-peten category-20 description-off\" data-name=\"Avances en el mejoramiento de carretera en Melchor de Mencos, Pet\u00e9n.\" data-date=\"2023-01-18T21:35:58-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/avances-en-el-mejoramiento-de-carretera-en-melchor-de-mencos-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20619&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/PSX_20230117_105229-990x619.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/PSX_20230117_105229-990x619.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/PSX_20230117_105229-1485x929.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 619\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"melchor de mencos, pet\u00e9n\" title=\"PSX_20230117_105229\" width=\"990\" height=\"619\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/avances-en-el-mejoramiento-de-carretera-en-melchor-de-mencos-peten\/\" title=\"Avances en el mejoramiento de carretera en Melchor de Mencos, Pet\u00e9n.\" rel=\"bookmark\">Avances en el mejoramiento de carretera en Melchor de Mencos, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/18\/avances-en-el-mejoramiento-de-carretera-en-melchor-de-mencos-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avances en el mejoramiento de carretera en Melchor de Mencos, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4896\" data-date=\"2023-01-17T18:28:12-06:00\" data-name=\"Decanse en paz Ren\u00e9 Mota\"><article class=\"post project-odd visible post-4896 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-esquelas category-20 description-off\" data-name=\"Decanse en paz Ren\u00e9 Mota\" data-date=\"2023-01-17T18:28:12-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/17\/decanse-en-paz-rene-mota\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-17-at-9.30.41-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-17-at-9.30.41-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-17-at-9.30.41-PM-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2023-01-17-at-9.30.41-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/17\/decanse-en-paz-rene-mota\/\" title=\"Decanse en paz Ren\u00e9 Mota\" rel=\"bookmark\">Decanse en paz Ren\u00e9 Mota<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/17\/decanse-en-paz-rene-mota\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/17\/decanse-en-paz-rene-mota\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Decanse en paz Ren\u00e9 Mota\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4880\" data-date=\"2023-01-09T16:48:51-06:00\" data-name=\"\u00a1Continuamos trabajando para Camot\u00e1n, Chiquimula!\"><article class=\"post project-odd visible post-4880 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-puentes category-20 description-off\" data-name=\"\u00a1Continuamos trabajando para Camot\u00e1n, Chiquimula!\" data-date=\"2023-01-09T16:48:51-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/09\/continuamos-trabajando-para-camotan-chiquimula\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20922%20576&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323349088_721502949584216_5620999760669479494_n-922x576.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323349088_721502949584216_5620999760669479494_n-922x576.jpg 922w\" loading=\"eager\" style=\"--ratio: 922 \/ 576\" sizes=\"(max-width: 922px) 100vw, 922px\" alt=\"\" title=\"323349088_721502949584216_5620999760669479494_n\" width=\"922\" height=\"576\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/09\/continuamos-trabajando-para-camotan-chiquimula\/\" title=\"\u00a1Continuamos trabajando para Camot\u00e1n, Chiquimula!\" rel=\"bookmark\">\u00a1Continuamos trabajando para Camot\u00e1n, Chiquimula!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/09\/continuamos-trabajando-para-camotan-chiquimula\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Continuamos trabajando para Camot\u00e1n, Chiquimula!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4877\" data-date=\"2023-01-05T15:31:00-06:00\" data-name=\"\u00a1Encu\u00e9ntranos en tus redes!\"><article class=\"post project-odd visible post-4877 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Encu\u00e9ntranos en tus redes!\" data-date=\"2023-01-05T15:31:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/05\/encuentranos-en-tus-redes\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20526%20328&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323626457_9278988708793332_5097022422558742947_n-526x328.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323626457_9278988708793332_5097022422558742947_n-526x328.jpg 526w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323626457_9278988708793332_5097022422558742947_n-526x329.jpg 526w\" loading=\"eager\" style=\"--ratio: 526 \/ 328\" sizes=\"(max-width: 526px) 100vw, 526px\" alt=\"\" title=\"323626457_9278988708793332_5097022422558742947_n\" width=\"526\" height=\"328\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/05\/encuentranos-en-tus-redes\/\" title=\"\u00a1Encu\u00e9ntranos en tus redes!\" rel=\"bookmark\">\u00a1Encu\u00e9ntranos en tus redes!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/05\/encuentranos-en-tus-redes\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Encu\u00e9ntranos en tus redes!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4851\" data-date=\"2023-01-04T17:21:37-06:00\" data-name=\"Se avanza con los trabajos en Huehuetenango\"><article class=\"post project-odd visible post-4851 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-operaciones category-20 description-off\" data-name=\"Se avanza con los trabajos en Huehuetenango\" data-date=\"2023-01-04T17:21:37-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/04\/se-avanza-con-los-trabajos-en-huehuetenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/2-1080x674.jpeg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"2\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/04\/se-avanza-con-los-trabajos-en-huehuetenango\/\" title=\"Se avanza con los trabajos en Huehuetenango\" rel=\"bookmark\">Se avanza con los trabajos en Huehuetenango<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/04\/se-avanza-con-los-trabajos-en-huehuetenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Se avanza con los trabajos en Huehuetenango\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4872\" data-date=\"2023-01-01T05:19:00-06:00\" data-name=\"Feliz A\u00f1o Nuevo 2023\"><article class=\"post project-odd visible post-4872 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-festividad category-20 description-off\" data-name=\"Feliz A\u00f1o Nuevo 2023\" data-date=\"2023-01-01T05:19:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/01\/feliz-ano-nuevo-2023\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20526%20328&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323227594_877999880006659_6944415504975120684_n-526x328.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323227594_877999880006659_6944415504975120684_n-526x328.jpg 526w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2023\/01\/323227594_877999880006659_6944415504975120684_n-526x329.jpg 526w\" loading=\"eager\" style=\"--ratio: 526 \/ 328\" sizes=\"(max-width: 526px) 100vw, 526px\" alt=\"\" title=\"323227594_877999880006659_6944415504975120684_n\" width=\"526\" height=\"328\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/01\/feliz-ano-nuevo-2023\/\" title=\"Feliz A\u00f1o Nuevo 2023\" rel=\"bookmark\">Feliz A\u00f1o Nuevo 2023<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2023\/01\/01\/feliz-ano-nuevo-2023\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Feliz A\u00f1o Nuevo 2023\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4830\" data-date=\"2022-12-22T16:52:37-06:00\" data-name=\"Avanzan los trabajos en el puente a desnivel sobre la Avenida Petapa\"><article class=\"post project-odd visible post-4830 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Avanzan los trabajos en el puente a desnivel sobre la Avenida Petapa\" data-date=\"2022-12-22T16:52:37-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/22\/avanzan-los-trabajos-en-el-puente-a-desnivel-sobre-la-avenida-petapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.14.07-5-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.14.07-5-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.14.07-5-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-12-14-at-15.14.07-5\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/22\/avanzan-los-trabajos-en-el-puente-a-desnivel-sobre-la-avenida-petapa\/\" title=\"Avanzan los trabajos en el puente a desnivel sobre la Avenida Petapa\" rel=\"bookmark\">Avanzan los trabajos en el puente a desnivel sobre la Avenida Petapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/22\/avanzan-los-trabajos-en-el-puente-a-desnivel-sobre-la-avenida-petapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan los trabajos en el puente a desnivel sobre la Avenida Petapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4811\" data-date=\"2022-12-21T21:20:00-06:00\" data-name=\"Avances en la construcci\u00f3n del paso a desnivel sobre la Calzada Roosevelt.\"><article class=\"post project-odd visible post-4811 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Avances en la construcci\u00f3n del paso a desnivel sobre la Calzada Roosevelt.\" data-date=\"2022-12-21T21:20:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/21\/avances-en-la-construccion-del-paso-a-desnivel-sobre-la-calzada-roosevelt\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.11.13-1-1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.11.13-1-1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-14-at-15.11.13-1-1-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"zona 7 y 11\" title=\"WhatsApp Image 2022-12-14 at 15.11.13 (1)\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/21\/avances-en-la-construccion-del-paso-a-desnivel-sobre-la-calzada-roosevelt\/\" title=\"Avances en la construcci\u00f3n del paso a desnivel sobre la Calzada Roosevelt.\" rel=\"bookmark\">Avances en la construcci\u00f3n del paso a desnivel sobre la Calzada Roosevelt.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/21\/avances-en-la-construccion-del-paso-a-desnivel-sobre-la-calzada-roosevelt\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avances en la construcci\u00f3n del paso a desnivel sobre la Calzada Roosevelt.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4802\" data-date=\"2022-12-20T16:48:16-06:00\" data-name=\"\u00a1Avanzamos en los trabajos en San Francisco, Pet\u00e9n!\"><article class=\"post project-odd visible post-4802 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"\u00a1Avanzamos en los trabajos en San Francisco, Pet\u00e9n!\" data-date=\"2022-12-20T16:48:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/20\/avanzamos-en-los-trabajos-en-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-20-at-10.18.00-2-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-20-at-10.18.00-2-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-20-at-10.18.00-2-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-12-20-at-10.18.00-2\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/20\/avanzamos-en-los-trabajos-en-san-francisco-peten\/\" title=\"\u00a1Avanzamos en los trabajos en San Francisco, Pet\u00e9n!\" rel=\"bookmark\">\u00a1Avanzamos en los trabajos en San Francisco, Pet\u00e9n!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/20\/avanzamos-en-los-trabajos-en-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Avanzamos en los trabajos en San Francisco, Pet\u00e9n!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4776\" data-date=\"2022-12-16T15:41:16-06:00\" data-name=\"La v\u00edspera de la Navidad es una \u00e9poca especial\"><article class=\"post project-odd visible post-4776 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"La v\u00edspera de la Navidad es una \u00e9poca especial\" data-date=\"2022-12-16T15:41:16-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/16\/la-vispera-de-la-navidad-es-una-epoca-especial\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-16-at-15.27.48-5-1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-16-at-15.27.48-5-1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-16-at-15.27.48-5-1-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Navidad\" title=\"Navidad\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/16\/la-vispera-de-la-navidad-es-una-epoca-especial\/\" title=\"La v\u00edspera de la Navidad es una \u00e9poca especial\" rel=\"bookmark\">La v\u00edspera de la Navidad es una \u00e9poca especial<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/16\/la-vispera-de-la-navidad-es-una-epoca-especial\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La v\u00edspera de la Navidad es una \u00e9poca especial\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4741\" data-date=\"2022-12-15T23:00:44-06:00\" data-name=\"Campa\u00f1a de vacunaci\u00f3n contra la Influenza\"><article class=\"post project-odd visible post-4741 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Campa\u00f1a de vacunaci\u00f3n contra la Influenza\" data-date=\"2022-12-15T23:00:44-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/15\/campana-de-vacunacion-contra-la-influenza\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-15.51.45-3-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-15.51.45-3-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-15.51.45-3-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-12-12-at-15.51.45-3\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/15\/campana-de-vacunacion-contra-la-influenza\/\" title=\"Campa\u00f1a de vacunaci\u00f3n contra la Influenza\" rel=\"bookmark\">Campa\u00f1a de vacunaci\u00f3n contra la Influenza<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/15\/campana-de-vacunacion-contra-la-influenza\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Campa\u00f1a de vacunaci\u00f3n contra la Influenza\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4719\" data-date=\"2022-12-07T19:38:35-06:00\" data-name=\"La quema del diablo.\"><article class=\"post project-odd visible post-4719 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"La quema del diablo.\" data-date=\"2022-12-07T19:38:35-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/la-quema-del-diablo\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-07-at-10.27.58-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-07-at-10.27.58-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"artes\" title=\"WhatsApp Image 2022-12-07 at 10.27.58\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/la-quema-del-diablo\/\" title=\"La quema del diablo.\" rel=\"bookmark\">La quema del diablo.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/la-quema-del-diablo\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La quema del diablo.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4711\" data-date=\"2022-12-07T18:56:56-06:00\" data-name=\"\u00a1Feliz D\u00eda del Locutor Nacional!\"><article class=\"post project-odd visible post-4711 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Feliz D\u00eda del Locutor Nacional!\" data-date=\"2022-12-07T18:56:56-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/feliz-dia-del-locutor-nacional\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-07-at-10.27.47-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-07-at-10.27.47-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"artes\" title=\"artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/feliz-dia-del-locutor-nacional\/\" title=\"\u00a1Feliz D\u00eda del Locutor Nacional!\" rel=\"bookmark\">\u00a1Feliz D\u00eda del Locutor Nacional!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/12\/07\/feliz-dia-del-locutor-nacional\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Feliz D\u00eda del Locutor Nacional!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4690\" data-date=\"2022-11-29T22:24:08-06:00\" data-name=\"\u00a1Inauguraci\u00f3n del Puente La Naisa!\"><article class=\"post project-odd visible post-4690 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"\u00a1Inauguraci\u00f3n del Puente La Naisa!\" data-date=\"2022-11-29T22:24:08-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/29\/inauguracion-del-puente-la-naisa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/317395961_512512940919955_7016625249682230863_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/317395961_512512940919955_7016625249682230863_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/317395961_512512940919955_7016625249682230863_n-1280x799.jpg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"La Naisa\" title=\"Inauguraci\u00f3n La Naisa\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/29\/inauguracion-del-puente-la-naisa\/\" title=\"\u00a1Inauguraci\u00f3n del Puente La Naisa!\" rel=\"bookmark\">\u00a1Inauguraci\u00f3n del Puente La Naisa!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/29\/inauguracion-del-puente-la-naisa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Inauguraci\u00f3n del Puente La Naisa!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4679\" data-date=\"2022-11-17T20:17:48-06:00\" data-name=\"Los trabajos avanzan en el Aer\u00f3dromo de San Jos\u00e9, Escuintla.\"><article class=\"post project-odd visible post-4679 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Los trabajos avanzan en el Aer\u00f3dromo de San Jos\u00e9, Escuintla.\" data-date=\"2022-11-17T20:17:48-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/17\/los-trabajos-avanzan-en-el-aerodromo-de-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-16-at-09.44.14-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-16-at-09.44.14-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Aer\u00f3dromo, Escuintla\" title=\"Aerodromo, Escuintla\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/17\/los-trabajos-avanzan-en-el-aerodromo-de-san-jose-escuintla\/\" title=\"Los trabajos avanzan en el Aer\u00f3dromo de San Jos\u00e9, Escuintla.\" rel=\"bookmark\">Los trabajos avanzan en el Aer\u00f3dromo de San Jos\u00e9, Escuintla.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/17\/los-trabajos-avanzan-en-el-aerodromo-de-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Los trabajos avanzan en el Aer\u00f3dromo de San Jos\u00e9, Escuintla.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4675\" data-date=\"2022-11-15T18:08:56-06:00\" data-name=\"Feliz D\u00eda del Adulto Mayor\"><article class=\"post project-odd visible post-4675 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Feliz D\u00eda del Adulto Mayor\" data-date=\"2022-11-15T18:08:56-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/15\/feliz-dia-del-adulto-mayor\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-15-at-11.03.19-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-15-at-11.03.19-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Adulto Mayor\" title=\"artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/15\/feliz-dia-del-adulto-mayor\/\" title=\"Feliz D\u00eda del Adulto Mayor\" rel=\"bookmark\">Feliz D\u00eda del Adulto Mayor<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/11\/15\/feliz-dia-del-adulto-mayor\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Feliz D\u00eda del Adulto Mayor\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4613\" data-date=\"2022-10-24T16:47:00-06:00\" data-name=\"Avanzan los trabajos del nuevo puente La Naisa\"><article class=\"post project-odd visible post-4613 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Avanzan los trabajos del nuevo puente La Naisa\" data-date=\"2022-10-24T16:47:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/24\/avanzan-los-trabajos-del-nuevo-puente-la-naisa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-24-at-11.48.28-4-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-24-at-11.48.28-4-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-24-at-11.48.28-4-1280x799.jpeg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"La Naisa\" title=\"La Naisa\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/24\/avanzan-los-trabajos-del-nuevo-puente-la-naisa\/\" title=\"Avanzan los trabajos del nuevo puente La Naisa\" rel=\"bookmark\">Avanzan los trabajos del nuevo puente La Naisa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/24\/avanzan-los-trabajos-del-nuevo-puente-la-naisa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Avanzan los trabajos del nuevo puente La Naisa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4609\" data-date=\"2022-10-11T10:01:00-06:00\" data-name=\"Toma en cuenta estos consejos para estar siempre preparado\"><article class=\"post project-odd visible post-4609 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Toma en cuenta estos consejos para estar siempre preparado\" data-date=\"2022-10-11T10:01:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/11\/toma-en-cuenta-estos-consejos-para-estar-siempre-preparado\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-10-at-16.53.20-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-10-at-16.53.20-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-10-at-16.53.20-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"artes\" title=\"artes\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/11\/toma-en-cuenta-estos-consejos-para-estar-siempre-preparado\/\" title=\"Toma en cuenta estos consejos para estar siempre preparado\" rel=\"bookmark\">Toma en cuenta estos consejos para estar siempre preparado<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/11\/toma-en-cuenta-estos-consejos-para-estar-siempre-preparado\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/11\/toma-en-cuenta-estos-consejos-para-estar-siempre-preparado\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Toma en cuenta estos consejos para estar siempre preparado\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4519\" data-date=\"2022-10-10T22:21:55-06:00\" data-name=\"La Mochila de las 72 horas\"><article class=\"post project-odd visible post-4519 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"La Mochila de las 72 horas\" data-date=\"2022-10-10T22:21:55-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/10\/la-mochila-de-las-72-horas\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-10-at-11.15.08-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-10-at-11.15.08-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/10\/la-mochila-de-las-72-horas\/\" title=\"La Mochila de las 72 horas\" rel=\"bookmark\">La Mochila de las 72 horas<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/10\/la-mochila-de-las-72-horas\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about La Mochila de las 72 horas\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4364\" data-date=\"2022-10-03T22:43:07-06:00\" data-name=\"El Fondo Social de Solidaridad celebra los 201 a\u00f1os de independencia de Guatemala\"><article class=\"post project-odd visible post-4364 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"El Fondo Social de Solidaridad celebra los 201 a\u00f1os de independencia de Guatemala\" data-date=\"2022-10-03T22:43:07-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/el-fondo-social-de-solidaridad-celebra-los-201-anos-de-independencia-de-guatemala\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/306856078_454968373341079_1782396074706728421_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/306856078_454968373341079_1782396074706728421_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"D\u00eda de la Independencia 2022\" title=\"D\u00eda de la Independencia 2022\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/el-fondo-social-de-solidaridad-celebra-los-201-anos-de-independencia-de-guatemala\/\" title=\"El Fondo Social de Solidaridad celebra los 201 a\u00f1os de independencia de Guatemala\" rel=\"bookmark\">El Fondo Social de Solidaridad celebra los 201 a\u00f1os de independencia de Guatemala<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/el-fondo-social-de-solidaridad-celebra-los-201-anos-de-independencia-de-guatemala\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El Fondo Social de Solidaridad celebra los 201 a\u00f1os de independencia de Guatemala\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4303\" data-date=\"2022-10-03T17:14:07-06:00\" data-name=\"Aplicaci\u00f3n de primera capa  de carpeta asf\u00e1ltica en San Francisco, Pet\u00e9n.\"><article class=\"post project-odd visible post-4303 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"Aplicaci\u00f3n de primera capa  de carpeta asf\u00e1ltica en San Francisco, Pet\u00e9n.\" data-date=\"2022-10-03T17:14:07-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/aplicacion-de-primera-capa-de-carpeta-asfaltica-en-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-23-at-14.06.26-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-23-at-14.06.26-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-23-at-14.06.26-1000x624.jpeg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-09-23-at-14.06.26\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/aplicacion-de-primera-capa-de-carpeta-asfaltica-en-san-francisco-peten\/\" title=\"Aplicaci\u00f3n de primera capa  de carpeta asf\u00e1ltica en San Francisco, Pet\u00e9n.\" rel=\"bookmark\">Aplicaci\u00f3n de primera capa  de carpeta asf\u00e1ltica en San Francisco, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/aplicacion-de-primera-capa-de-carpeta-asfaltica-en-san-francisco-peten\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/10\/03\/aplicacion-de-primera-capa-de-carpeta-asfaltica-en-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Aplicaci\u00f3n de primera capa  de carpeta asf\u00e1ltica en San Francisco, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4293\" data-date=\"2022-09-28T16:01:00-06:00\" data-name=\"D\u00eda Internacional del Derecho de Acceso Universal a la Informaci\u00f3n.\"><article class=\"post project-odd visible post-4293 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"D\u00eda Internacional del Derecho de Acceso Universal a la Informaci\u00f3n.\" data-date=\"2022-09-28T16:01:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/28\/dia-internacional-del-derecho-de-acceso-universal-a-la-informacion\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-28-at-14.08.00-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-28-at-14.08.00-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/28\/dia-internacional-del-derecho-de-acceso-universal-a-la-informacion\/\" title=\"D\u00eda Internacional del Derecho de Acceso Universal a la Informaci\u00f3n.\" rel=\"bookmark\">D\u00eda Internacional del Derecho de Acceso Universal a la Informaci\u00f3n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/28\/dia-internacional-del-derecho-de-acceso-universal-a-la-informacion\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/28\/dia-internacional-del-derecho-de-acceso-universal-a-la-informacion\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about D\u00eda Internacional del Derecho de Acceso Universal a la Informaci\u00f3n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4321\" data-date=\"2022-09-24T20:22:00-06:00\" data-name=\"Continuamos con los trabajos en San Francisco, Pet\u00e9n.\"><article class=\"post project-odd visible post-4321 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Continuamos con los trabajos en San Francisco, Pet\u00e9n.\" data-date=\"2022-09-24T20:22:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/24\/continuamos-con-los-trabajos-en-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/FddGQyWWABQ1EYD-820x512.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/FddGQyWWABQ1EYD-820x512.jpg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/24\/continuamos-con-los-trabajos-en-san-francisco-peten\/\" title=\"Continuamos con los trabajos en San Francisco, Pet\u00e9n.\" rel=\"bookmark\">Continuamos con los trabajos en San Francisco, Pet\u00e9n.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/24\/continuamos-con-los-trabajos-en-san-francisco-peten\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/24\/continuamos-con-los-trabajos-en-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continuamos con los trabajos en San Francisco, Pet\u00e9n.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4338\" data-date=\"2022-09-22T21:36:00-06:00\" data-name=\"Medidas de prevenci\u00f3n para evitar accidentes en \u00e9poca de invierno.\"><article class=\"post project-odd visible post-4338 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-noticias category-20 description-off\" data-name=\"Medidas de prevenci\u00f3n para evitar accidentes en \u00e9poca de invierno.\" data-date=\"2022-09-22T21:36:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/22\/medidas-de-prevencion-para-evitar-accidentes-en-epoca-de-invierno\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/306948924_460495842788332_315995118996318102_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/306948924_460495842788332_315995118996318102_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/306948924_460495842788332_315995118996318102_n-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Artes\" title=\"Artes\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/22\/medidas-de-prevencion-para-evitar-accidentes-en-epoca-de-invierno\/\" title=\"Medidas de prevenci\u00f3n para evitar accidentes en \u00e9poca de invierno.\" rel=\"bookmark\">Medidas de prevenci\u00f3n para evitar accidentes en \u00e9poca de invierno.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/22\/medidas-de-prevencion-para-evitar-accidentes-en-epoca-de-invierno\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/22\/medidas-de-prevencion-para-evitar-accidentes-en-epoca-de-invierno\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Medidas de prevenci\u00f3n para evitar accidentes en \u00e9poca de invierno.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4344\" data-date=\"2022-09-21T21:00:00-06:00\" data-name=\"D\u00eda Internacional de la Paz.\"><article class=\"post project-odd visible post-4344 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"D\u00eda Internacional de la Paz.\" data-date=\"2022-09-21T21:00:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/21\/dia-internacional-de-la-paz\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-21-at-12.22.00-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-21-at-12.22.00-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"WhatsApp Image 2022-09-21 at 12.22.00\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/21\/dia-internacional-de-la-paz\/\" title=\"D\u00eda Internacional de la Paz.\" rel=\"bookmark\">D\u00eda Internacional de la Paz.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/21\/dia-internacional-de-la-paz\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about D\u00eda Internacional de la Paz.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4359\" data-date=\"2022-09-15T22:11:00-06:00\" data-name=\"\u00a1Guatemala tu nombre inmortal! Feliz d\u00eda de la independencia.\"><article class=\"post project-odd visible post-4359 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Guatemala tu nombre inmortal! Feliz d\u00eda de la independencia.\" data-date=\"2022-09-15T22:11:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/15\/guatemala-tu-nombre-inmortal-feliz-dia-de-la-independencia\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-14-at-16.30.51-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-14-at-16.30.51-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-14-at-16.30.51-1000x624.jpeg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"ARTES\" title=\"WhatsApp-Image-2022-09-14-at-16.30.51\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/15\/guatemala-tu-nombre-inmortal-feliz-dia-de-la-independencia\/\" title=\"\u00a1Guatemala tu nombre inmortal! Feliz d\u00eda de la independencia.\" rel=\"bookmark\">\u00a1Guatemala tu nombre inmortal! Feliz d\u00eda de la independencia.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/15\/guatemala-tu-nombre-inmortal-feliz-dia-de-la-independencia\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Guatemala tu nombre inmortal! Feliz d\u00eda de la independencia.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4375\" data-date=\"2022-09-13T22:45:00-06:00\" data-name=\"Descanse en paz.\"><article class=\"post project-odd visible post-4375 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"Descanse en paz.\" data-date=\"2022-09-13T22:45:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-14.12.53-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-14.12.53-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-14.12.53-1024x639.jpeg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Esquelas\" title=\"Esquelas\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz\/\" title=\"Descanse en paz.\" rel=\"bookmark\">Descanse en paz.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Descanse en paz.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4379\" data-date=\"2022-09-13T21:10:00-06:00\" data-name=\"Descanse en paz.\"><article class=\"post project-odd visible post-4379 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"Descanse en paz.\" data-date=\"2022-09-13T21:10:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-13.09.22-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-13.09.22-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-09-13-at-13.09.22-1024x639.jpeg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Esquelas\" title=\"Esquelas\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz-2\/\" title=\"Descanse en paz.\" rel=\"bookmark\">Descanse en paz.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz-2\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/13\/descanse-en-paz-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Descanse en paz.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4384\" data-date=\"2022-09-12T21:00:00-06:00\" data-name=\"S\u00edmbolo de la libertad, EL Quetzal\"><article class=\"post project-odd visible post-4384 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"S\u00edmbolo de la libertad, EL Quetzal\" data-date=\"2022-09-12T21:00:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/12\/4384\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-12-at-15.15.13-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-12-at-15.15.13-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/12\/4384\/\" title=\"S\u00edmbolo de la libertad, EL Quetzal\" rel=\"bookmark\">S\u00edmbolo de la libertad, EL Quetzal<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/12\/4384\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about S\u00edmbolo de la libertad, EL Quetzal\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4398\" data-date=\"2022-09-06T21:29:00-06:00\" data-name=\"Descanse en paz.\"><article class=\"post project-odd visible post-4398 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"Descanse en paz.\" data-date=\"2022-09-06T21:29:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/descanse-en-paz-3\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20792%20494&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/obituario-792x494.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/obituario-792x494.jpg 792w\" loading=\"eager\" style=\"--ratio: 792 \/ 494\" sizes=\"(max-width: 792px) 100vw, 792px\" alt=\"Esquelas\" title=\"Esquelas\" width=\"792\" height=\"494\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/descanse-en-paz-3\/\" title=\"Descanse en paz.\" rel=\"bookmark\">Descanse en paz.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/descanse-en-paz-3\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Descanse en paz.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4403\" data-date=\"2022-09-06T10:50:00-06:00\" data-name=\"\u00a1S\u00edguenos en nuestras redes sociales!\"><article class=\"post project-odd visible post-4403 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1S\u00edguenos en nuestras redes sociales!\" data-date=\"2022-09-06T10:50:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/siguenos-en-nuestras-redes-sociales\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/IMG-20220906-WA0022-820x512.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/IMG-20220906-WA0022-820x512.jpg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/siguenos-en-nuestras-redes-sociales\/\" title=\"\u00a1S\u00edguenos en nuestras redes sociales!\" rel=\"bookmark\">\u00a1S\u00edguenos en nuestras redes sociales!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/06\/siguenos-en-nuestras-redes-sociales\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1S\u00edguenos en nuestras redes sociales!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4415\" data-date=\"2022-09-05T22:06:00-06:00\" data-name=\"Por iniciar trabajos en puente La Barrita, en San Jos\u00e9, Escuintla.\"><article class=\"post project-odd visible post-4415 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Por iniciar trabajos en puente La Barrita, en San Jos\u00e9, Escuintla.\" data-date=\"2022-09-05T22:06:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/05\/por-iniciar-trabajos-en-puente-la-barrita-en-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-31-at-12.29.55-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-31-at-12.29.55-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-31-at-12.29.55-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Artes\" title=\"Artes\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/05\/por-iniciar-trabajos-en-puente-la-barrita-en-san-jose-escuintla\/\" title=\"Por iniciar trabajos en puente La Barrita, en San Jos\u00e9, Escuintla.\" rel=\"bookmark\">Por iniciar trabajos en puente La Barrita, en San Jos\u00e9, Escuintla.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/05\/por-iniciar-trabajos-en-puente-la-barrita-en-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Por iniciar trabajos en puente La Barrita, en San Jos\u00e9, Escuintla.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4421\" data-date=\"2022-09-01T22:11:00-06:00\" data-name=\"\u00a1Iniciamos los trabajos en zona 11 de la ciudad!\"><article class=\"post project-odd visible post-4421 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"\u00a1Iniciamos los trabajos en zona 11 de la ciudad!\" data-date=\"2022-09-01T22:11:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/iniciamos-los-trabajos-en-zona-11-de-la-ciudad\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/304955344_446292617541988_6064113384639407713_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/304955344_446292617541988_6064113384639407713_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"Inauguraci\u00f3n proyecto zona 11 7\" title=\"Inauguraci\u00f3n proyecto zona 11 7\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/iniciamos-los-trabajos-en-zona-11-de-la-ciudad\/\" title=\"\u00a1Iniciamos los trabajos en zona 11 de la ciudad!\" rel=\"bookmark\">\u00a1Iniciamos los trabajos en zona 11 de la ciudad!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/iniciamos-los-trabajos-en-zona-11-de-la-ciudad\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Iniciamos los trabajos en zona 11 de la ciudad!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4429\" data-date=\"2022-09-01T17:42:00-06:00\" data-name=\"\u00a1Inicio de construcci\u00f3n del paso a desnivel sobre la Avenida Petapa y 53 calle zona 12 de Guatemala! \ud83d\ude9c\ud83d\udea7\"><article class=\"post project-odd visible post-4429 type-post status-publish format-standard has-post-thumbnail hentry category-noticias category-20 description-off\" data-name=\"\u00a1Inicio de construcci\u00f3n del paso a desnivel sobre la Avenida Petapa y 53 calle zona 12 de Guatemala! \ud83d\ude9c\ud83d\udea7\" data-date=\"2022-09-01T17:42:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/inicio-de-construccion-del-paso-a-desnivel-sobre-la-avenida-petapa-y-53-calle-zona-12-de-guatemala-%f0%9f%9a%9c%f0%9f%9a%a7\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/305108833_446292784208638_2010732065524612528_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/305108833_446292784208638_2010732065524612528_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"Inicio trabajo Petapa\" title=\"Inicio trabajo Petapa\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/inicio-de-construccion-del-paso-a-desnivel-sobre-la-avenida-petapa-y-53-calle-zona-12-de-guatemala-%f0%9f%9a%9c%f0%9f%9a%a7\/\" title=\"\u00a1Inicio de construcci\u00f3n del paso a desnivel sobre la Avenida Petapa y 53 calle zona 12 de Guatemala! \ud83d\ude9c\ud83d\udea7\" rel=\"bookmark\">\u00a1Inicio de construcci\u00f3n del paso a desnivel sobre la Avenida Petapa y 53 calle zona 12 de Guatemala! \ud83d\ude9c\ud83d\udea7<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/09\/01\/inicio-de-construccion-del-paso-a-desnivel-sobre-la-avenida-petapa-y-53-calle-zona-12-de-guatemala-%f0%9f%9a%9c%f0%9f%9a%a7\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Inicio de construcci\u00f3n del paso a desnivel sobre la Avenida Petapa y 53 calle zona 12 de Guatemala! \ud83d\ude9c\ud83d\udea7\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4447\" data-date=\"2022-08-31T21:14:00-06:00\" data-name=\"Hoy se conmemora el D\u00eda Internacional de la Solidaridad Humana.\"><article class=\"post project-odd visible post-4447 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Hoy se conmemora el D\u00eda Internacional de la Solidaridad Humana.\" data-date=\"2022-08-31T21:14:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/31\/hoy-se-conmemora-el-dia-internacional-de-la-solidaridad-humana\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-31-at-11.03.04-AM-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-31-at-11.03.04-AM-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"Artes\" title=\"Artes\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/31\/hoy-se-conmemora-el-dia-internacional-de-la-solidaridad-humana\/\" title=\"Hoy se conmemora el D\u00eda Internacional de la Solidaridad Humana.\" rel=\"bookmark\">Hoy se conmemora el D\u00eda Internacional de la Solidaridad Humana.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/31\/hoy-se-conmemora-el-dia-internacional-de-la-solidaridad-humana\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Hoy se conmemora el D\u00eda Internacional de la Solidaridad Humana.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4436\" data-date=\"2022-08-30T20:57:00-06:00\" data-name=\"Continuamos con los trabajos de reposici\u00f3n del puente vehicular La Naisa\"><article class=\"post project-odd visible post-4436 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-escuintla category-20 description-off\" data-name=\"Continuamos con los trabajos de reposici\u00f3n del puente vehicular La Naisa\" data-date=\"2022-08-30T20:57:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/30\/continuamos-con-los-trabajos-de-reposicion-del-puente-vehicular-la-naisa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/IMG_2876-990x618.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/IMG_2876-990x618.png 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/IMG_2876-1485x927.png 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"Puente La Naisa\" title=\"Puente La Naisa\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/30\/continuamos-con-los-trabajos-de-reposicion-del-puente-vehicular-la-naisa\/\" title=\"Continuamos con los trabajos de reposici\u00f3n del puente vehicular La Naisa\" rel=\"bookmark\">Continuamos con los trabajos de reposici\u00f3n del puente vehicular La Naisa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/30\/continuamos-con-los-trabajos-de-reposicion-del-puente-vehicular-la-naisa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continuamos con los trabajos de reposici\u00f3n del puente vehicular La Naisa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4451\" data-date=\"2022-08-17T22:00:00-06:00\" data-name=\"Hoy conmemoramos el D\u00eda Nacional de la Bandera.\"><article class=\"post project-odd visible post-4451 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Hoy conmemoramos el D\u00eda Nacional de la Bandera.\" data-date=\"2022-08-17T22:00:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/17\/hoy-conmemoramos-el-dia-nacional-de-la-bandera\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/300156575_436120511892532_3148204197618075271_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/300156575_436120511892532_3148204197618075271_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/300156575_436120511892532_3148204197618075271_n-1000x624.jpg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"300156575_436120511892532_3148204197618075271_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/17\/hoy-conmemoramos-el-dia-nacional-de-la-bandera\/\" title=\"Hoy conmemoramos el D\u00eda Nacional de la Bandera.\" rel=\"bookmark\">Hoy conmemoramos el D\u00eda Nacional de la Bandera.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/17\/hoy-conmemoramos-el-dia-nacional-de-la-bandera\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Hoy conmemoramos el D\u00eda Nacional de la Bandera.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4454\" data-date=\"2022-08-16T16:53:00-06:00\" data-name=\"Lamentamos el sensible fallecimiento de nuestro compa\u00f1ero de labores, Boanerges Vel\u00e1squez , rogamos a Dios les de paz y resignaci\u00f3n a su apreciable familia y amigos.\"><article class=\"post project-odd visible post-4454 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Lamentamos el sensible fallecimiento de nuestro compa\u00f1ero de labores, Boanerges Vel\u00e1squez , rogamos a Dios les de paz y resignaci\u00f3n a su apreciable familia y amigos.\" data-date=\"2022-08-16T16:53:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/16\/lamentamos-el-sensible-fallecimiento-de-nuestro-companero-de-labores-boanerges-velasquez-rogamos-a-dios-les-de-paz-y-resignacion-a-su-apreciable-familia-y-amigos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/299880407_435340801970503_4076348527363570163_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/299880407_435340801970503_4076348527363570163_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/299880407_435340801970503_4076348527363570163_n-1024x639.jpg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"299880407_435340801970503_4076348527363570163_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/16\/lamentamos-el-sensible-fallecimiento-de-nuestro-companero-de-labores-boanerges-velasquez-rogamos-a-dios-les-de-paz-y-resignacion-a-su-apreciable-familia-y-amigos\/\" title=\"Lamentamos el sensible fallecimiento de nuestro compa\u00f1ero de labores, Boanerges Vel\u00e1squez , rogamos a Dios les de paz y resignaci\u00f3n a su apreciable familia y amigos.\" rel=\"bookmark\">Lamentamos el sensible fallecimiento de nuestro compa\u00f1ero de labores, Boanerges Vel\u00e1squez , rogamos a Dios les de paz y resignaci\u00f3n a su apreciable familia y amigos.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/16\/lamentamos-el-sensible-fallecimiento-de-nuestro-companero-de-labores-boanerges-velasquez-rogamos-a-dios-les-de-paz-y-resignacion-a-su-apreciable-familia-y-amigos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Lamentamos el sensible fallecimiento de nuestro compa\u00f1ero de labores, Boanerges Vel\u00e1squez , rogamos a Dios les de paz y resignaci\u00f3n a su apreciable familia y amigos.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4458\" data-date=\"2022-08-09T20:56:00-06:00\" data-name=\"Hoy se conmemora el D\u00eda Nacional e Internacional de Pueblos Ind\u00edgenas.\"><article class=\"post project-odd visible post-4458 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Hoy se conmemora el D\u00eda Nacional e Internacional de Pueblos Ind\u00edgenas.\" data-date=\"2022-08-09T20:56:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/09\/hoy-se-conmemora-el-dia-nacional-e-internacional-de-pueblos-indigenas\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/298761601_430671002437483_4789097278838869912_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/298761601_430671002437483_4789097278838869912_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/298761601_430671002437483_4789097278838869912_n-1000x624.jpg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"298761601_430671002437483_4789097278838869912_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/09\/hoy-se-conmemora-el-dia-nacional-e-internacional-de-pueblos-indigenas\/\" title=\"Hoy se conmemora el D\u00eda Nacional e Internacional de Pueblos Ind\u00edgenas.\" rel=\"bookmark\">Hoy se conmemora el D\u00eda Nacional e Internacional de Pueblos Ind\u00edgenas.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/09\/hoy-se-conmemora-el-dia-nacional-e-internacional-de-pueblos-indigenas\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/09\/hoy-se-conmemora-el-dia-nacional-e-internacional-de-pueblos-indigenas\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Hoy se conmemora el D\u00eda Nacional e Internacional de Pueblos Ind\u00edgenas.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4462\" data-date=\"2022-08-05T21:16:00-06:00\" data-name=\"\u00a1S\u00edguenos en nuestras redes sociales para enterarte de nuestras noticias!\"><article class=\"post project-odd visible post-4462 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1S\u00edguenos en nuestras redes sociales para enterarte de nuestras noticias!\" data-date=\"2022-08-05T21:16:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/05\/siguenos-en-nuestras-redes-sociales-para-enterarte-de-nuestras-noticias\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-05-at-4.21.06-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-05-at-4.21.06-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-05-at-4.21.06-PM-1000x624.jpeg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-08-05-at-4.21.06-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/05\/siguenos-en-nuestras-redes-sociales-para-enterarte-de-nuestras-noticias\/\" title=\"\u00a1S\u00edguenos en nuestras redes sociales para enterarte de nuestras noticias!\" rel=\"bookmark\">\u00a1S\u00edguenos en nuestras redes sociales para enterarte de nuestras noticias!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/05\/siguenos-en-nuestras-redes-sociales-para-enterarte-de-nuestras-noticias\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1S\u00edguenos en nuestras redes sociales para enterarte de nuestras noticias!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4465\" data-date=\"2022-08-04T09:36:00-06:00\" data-name=\"\u00a1Obras que generan desarrollo!\"><article class=\"post project-odd visible post-4465 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Obras que generan desarrollo!\" data-date=\"2022-08-04T09:36:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/04\/obras-que-generan-desarrollo\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-03-at-1.14.59-PM-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-03-at-1.14.59-PM-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"\" title=\"WhatsApp Image 2022-08-03 at 1.14.59 PM\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/04\/obras-que-generan-desarrollo\/\" title=\"\u00a1Obras que generan desarrollo!\" rel=\"bookmark\">\u00a1Obras que generan desarrollo!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/04\/obras-que-generan-desarrollo\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Obras que generan desarrollo!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4469\" data-date=\"2022-08-03T21:39:00-06:00\" data-name=\"Medidas de prevenci\u00f3n para evitar el contagio de la Viruela del Mono.\"><article class=\"post project-odd visible post-4469 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Medidas de prevenci\u00f3n para evitar el contagio de la Viruela del Mono.\" data-date=\"2022-08-03T21:39:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/03\/medidas-de-prevencion-para-evitar-el-contagio-de-la-viruela-del-mono\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-03-at-1.16.39-PM-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-08-03-at-1.16.39-PM-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"\" title=\"WhatsApp Image 2022-08-03 at 1.16.39 PM\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/03\/medidas-de-prevencion-para-evitar-el-contagio-de-la-viruela-del-mono\/\" title=\"Medidas de prevenci\u00f3n para evitar el contagio de la Viruela del Mono.\" rel=\"bookmark\">Medidas de prevenci\u00f3n para evitar el contagio de la Viruela del Mono.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/03\/medidas-de-prevencion-para-evitar-el-contagio-de-la-viruela-del-mono\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Medidas de prevenci\u00f3n para evitar el contagio de la Viruela del Mono.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4473\" data-date=\"2022-08-01T09:11:00-06:00\" data-name=\"Estamos trabajando en el muro perimetral del Aer\u00f3dromo San Jos\u00e9, Escuintla.\"><article class=\"post project-odd visible post-4473 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Estamos trabajando en el muro perimetral del Aer\u00f3dromo San Jos\u00e9, Escuintla.\" data-date=\"2022-08-01T09:11:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/01\/estamos-trabajando-en-el-muro-perimetral-del-aerodromo-san-jose-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-29-at-2.44.03-PM-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-29-at-2.44.03-PM-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"\" title=\"WhatsApp Image 2022-07-29 at 2.44.03 PM\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/01\/estamos-trabajando-en-el-muro-perimetral-del-aerodromo-san-jose-escuintla\/\" title=\"Estamos trabajando en el muro perimetral del Aer\u00f3dromo San Jos\u00e9, Escuintla.\" rel=\"bookmark\">Estamos trabajando en el muro perimetral del Aer\u00f3dromo San Jos\u00e9, Escuintla.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/08\/01\/estamos-trabajando-en-el-muro-perimetral-del-aerodromo-san-jose-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Estamos trabajando en el muro perimetral del Aer\u00f3dromo San Jos\u00e9, Escuintla.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4477\" data-date=\"2022-07-27T11:46:00-06:00\" data-name=\"Mejoramiento de la carretera que conduce del puente La Barranquilla hacia Plan Buena Vista en Sanarate, El Progreso.\"><article class=\"post project-odd visible post-4477 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Mejoramiento de la carretera que conduce del puente La Barranquilla hacia Plan Buena Vista en Sanarate, El Progreso.\" data-date=\"2022-07-27T11:46:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/27\/mejoramiento-de-la-carretera-que-conduce-del-puente-la-barranquilla-hacia-plan-buena-vista-en-sanarate-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-27-at-4.38.37-PM-1-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-27-at-4.38.37-PM-1-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"\" title=\"WhatsApp Image 2022-07-27 at 4.38.37 PM (1)\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/27\/mejoramiento-de-la-carretera-que-conduce-del-puente-la-barranquilla-hacia-plan-buena-vista-en-sanarate-el-progreso\/\" title=\"Mejoramiento de la carretera que conduce del puente La Barranquilla hacia Plan Buena Vista en Sanarate, El Progreso.\" rel=\"bookmark\">Mejoramiento de la carretera que conduce del puente La Barranquilla hacia Plan Buena Vista en Sanarate, El Progreso.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/27\/mejoramiento-de-la-carretera-que-conduce-del-puente-la-barranquilla-hacia-plan-buena-vista-en-sanarate-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mejoramiento de la carretera que conduce del puente La Barranquilla hacia Plan Buena Vista en Sanarate, El Progreso.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4481\" data-date=\"2022-07-25T21:51:00-06:00\" data-name=\"D\u00eda Internacional de la Mujer Afrodescendiente\"><article class=\"post project-odd visible post-4481 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"D\u00eda Internacional de la Mujer Afrodescendiente\" data-date=\"2022-07-25T21:51:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/25\/dia-internacional-de-la-mujer-afrodescendiente\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20820%20512&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-25-at-10.39.05-AM-820x512.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-25-at-10.39.05-AM-820x512.jpeg 820w\" loading=\"eager\" style=\"--ratio: 820 \/ 512\" sizes=\"(max-width: 820px) 100vw, 820px\" alt=\"\" title=\"WhatsApp Image 2022-07-25 at 10.39.05 AM\" width=\"820\" height=\"512\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/25\/dia-internacional-de-la-mujer-afrodescendiente\/\" title=\"D\u00eda Internacional de la Mujer Afrodescendiente\" rel=\"bookmark\">D\u00eda Internacional de la Mujer Afrodescendiente<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/25\/dia-internacional-de-la-mujer-afrodescendiente\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about D\u00eda Internacional de la Mujer Afrodescendiente\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4485\" data-date=\"2022-07-20T09:54:00-06:00\" data-name=\"Fundici\u00f3n de vigas longitudinales del puente La Naisa, Santa Lucia Cotzumalguapa, Escuintla\"><article class=\"post project-odd visible post-4485 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Fundici\u00f3n de vigas longitudinales del puente La Naisa, Santa Lucia Cotzumalguapa, Escuintla\" data-date=\"2022-07-20T09:54:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/20\/fundicion-de-vigas-longitudinales-del-puente-la-naisa-santa-lucia-cotzumalguapa-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-19-at-4.30.37-PM-1-720x450.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-19-at-4.30.37-PM-1-720x450.jpeg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"WhatsApp Image 2022-07-19 at 4.30.37 PM (1)\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/20\/fundicion-de-vigas-longitudinales-del-puente-la-naisa-santa-lucia-cotzumalguapa-escuintla\/\" title=\"Fundici\u00f3n de vigas longitudinales del puente La Naisa, Santa Lucia Cotzumalguapa, Escuintla\" rel=\"bookmark\">Fundici\u00f3n de vigas longitudinales del puente La Naisa, Santa Lucia Cotzumalguapa, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/20\/fundicion-de-vigas-longitudinales-del-puente-la-naisa-santa-lucia-cotzumalguapa-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Fundici\u00f3n de vigas longitudinales del puente La Naisa, Santa Lucia Cotzumalguapa, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4489\" data-date=\"2022-07-17T10:02:00-06:00\" data-name=\"\u00a1Feliz D\u00eda Nacional del Polic\u00eda Civil!\"><article class=\"post project-odd visible post-4489 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Feliz D\u00eda Nacional del Polic\u00eda Civil!\" data-date=\"2022-07-17T10:02:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/17\/feliz-dia-nacional-del-policia-civil\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/294651316_415488130622437_7480085665428243872_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/294651316_415488130622437_7480085665428243872_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/294651316_415488130622437_7480085665428243872_n-1024x639.jpg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"294651316_415488130622437_7480085665428243872_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/17\/feliz-dia-nacional-del-policia-civil\/\" title=\"\u00a1Feliz D\u00eda Nacional del Polic\u00eda Civil!\" rel=\"bookmark\">\u00a1Feliz D\u00eda Nacional del Polic\u00eda Civil!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/17\/feliz-dia-nacional-del-policia-civil\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Feliz D\u00eda Nacional del Polic\u00eda Civil!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4492\" data-date=\"2022-07-12T10:58:00-06:00\" data-name=\"Completa tu esquema de vacunaci\u00f3n Covid-19 \u00a1Prot\u00e9gete y cuida a los tuyos!\"><article class=\"post project-odd visible post-4492 type-post status-publish format-standard has-post-thumbnail hentry category-news tag-artes category-4 description-off\" data-name=\"Completa tu esquema de vacunaci\u00f3n Covid-19 \u00a1Prot\u00e9gete y cuida a los tuyos!\" data-date=\"2022-07-12T10:58:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/12\/completa-tu-esquema-de-vacunacion-covid-19-protegete-y-cuida-a-los-tuyos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-07-at-3.24.09-PM-720x450.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-07-at-3.24.09-PM-720x450.jpeg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"Covid-19\" title=\"Covid-19\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/12\/completa-tu-esquema-de-vacunacion-covid-19-protegete-y-cuida-a-los-tuyos\/\" title=\"Completa tu esquema de vacunaci\u00f3n Covid-19 \u00a1Prot\u00e9gete y cuida a los tuyos!\" rel=\"bookmark\">Completa tu esquema de vacunaci\u00f3n Covid-19 \u00a1Prot\u00e9gete y cuida a los tuyos!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/news\/\" >News<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/12\/completa-tu-esquema-de-vacunacion-covid-19-protegete-y-cuida-a-los-tuyos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Completa tu esquema de vacunaci\u00f3n Covid-19 \u00a1Prot\u00e9gete y cuida a los tuyos!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4496\" data-date=\"2022-07-11T09:02:00-06:00\" data-name=\"Continuamos los trabajos en el puente La Naisa en Santa Luc\u00eda Cotzumalguapa, Escuintla\"><article class=\"post project-odd visible post-4496 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Continuamos los trabajos en el puente La Naisa en Santa Luc\u00eda Cotzumalguapa, Escuintla\" data-date=\"2022-07-11T09:02:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/11\/continuamos-los-trabajos-en-el-puente-la-naisa-en-santa-lucia-cotzumalguapa-escuintla\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-11-at-10.38.39-AM-1-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-11-at-10.38.39-AM-1-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-11-at-10.38.39-AM-1-1024x639.jpeg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-07-11-at-10.38.39-AM-1\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/11\/continuamos-los-trabajos-en-el-puente-la-naisa-en-santa-lucia-cotzumalguapa-escuintla\/\" title=\"Continuamos los trabajos en el puente La Naisa en Santa Luc\u00eda Cotzumalguapa, Escuintla\" rel=\"bookmark\">Continuamos los trabajos en el puente La Naisa en Santa Luc\u00eda Cotzumalguapa, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/11\/continuamos-los-trabajos-en-el-puente-la-naisa-en-santa-lucia-cotzumalguapa-escuintla\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continuamos los trabajos en el puente La Naisa en Santa Luc\u00eda Cotzumalguapa, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4499\" data-date=\"2022-07-07T09:32:00-06:00\" data-name=\"L\u00e1vate las manos con agua y jab\u00f3n por 20 segundos, esto evitar\u00e1 que te infectes de Covid-19 y otras enfermedades.\u00a0\"><article class=\"post project-odd visible post-4499 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-covid-19 category-20 description-off\" data-name=\"L\u00e1vate las manos con agua y jab\u00f3n por 20 segundos, esto evitar\u00e1 que te infectes de Covid-19 y otras enfermedades.\u00a0\" data-date=\"2022-07-07T09:32:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/07\/lavate-las-manos-con-agua-y-jabon-por-20-segundos-esto-evitara-que-te-infectes-de-covid-19-y-otras-enfermedades\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-06-at-12.30.42-PM-720x450.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-06-at-12.30.42-PM-720x450.jpeg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"WhatsApp Image 2022-07-06 at 12.30.42 PM\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/07\/lavate-las-manos-con-agua-y-jabon-por-20-segundos-esto-evitara-que-te-infectes-de-covid-19-y-otras-enfermedades\/\" title=\"L\u00e1vate las manos con agua y jab\u00f3n por 20 segundos, esto evitar\u00e1 que te infectes de Covid-19 y otras enfermedades.\u00a0\" rel=\"bookmark\">L\u00e1vate las manos con agua y jab\u00f3n por 20 segundos, esto evitar\u00e1 que te infectes de Covid-19 y otras enfermedades.\u00a0<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/07\/lavate-las-manos-con-agua-y-jabon-por-20-segundos-esto-evitara-que-te-infectes-de-covid-19-y-otras-enfermedades\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about L\u00e1vate las manos con agua y jab\u00f3n por 20 segundos, esto evitar\u00e1 que te infectes de Covid-19 y otras enfermedades.\u00a0\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4503\" data-date=\"2022-07-06T09:44:00-06:00\" data-name=\"\u00a1Yo me cuido y cuido a todos a mi alrededor!\"><article class=\"post project-odd visible post-4503 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-covid-19 category-20 description-off\" data-name=\"\u00a1Yo me cuido y cuido a todos a mi alrededor!\" data-date=\"2022-07-06T09:44:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/06\/yo-me-cuido-y-cuido-a-todos-a-mi-alrededor\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-4.49.04-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-4.49.04-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-4.49.04-PM-1080x674.jpeg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-07-05-at-4.49.04-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/06\/yo-me-cuido-y-cuido-a-todos-a-mi-alrededor\/\" title=\"\u00a1Yo me cuido y cuido a todos a mi alrededor!\" rel=\"bookmark\">\u00a1Yo me cuido y cuido a todos a mi alrededor!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/06\/yo-me-cuido-y-cuido-a-todos-a-mi-alrededor\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Yo me cuido y cuido a todos a mi alrededor!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4506\" data-date=\"2022-07-05T09:48:00-06:00\" data-name=\"Continua utilizando tu mascarilla en lugares p\u00fablicos\"><article class=\"post project-odd visible post-4506 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-covid-19 category-20 description-off\" data-name=\"Continua utilizando tu mascarilla en lugares p\u00fablicos\" data-date=\"2022-07-05T09:48:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/05\/continua-utilizando-tu-mascarilla-en-lugares-publicos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-1.29.18-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-1.29.18-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-05-at-1.29.18-PM-1080x674.jpeg 1080w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-07-05-at-1.29.18-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/05\/continua-utilizando-tu-mascarilla-en-lugares-publicos\/\" title=\"Continua utilizando tu mascarilla en lugares p\u00fablicos\" rel=\"bookmark\">Continua utilizando tu mascarilla en lugares p\u00fablicos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/05\/continua-utilizando-tu-mascarilla-en-lugares-publicos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continua utilizando tu mascarilla en lugares p\u00fablicos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4509\" data-date=\"2022-07-01T09:55:00-06:00\" data-name=\"\u00a1Impulsando desarrollo y progreso al pa\u00eds!\"><article class=\"post project-odd visible post-4509 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Impulsando desarrollo y progreso al pa\u00eds!\" data-date=\"2022-07-01T09:55:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/01\/impulsando-desarrollo-y-progreso-al-pais\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-01-at-1.25.03-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-01-at-1.25.03-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-07-01-at-1.25.03-PM-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-07-01-at-1.25.03-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/01\/impulsando-desarrollo-y-progreso-al-pais\/\" title=\"\u00a1Impulsando desarrollo y progreso al pa\u00eds!\" rel=\"bookmark\">\u00a1Impulsando desarrollo y progreso al pa\u00eds!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/07\/01\/impulsando-desarrollo-y-progreso-al-pais\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Impulsando desarrollo y progreso al pa\u00eds!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4512\" data-date=\"2022-06-30T09:58:00-06:00\" data-name=\"Feliz D\u00eda del Ej\u00e9rcito.\"><article class=\"post project-odd visible post-4512 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Feliz D\u00eda del Ej\u00e9rcito.\" data-date=\"2022-06-30T09:58:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/30\/feliz-dia-del-ejercito\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-29-at-2.21.48-PM-720x450.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-29-at-2.21.48-PM-720x450.jpeg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"WhatsApp Image 2022-06-29 at 2.21.48 PM\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/30\/feliz-dia-del-ejercito\/\" title=\"Feliz D\u00eda del Ej\u00e9rcito.\" rel=\"bookmark\">Feliz D\u00eda del Ej\u00e9rcito.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/30\/feliz-dia-del-ejercito\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Feliz D\u00eda del Ej\u00e9rcito.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4516\" data-date=\"2022-06-27T10:02:00-06:00\" data-name=\"Seguimos trabajando en el desarrollo de pa\u00eds, avanzan los trabajos en carretera de San Francisco, Pet\u00e9n\"><article class=\"post project-odd visible post-4516 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Seguimos trabajando en el desarrollo de pa\u00eds, avanzan los trabajos en carretera de San Francisco, Pet\u00e9n\" data-date=\"2022-06-27T10:02:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/27\/seguimos-trabajando-en-el-desarrollo-de-pais-avanzan-los-trabajos-en-carretera-de-san-francisco-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-27-at-3.59.00-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-27-at-3.59.00-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-27-at-3.59.00-PM-1485x927.jpeg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-06-27-at-3.59.00-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/27\/seguimos-trabajando-en-el-desarrollo-de-pais-avanzan-los-trabajos-en-carretera-de-san-francisco-peten\/\" title=\"Seguimos trabajando en el desarrollo de pa\u00eds, avanzan los trabajos en carretera de San Francisco, Pet\u00e9n\" rel=\"bookmark\">Seguimos trabajando en el desarrollo de pa\u00eds, avanzan los trabajos en carretera de San Francisco, Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/27\/seguimos-trabajando-en-el-desarrollo-de-pais-avanzan-los-trabajos-en-carretera-de-san-francisco-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Seguimos trabajando en el desarrollo de pa\u00eds, avanzan los trabajos en carretera de San Francisco, Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4546\" data-date=\"2022-06-21T05:06:00-06:00\" data-name=\"Mant\u00e9n tu distancia, evita accidentes\u00a0\ufffc\ufffc\ufffc\"><article class=\"post project-odd visible post-4546 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Mant\u00e9n tu distancia, evita accidentes\u00a0\ufffc\ufffc\ufffc\" data-date=\"2022-06-21T05:06:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/21\/manten-tu-distancia-evita-accidentes-%ef%bf%bc%ef%bf%bc%ef%bf%bc\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20500%20312&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-21-at-2.18.19-PM-500x312.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-06-21-at-2.18.19-PM-500x312.jpeg 500w\" loading=\"eager\" style=\"--ratio: 500 \/ 312\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"WhatsApp-Image-2022-06-21-at-2.18.19-PM\" width=\"500\" height=\"312\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/21\/manten-tu-distancia-evita-accidentes-%ef%bf%bc%ef%bf%bc%ef%bf%bc\/\" title=\"Mant\u00e9n tu distancia, evita accidentes\u00a0\ufffc\ufffc\ufffc\" rel=\"bookmark\">Mant\u00e9n tu distancia, evita accidentes\u00a0\ufffc\ufffc\ufffc<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/21\/manten-tu-distancia-evita-accidentes-%ef%bf%bc%ef%bf%bc%ef%bf%bc\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Mant\u00e9n tu distancia, evita accidentes\u00a0\ufffc\ufffc\ufffc\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3764\" data-date=\"2022-06-17T16:05:04-06:00\" data-name=\"El coordinador ejecutivo del Fondo Social de Solidaridad -FSS- Manuel Alfonso Castellanos Alonzo, felicit\u00f3 a los padres del FSS en su d\u00eda\"><article class=\"post project-odd visible post-3764 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-padres category-20 description-off\" data-name=\"El coordinador ejecutivo del Fondo Social de Solidaridad -FSS- Manuel Alfonso Castellanos Alonzo, felicit\u00f3 a los padres del FSS en su d\u00eda\" data-date=\"2022-06-17T16:05:04-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/felicito-a-los-padres-del-fss-en-su-dia\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/dia-del-padre-fss-01-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/dia-del-padre-fss-01-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/dia-del-padre-fss-01-1485x927.jpg 1485w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"dia-del-padre-fss-01\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/felicito-a-los-padres-del-fss-en-su-dia\/\" title=\"El coordinador ejecutivo del Fondo Social de Solidaridad -FSS- Manuel Alfonso Castellanos Alonzo, felicit\u00f3 a los padres del FSS en su d\u00eda\" rel=\"bookmark\">El coordinador ejecutivo del Fondo Social de Solidaridad -FSS- Manuel Alfonso Castellanos Alonzo, felicit\u00f3 a los padres del FSS en su d\u00eda<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/felicito-a-los-padres-del-fss-en-su-dia\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/felicito-a-los-padres-del-fss-en-su-dia\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El coordinador ejecutivo del Fondo Social de Solidaridad -FSS- Manuel Alfonso Castellanos Alonzo, felicit\u00f3 a los padres del FSS en su d\u00eda\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4558\" data-date=\"2022-06-17T09:51:00-06:00\" data-name=\"\u00a1Feliz D\u00eda del Padre!\"><article class=\"post project-odd visible post-4558 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"\u00a1Feliz D\u00eda del Padre!\" data-date=\"2022-06-17T09:51:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/feliz-dia-del-padre\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/288811845_394627439375173_3481720203558803608_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/288811845_394627439375173_3481720203558803608_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/288811845_394627439375173_3481720203558803608_n-1024x639.jpg 1024w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"288811845_394627439375173_3481720203558803608_n\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/feliz-dia-del-padre\/\" title=\"\u00a1Feliz D\u00eda del Padre!\" rel=\"bookmark\">\u00a1Feliz D\u00eda del Padre!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/17\/feliz-dia-del-padre\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Feliz D\u00eda del Padre!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3778\" data-date=\"2022-06-16T17:12:31-06:00\" data-name=\"En el municipio de San Jos\u00e9, Escuintla, continuamos con las acciones que transforman nuestra Guatemala\"><article class=\"post project-odd visible post-3778 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"En el municipio de San Jos\u00e9, Escuintla, continuamos con las acciones que transforman nuestra Guatemala\" data-date=\"2022-06-16T17:12:31-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/16\/en-el-municipio-de-san-jose-escuintla-continuamos-con-las-acciones-que-transforman-nuestra-guatemala\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/san-jose-escuintla-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/san-jose-escuintla-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/san-jose-escuintla-1230x768.jpg 1230w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"san-jose-escuintla\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/16\/en-el-municipio-de-san-jose-escuintla-continuamos-con-las-acciones-que-transforman-nuestra-guatemala\/\" title=\"En el municipio de San Jos\u00e9, Escuintla, continuamos con las acciones que transforman nuestra Guatemala\" rel=\"bookmark\">En el municipio de San Jos\u00e9, Escuintla, continuamos con las acciones que transforman nuestra Guatemala<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/16\/en-el-municipio-de-san-jose-escuintla-continuamos-con-las-acciones-que-transforman-nuestra-guatemala\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/16\/en-el-municipio-de-san-jose-escuintla-continuamos-con-las-acciones-que-transforman-nuestra-guatemala\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about En el municipio de San Jos\u00e9, Escuintla, continuamos con las acciones que transforman nuestra Guatemala\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3781\" data-date=\"2022-06-14T17:20:14-06:00\" data-name=\"S\u00edguenos en Instagram, estamos como: fondosocialdesolidaridadgt\"><article class=\"post project-odd visible post-3781 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-instagram tag-noticias category-20 description-off\" data-name=\"S\u00edguenos en Instagram, estamos como: fondosocialdesolidaridadgt\" data-date=\"2022-06-14T17:20:14-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/instagram-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/instagram-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"instagram\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram\/\" title=\"S\u00edguenos en Instagram, estamos como: fondosocialdesolidaridadgt\" rel=\"bookmark\">S\u00edguenos en Instagram, estamos como: fondosocialdesolidaridadgt<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about S\u00edguenos en Instagram, estamos como: fondosocialdesolidaridadgt\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4562\" data-date=\"2022-06-14T09:04:00-06:00\" data-name=\"S\u00edguenos en Instagram\"><article class=\"post project-odd visible post-4562 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"S\u00edguenos en Instagram\" data-date=\"2022-06-14T09:04:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram-2\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-05-20-at-1.33.59-PM-990x618.jpeg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-05-20-at-1.33.59-PM-990x618.jpeg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-05-20-at-1.33.59-PM-1000x624.jpeg 1000w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"WhatsApp-Image-2022-05-20-at-1.33.59-PM\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram-2\/\" title=\"S\u00edguenos en Instagram\" rel=\"bookmark\">S\u00edguenos en Instagram<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/14\/siguenos-en-instagram-2\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about S\u00edguenos en Instagram\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3790\" data-date=\"2022-06-08T18:11:28-06:00\" data-name=\"Revisa tu veh\u00edculo constantemente, en \u00e9poca de lluvias\"><article class=\"post project-odd visible post-3790 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-lluvias tag-noticias category-20 description-off\" data-name=\"Revisa tu veh\u00edculo constantemente, en \u00e9poca de lluvias\" data-date=\"2022-06-08T18:11:28-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/08\/revisa-tu-vehiculo-constantemente-en-epoca-de-lluvias\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"lluvias\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/08\/revisa-tu-vehiculo-constantemente-en-epoca-de-lluvias\/\" title=\"Revisa tu veh\u00edculo constantemente, en \u00e9poca de lluvias\" rel=\"bookmark\">Revisa tu veh\u00edculo constantemente, en \u00e9poca de lluvias<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/08\/revisa-tu-vehiculo-constantemente-en-epoca-de-lluvias\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/08\/revisa-tu-vehiculo-constantemente-en-epoca-de-lluvias\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Revisa tu veh\u00edculo constantemente, en \u00e9poca de lluvias\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3796\" data-date=\"2022-06-06T18:21:02-06:00\" data-name=\"Estamos trabajando en comunidades de Santa Cruz Barillas, Huehuetenango.\"><article class=\"post project-odd visible post-3796 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias category-20 description-off\" data-name=\"Estamos trabajando en comunidades de Santa Cruz Barillas, Huehuetenango.\" data-date=\"2022-06-06T18:21:02-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/06\/estamos-trabajando-en-comunidades-de-santa-cruz-barillas-huehuetenango\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/carreteras-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/carreteras-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"carreteras\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/06\/estamos-trabajando-en-comunidades-de-santa-cruz-barillas-huehuetenango\/\" title=\"Estamos trabajando en comunidades de Santa Cruz Barillas, Huehuetenango.\" rel=\"bookmark\">Estamos trabajando en comunidades de Santa Cruz Barillas, Huehuetenango.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/06\/estamos-trabajando-en-comunidades-de-santa-cruz-barillas-huehuetenango\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/06\/estamos-trabajando-en-comunidades-de-santa-cruz-barillas-huehuetenango\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Estamos trabajando en comunidades de Santa Cruz Barillas, Huehuetenango.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3800\" data-date=\"2022-06-01T18:24:50-06:00\" data-name=\"\u00a1Aportando al crecimiento de nuestro pa\u00eds!\"><article class=\"post project-odd visible post-3800 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-escuintla tag-noticias category-20 description-off\" data-name=\"\u00a1Aportando al crecimiento de nuestro pa\u00eds!\" data-date=\"2022-06-01T18:24:50-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/01\/aportando-al-crecimiento-de-nuestro-pais\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/san-jose-escuintla-02-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/san-jose-escuintla-02-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"san-jose-escuintla-02\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/01\/aportando-al-crecimiento-de-nuestro-pais\/\" title=\"\u00a1Aportando al crecimiento de nuestro pa\u00eds!\" rel=\"bookmark\">\u00a1Aportando al crecimiento de nuestro pa\u00eds!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/01\/aportando-al-crecimiento-de-nuestro-pais\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/06\/01\/aportando-al-crecimiento-de-nuestro-pais\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Aportando al crecimiento de nuestro pa\u00eds!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3803\" data-date=\"2022-05-30T18:32:34-06:00\" data-name=\"Estamos trabajando en comunidades de Sanarate, El Progreso.\"><article class=\"post project-odd visible post-3803 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Estamos trabajando en comunidades de Sanarate, El Progreso.\" data-date=\"2022-05-30T18:32:34-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/30\/estamos-trabajando-en-comunidades-de-sanarate-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/progreso-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/progreso-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"progreso\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/30\/estamos-trabajando-en-comunidades-de-sanarate-el-progreso\/\" title=\"Estamos trabajando en comunidades de Sanarate, El Progreso.\" rel=\"bookmark\">Estamos trabajando en comunidades de Sanarate, El Progreso.<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/30\/estamos-trabajando-en-comunidades-de-sanarate-el-progreso\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/30\/estamos-trabajando-en-comunidades-de-sanarate-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Estamos trabajando en comunidades de Sanarate, El Progreso.\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3817\" data-date=\"2022-05-26T19:19:54-06:00\" data-name=\"El Fondo Social de Solidaridad, contin\u00faa con la rehabilitaci\u00f3n del Puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla\"><article class=\"post project-odd visible post-3817 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-escuintla tag-noticias category-20 description-off\" data-name=\"El Fondo Social de Solidaridad, contin\u00faa con la rehabilitaci\u00f3n del Puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla\" data-date=\"2022-05-26T19:19:54-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/26\/rehabilitacion-del-puente-la-naisa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/escuintla-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/escuintla-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"escuintla\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/26\/rehabilitacion-del-puente-la-naisa\/\" title=\"El Fondo Social de Solidaridad, contin\u00faa con la rehabilitaci\u00f3n del Puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla\" rel=\"bookmark\">El Fondo Social de Solidaridad, contin\u00faa con la rehabilitaci\u00f3n del Puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/26\/rehabilitacion-del-puente-la-naisa\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/26\/rehabilitacion-del-puente-la-naisa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about El Fondo Social de Solidaridad, contin\u00faa con la rehabilitaci\u00f3n del Puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3830\" data-date=\"2022-05-24T19:32:50-06:00\" data-name=\"Suscr\u00edbete a nuestro canal de YouTube y ent\u00e9rate de las noticias del Fondo Social de Solidaridad \ud83d\ude9c\ud83d\udea7\ud83d\udc77\u200d\u2642\ufe0f\ud83d\udc77\u200d\u2640\ufe0f\"><article class=\"post project-odd visible post-3830 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias tag-youtube category-20 description-off\" data-name=\"Suscr\u00edbete a nuestro canal de YouTube y ent\u00e9rate de las noticias del Fondo Social de Solidaridad \ud83d\ude9c\ud83d\udea7\ud83d\udc77\u200d\u2642\ufe0f\ud83d\udc77\u200d\u2640\ufe0f\" data-date=\"2022-05-24T19:32:50-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/suscribete-a-nuestro-canal-de-youtube\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/youtube-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/youtube-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"youtube\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/suscribete-a-nuestro-canal-de-youtube\/\" title=\"Suscr\u00edbete a nuestro canal de YouTube y ent\u00e9rate de las noticias del Fondo Social de Solidaridad \ud83d\ude9c\ud83d\udea7\ud83d\udc77\u200d\u2642\ufe0f\ud83d\udc77\u200d\u2640\ufe0f\" rel=\"bookmark\">Suscr\u00edbete a nuestro canal de YouTube y ent\u00e9rate de las noticias del Fondo Social de Solidaridad \ud83d\ude9c\ud83d\udea7\ud83d\udc77\u200d\u2642\ufe0f\ud83d\udc77\u200d\u2640\ufe0f<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/suscribete-a-nuestro-canal-de-youtube\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/suscribete-a-nuestro-canal-de-youtube\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Suscr\u00edbete a nuestro canal de YouTube y ent\u00e9rate de las noticias del Fondo Social de Solidaridad \ud83d\ude9c\ud83d\udea7\ud83d\udc77\u200d\u2642\ufe0f\ud83d\udc77\u200d\u2640\ufe0f\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3820\" data-date=\"2022-05-24T19:24:35-06:00\" data-name=\"Al encender las luces de tu auto, ayudas a que el conductor de enfrente pueda verte con facilidad \ud83e\udd29\ud83d\ude96\ud83d\udca1 #AccionesQue Transforman\"><article class=\"post project-odd visible post-3820 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-lluvias tag-noticias category-20 description-off\" data-name=\"Al encender las luces de tu auto, ayudas a que el conductor de enfrente pueda verte con facilidad \ud83e\udd29\ud83d\ude96\ud83d\udca1 #AccionesQue Transforman\" data-date=\"2022-05-24T19:24:35-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/al-encender-las-luces-de-tu-auto-ayudas-a-que-el-conductor-de-enfrente-pueda-verte-con-facilidad-%f0%9f%a4%a9%f0%9f%9a%96%f0%9f%92%a1-accionesque-transforman\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-01-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-01-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"lluvias-01\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/al-encender-las-luces-de-tu-auto-ayudas-a-que-el-conductor-de-enfrente-pueda-verte-con-facilidad-%f0%9f%a4%a9%f0%9f%9a%96%f0%9f%92%a1-accionesque-transforman\/\" title=\"Al encender las luces de tu auto, ayudas a que el conductor de enfrente pueda verte con facilidad \ud83e\udd29\ud83d\ude96\ud83d\udca1 #AccionesQue Transforman\" rel=\"bookmark\">Al encender las luces de tu auto, ayudas a que el conductor de enfrente pueda verte con facilidad \ud83e\udd29\ud83d\ude96\ud83d\udca1 #AccionesQue Transforman<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/al-encender-las-luces-de-tu-auto-ayudas-a-que-el-conductor-de-enfrente-pueda-verte-con-facilidad-%f0%9f%a4%a9%f0%9f%9a%96%f0%9f%92%a1-accionesque-transforman\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/24\/al-encender-las-luces-de-tu-auto-ayudas-a-que-el-conductor-de-enfrente-pueda-verte-con-facilidad-%f0%9f%a4%a9%f0%9f%9a%96%f0%9f%92%a1-accionesque-transforman\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Al encender las luces de tu auto, ayudas a que el conductor de enfrente pueda verte con facilidad \ud83e\udd29\ud83d\ude96\ud83d\udca1 #AccionesQue Transforman\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3825\" data-date=\"2022-05-20T19:26:24-06:00\" data-name=\"Nuestras condolencias para nuestro compa\u00f1ero Jos\u00e9 Garc\u00eda y su familia\"><article class=\"post project-odd visible post-3825 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Nuestras condolencias para nuestro compa\u00f1ero Jos\u00e9 Garc\u00eda y su familia\" data-date=\"2022-05-20T19:26:24-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/20\/nuestras-condolencias-para-nuestro-companero-jose-garcia-y-su-familia\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/condolencias-etelvina-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/condolencias-etelvina-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/condolencias-etelvina-1280x799.jpg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"condolencias-etelvina\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/20\/nuestras-condolencias-para-nuestro-companero-jose-garcia-y-su-familia\/\" title=\"Nuestras condolencias para nuestro compa\u00f1ero Jos\u00e9 Garc\u00eda y su familia\" rel=\"bookmark\">Nuestras condolencias para nuestro compa\u00f1ero Jos\u00e9 Garc\u00eda y su familia<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/20\/nuestras-condolencias-para-nuestro-companero-jose-garcia-y-su-familia\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/20\/nuestras-condolencias-para-nuestro-companero-jose-garcia-y-su-familia\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Nuestras condolencias para nuestro compa\u00f1ero Jos\u00e9 Garc\u00eda y su familia\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3829\" data-date=\"2022-05-17T19:34:13-06:00\" data-name=\"En \u00e9poca de lluvia es importante que tomes tus precauciones para evitar accidentes\ud83c\udf02\ud83c\udf27\u2614\ufe0f\"><article class=\"post project-odd visible post-3829 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-lluvias tag-noticias category-20 description-off\" data-name=\"En \u00e9poca de lluvia es importante que tomes tus precauciones para evitar accidentes\ud83c\udf02\ud83c\udf27\u2614\ufe0f\" data-date=\"2022-05-17T19:34:13-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/17\/en-epoca-de-lluvia-es-importante\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-02-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/lluvias-02-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"lluvias-02\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/17\/en-epoca-de-lluvia-es-importante\/\" title=\"En \u00e9poca de lluvia es importante que tomes tus precauciones para evitar accidentes\ud83c\udf02\ud83c\udf27\u2614\ufe0f\" rel=\"bookmark\">En \u00e9poca de lluvia es importante que tomes tus precauciones para evitar accidentes\ud83c\udf02\ud83c\udf27\u2614\ufe0f<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/17\/en-epoca-de-lluvia-es-importante\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/17\/en-epoca-de-lluvia-es-importante\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about En \u00e9poca de lluvia es importante que tomes tus precauciones para evitar accidentes\ud83c\udf02\ud83c\udf27\u2614\ufe0f\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"3836\" data-date=\"2022-05-11T19:37:39-06:00\" data-name=\"Continuamos con los trabajos en El Progreso, llevando desarrollo a los guatemaltecos\"><article class=\"post project-odd visible post-3836 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-carreteras tag-noticias category-20 description-off\" data-name=\"Continuamos con los trabajos en El Progreso, llevando desarrollo a los guatemaltecos\" data-date=\"2022-05-11T19:37:39-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/11\/continuamos-con-los-trabajos-en-el-progreso\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20720%20450&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/progreso-01-720x450.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/06\/progreso-01-720x450.jpg 720w\" loading=\"eager\" style=\"--ratio: 720 \/ 450\" sizes=\"(max-width: 720px) 100vw, 720px\" alt=\"\" title=\"progreso-01\" width=\"720\" height=\"450\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/11\/continuamos-con-los-trabajos-en-el-progreso\/\" title=\"Continuamos con los trabajos en El Progreso, llevando desarrollo a los guatemaltecos\" rel=\"bookmark\">Continuamos con los trabajos en El Progreso, llevando desarrollo a los guatemaltecos<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/11\/continuamos-con-los-trabajos-en-el-progreso\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/05\/11\/continuamos-con-los-trabajos-en-el-progreso\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Continuamos con los trabajos en El Progreso, llevando desarrollo a los guatemaltecos\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4391\" data-date=\"2022-01-27T09:29:00-06:00\" data-name=\"Informe general de la Rep\u00fablica 2021: San Luis Pet\u00e9n\"><article class=\"post project-odd visible post-4391 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-noticias category-20 description-off\" data-name=\"Informe general de la Rep\u00fablica 2021: San Luis Pet\u00e9n\" data-date=\"2022-01-27T09:29:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/27\/informe-general-de-la-republica-2021-san-luis-peten\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20500&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 500\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\" title=\"2021 Informe general de la Rep\u00fablica\" width=\"800\" height=\"500\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/27\/informe-general-de-la-republica-2021-san-luis-peten\/\" title=\"Informe general de la Rep\u00fablica 2021: San Luis Pet\u00e9n\" rel=\"bookmark\">Informe general de la Rep\u00fablica 2021: San Luis Pet\u00e9n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/27\/informe-general-de-la-republica-2021-san-luis-peten\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Informe general de la Rep\u00fablica 2021: San Luis Pet\u00e9n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4407\" data-date=\"2022-01-26T05:35:00-06:00\" data-name=\"En Santo Domingo Suchitepequez \u00a1Trabajamos para los guatemaltecos!\"><article class=\"post project-odd visible post-4407 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-noticias category-20 description-off\" data-name=\"En Santo Domingo Suchitepequez \u00a1Trabajamos para los guatemaltecos!\" data-date=\"2022-01-26T05:35:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/26\/en-santo-domingo-suchitepequez-trabajamos-para-los-guatemaltecos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20526%20328&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/272662071_2904407936518135_8538774569430706060_n-526x328.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/272662071_2904407936518135_8538774569430706060_n-526x328.jpg 526w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/272662071_2904407936518135_8538774569430706060_n-526x329.jpg 526w\" loading=\"eager\" style=\"--ratio: 526 \/ 328\" sizes=\"(max-width: 526px) 100vw, 526px\" alt=\"\" title=\"272662071_2904407936518135_8538774569430706060_n\" width=\"526\" height=\"328\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/26\/en-santo-domingo-suchitepequez-trabajamos-para-los-guatemaltecos\/\" title=\"En Santo Domingo Suchitepequez \u00a1Trabajamos para los guatemaltecos!\" rel=\"bookmark\">En Santo Domingo Suchitepequez \u00a1Trabajamos para los guatemaltecos!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/26\/en-santo-domingo-suchitepequez-trabajamos-para-los-guatemaltecos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about En Santo Domingo Suchitepequez \u00a1Trabajamos para los guatemaltecos!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4386\" data-date=\"2022-01-24T21:22:00-06:00\" data-name=\"Informe General de la Rep\u00fablica 2021: Quich\u00e9\"><article class=\"post project-odd visible post-4386 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-noticias category-20 description-off\" data-name=\"Informe General de la Rep\u00fablica 2021: Quich\u00e9\" data-date=\"2022-01-24T21:22:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/24\/informe-general-de-la-republica-2021-quiche\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20500&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 500\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\" title=\"2021 Informe general de la Rep\u00fablica\" width=\"800\" height=\"500\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/24\/informe-general-de-la-republica-2021-quiche\/\" title=\"Informe General de la Rep\u00fablica 2021: Quich\u00e9\" rel=\"bookmark\">Informe General de la Rep\u00fablica 2021: Quich\u00e9<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/24\/informe-general-de-la-republica-2021-quiche\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Informe General de la Rep\u00fablica 2021: Quich\u00e9\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4410\" data-date=\"2022-01-19T05:52:00-06:00\" data-name=\"Informe General de la Rep\u00fablica 2021: Conguaco Jutiapa\"><article class=\"post project-odd visible post-4410 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-noticias category-20 description-off\" data-name=\"Informe General de la Rep\u00fablica 2021: Conguaco Jutiapa\" data-date=\"2022-01-19T05:52:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/19\/informe-general-de-la-republica-conguaco-jutiapa\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20500&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 500\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\" title=\"2021 Informe general de la Rep\u00fablica\" width=\"800\" height=\"500\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/19\/informe-general-de-la-republica-conguaco-jutiapa\/\" title=\"Informe General de la Rep\u00fablica 2021: Conguaco Jutiapa\" rel=\"bookmark\">Informe General de la Rep\u00fablica 2021: Conguaco Jutiapa<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/19\/informe-general-de-la-republica-conguaco-jutiapa\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Informe General de la Rep\u00fablica 2021: Conguaco Jutiapa\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4341\" data-date=\"2022-01-13T21:59:00-06:00\" data-name=\"\u00a1M\u00e1s de 112 mil beneficiados!\"><article class=\"post project-odd visible post-4341 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-coordinador tag-fotos tag-maquinaria tag-noticias category-20 media-wide description-off\" data-name=\"\u00a1M\u00e1s de 112 mil beneficiados!\" data-date=\"2022-01-13T21:59:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/13\/mas-de-112-mil-beneficiados%ef%bf%bc\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/245553364_2895622720729990_2529252460079889190_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/245553364_2895622720729990_2529252460079889190_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"Coord-Manuel 1\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/13\/mas-de-112-mil-beneficiados%ef%bf%bc\/\" title=\"\u00a1M\u00e1s de 112 mil beneficiados!\" rel=\"bookmark\">\u00a1M\u00e1s de 112 mil beneficiados!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/13\/mas-de-112-mil-beneficiados%ef%bf%bc\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1M\u00e1s de 112 mil beneficiados!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4331\" data-date=\"2022-01-07T09:05:00-06:00\" data-name=\"VACUNATE: Dosis de Refuerzo\"><article class=\"post project-odd visible post-4331 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes tag-covid-19 category-20 description-off\" data-name=\"VACUNATE: Dosis de Refuerzo\" data-date=\"2022-01-07T09:05:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/07\/vacunate-dosis-de-refuerzo\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270429318_2891359961156266_3792097028344589321_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270429318_2891359961156266_3792097028344589321_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270429318_2891359961156266_3792097028344589321_n-1280x799.jpg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"Vacunaciones\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/07\/vacunate-dosis-de-refuerzo\/\" title=\"VACUNATE: Dosis de Refuerzo\" rel=\"bookmark\">VACUNATE: Dosis de Refuerzo<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/07\/vacunate-dosis-de-refuerzo\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/07\/vacunate-dosis-de-refuerzo\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about VACUNATE: Dosis de Refuerzo\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4356\" data-date=\"2022-01-03T10:22:00-06:00\" data-name=\"Informe General de la Rep\u00fablica 2021: San Mateo Ixtat\u00e1n\"><article class=\"post project-odd visible post-4356 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"Informe General de la Rep\u00fablica 2021: San Mateo Ixtat\u00e1n\" data-date=\"2022-01-03T10:22:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/informe-general-de-la-republica-2021\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20500&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/header-tw-800x500.png 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 500\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"\" title=\"2021 Informe general de la Rep\u00fablica\" width=\"800\" height=\"500\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/informe-general-de-la-republica-2021\/\" title=\"Informe General de la Rep\u00fablica 2021: San Mateo Ixtat\u00e1n\" rel=\"bookmark\">Informe General de la Rep\u00fablica 2021: San Mateo Ixtat\u00e1n<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/informe-general-de-la-republica-2021\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about Informe General de la Rep\u00fablica 2021: San Mateo Ixtat\u00e1n\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4317\" data-date=\"2022-01-03T07:55:00-06:00\" data-name=\"En San Luis Pet\u00e9n \u00a1Trabajamos para los Guatemaltecos!\"><article class=\"post project-odd visible post-4317 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 description-off\" data-name=\"En San Luis Pet\u00e9n \u00a1Trabajamos para los Guatemaltecos!\" data-date=\"2022-01-03T07:55:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/en-san-luis-peten-trabajamos-para-los-guatemaltecos\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20990%20618&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270306728_2889369491355313_4331368641393906775_n-990x618.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270306728_2889369491355313_4331368641393906775_n-990x618.jpg 990w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270306728_2889369491355313_4331368641393906775_n-1280x799.jpg 1280w\" loading=\"eager\" style=\"--ratio: 990 \/ 618\" sizes=\"(max-width: 990px) 100vw, 990px\" alt=\"\" title=\"Testimonio San Luis\" width=\"990\" height=\"618\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/en-san-luis-peten-trabajamos-para-los-guatemaltecos\/\" title=\"En San Luis Pet\u00e9n \u00a1Trabajamos para los Guatemaltecos!\" rel=\"bookmark\">En San Luis Pet\u00e9n \u00a1Trabajamos para los Guatemaltecos!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/en-san-luis-peten-trabajamos-para-los-guatemaltecos\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2022\/01\/03\/en-san-luis-peten-trabajamos-para-los-guatemaltecos\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about En San Luis Pet\u00e9n \u00a1Trabajamos para los Guatemaltecos!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><div class=\"hidden wf-cell\" data-post-id=\"4295\" data-date=\"2021-12-31T23:00:00-06:00\" data-name=\"\u00a1Feliz a\u00f1o nuevo!\"><article class=\"post project-odd visible post-4295 type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-artes category-20 media-wide description-off\" data-name=\"\u00a1Feliz a\u00f1o nuevo!\" data-date=\"2021-12-31T23:00:00-06:00\">\n\n<div class=\"post-thumbnail-wrap\">\n\t<div class=\"post-thumbnail\">\n\t\t\n\t\t\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2021\/12\/31\/feliz-ano-nuevo\/\" class=\"post-thumbnail-rollover layzr-bg layzr-bg\" ><img decoding=\"async\" class=\"iso-lazy-load preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20960%20599&#39;%2F%3E\" data-src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270069521_2886787211613541_7624911592253056079_n-960x599.jpg\" data-srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270069521_2886787211613541_7624911592253056079_n-960x599.jpg 960w\" loading=\"eager\" style=\"--ratio: 960 \/ 599\" sizes=\"(max-width: 960px) 100vw, 960px\" alt=\"\" title=\"A\u00f1o nuevo\" width=\"960\" height=\"599\"  \/><\/a>\t<\/div>\n<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"entry-title\">\n\t\t<a href=\"https:\/\/fss.gob.gt\/es\/2021\/12\/31\/feliz-ano-nuevo\/\" title=\"\u00a1Feliz a\u00f1o nuevo!\" rel=\"bookmark\">\u00a1Feliz a\u00f1o nuevo!<\/a>\n\t<\/h3>\n\n\t<div class=\"entry-meta\"><span class=\"category-link\"><a href=\"https:\/\/fss.gob.gt\/es\/category\/noticias\/\" >Noticias<\/a><\/span><a href=\"https:\/\/fss.gob.gt\/es\/2021\/12\/31\/feliz-ano-nuevo\/#respond\" class=\"comment-link\" >Deja un comentario<\/a><\/div>\n\t\n\t\n<a href=\"https:\/\/fss.gob.gt\/es\/2021\/12\/31\/feliz-ano-nuevo\/\" class=\"dt-btn-s dt-btn post-details details-type-btn\" aria-label=\"Read more about \u00a1Feliz a\u00f1o nuevo!\">Leer noticia<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><div class=\"paginator paginator-more-button\">\n\t\t\t\t<a class=\"button-load-more \" href=\"javascript:void(0);\" data-dt-page=\"1\" ><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"button-caption\">Cargar m\u00e1s<\/span><\/a>\n\t\t\t<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column css=\u00bb.vc_custom_1575296582826{padding-bottom: 30px !important;}\u00bb][\/vc_column][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1491","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/pages\/1491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/comments?post=1491"}],"version-history":[{"count":5,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/pages\/1491\/revisions"}],"predecessor-version":[{"id":7289,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/pages\/1491\/revisions\/7289"}],"wp:attachment":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/media?parent=1491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}