{"id":4341,"date":"2022-01-13T21:59:00","date_gmt":"2022-01-13T21:59:00","guid":{"rendered":"https:\/\/fss.gob.gt\/es\/?p=4341"},"modified":"2022-10-03T22:01:04","modified_gmt":"2022-10-03T22:01:04","slug":"mas-de-112-mil-beneficiados%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/fss.gob.gt\/es\/2022\/01\/13\/mas-de-112-mil-beneficiados%ef%bf%bc\/","title":{"rendered":"\u00a1M\u00e1s de 112 mil beneficiados!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de la pol\u00edtica General de Gobierno del presidente Dr. Alejandro Giammattei, el coordinador ejecutivo del Fondo Social de Solidaridad, Lic Manuel Alfonso Castellanos Alonzo, inaugur\u00f3 los trabajos de reposici\u00f3n del puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas obras se beneficiar\u00e1n a 112,780 personas. Adem\u00e1s, ayuda al impulso econ\u00f3mico departamental, que ya el puente es una de las v\u00edas importantes para todo el sur del <a><\/a>pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fondo Social de Solidaridad es parte del Ministerio de Comunicaciones, Infraestructura y Vivienda, que vela por el desarrollo de todos los guatemaltecos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"641\" data-id=\"4346\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270279610_2895622757396653_5205033476790311089_n.jpg\" alt=\"\" class=\"wp-image-4346\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270279610_2895622757396653_5205033476790311089_n.jpg 960w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270279610_2895622757396653_5205033476790311089_n-300x200.jpg 300w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/270279610_2895622757396653_5205033476790311089_n-768x513.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption>Inicio de obras en puente La Naisa<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" data-id=\"4345\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/271638701_2895622790729983_5456284108865564260_n.jpg\" alt=\"\" class=\"wp-image-4345\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/271638701_2895622790729983_5456284108865564260_n.jpg 960w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/271638701_2895622790729983_5456284108865564260_n-300x200.jpg 300w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2022\/10\/271638701_2895622790729983_5456284108865564260_n-768x512.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption>Inicio de obras en puente La Naisa<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de la pol\u00edtica General de Gobierno del presidente Dr. Alejandro Giammattei, el coordinador ejecutivo del Fondo Social de Solidaridad, Lic Manuel Alfonso Castellanos Alonzo, inaugur\u00f3 los trabajos de reposici\u00f3n del puente La Naisa, en Santa Luc\u00eda Cotzumalguapa, Escuintla. Con estas obras se beneficiar\u00e1n a 112,780 personas. Adem\u00e1s, ayuda al impulso econ\u00f3mico departamental, que&hellip;<\/p>\n","protected":false},"author":4,"featured_media":4347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[33,34,35,21],"class_list":["post-4341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-coordinador","tag-fotos","tag-maquinaria","tag-noticias","category-20","description-off"],"_links":{"self":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/4341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/comments?post=4341"}],"version-history":[{"count":4,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/4341\/revisions"}],"predecessor-version":[{"id":4355,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/4341\/revisions\/4355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/media\/4347"}],"wp:attachment":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/media?parent=4341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/categories?post=4341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/tags?post=4341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}