{"id":6580,"date":"2024-02-23T15:24:54","date_gmt":"2024-02-23T21:24:54","guid":{"rendered":"https:\/\/fss.gob.gt\/es\/?p=6580"},"modified":"2024-04-17T11:43:03","modified_gmt":"2024-04-17T17:43:03","slug":"supervision-de-mejoramiento-en-la-pista-de-taxeo-del-aeropuerto-internacional-la-aurora","status":"publish","type":"post","link":"https:\/\/fss.gob.gt\/es\/2024\/02\/23\/supervision-de-mejoramiento-en-la-pista-de-taxeo-del-aeropuerto-internacional-la-aurora\/","title":{"rendered":"Supervisi\u00f3n  de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Ministra de Comunicaciones Jazm\u00edn De La Vega realiza supervisi\u00f3n de la entrega del primer tramo de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/twitter.com\/hashtag\/GuatemalaSaleAdelante?src=hashtag_click\">#GuatemalaSaleAdelante<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" data-id=\"6584\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-7.png\" alt=\"\" class=\"wp-image-6584\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-7.png 720w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-7-300x200.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6583\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-6-1024x682.png\" alt=\"\" class=\"wp-image-6583\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-6-1024x682.png 1024w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-6-300x200.png 300w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-6-768x512.png 768w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-6.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"6582\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-5-1024x682.png\" alt=\"\" class=\"wp-image-6582\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-5-1024x682.png 1024w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-5-300x200.png 300w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-5-768x512.png 768w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-5.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"6581\" src=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-4-1024x683.png\" alt=\"\" class=\"wp-image-6581\" srcset=\"https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-4-1024x683.png 1024w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-4-300x200.png 300w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-4-768x512.png 768w, https:\/\/fss.gob.gt\/es\/wp-content\/uploads\/2024\/02\/image-4.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Ministra de Comunicaciones Jazm\u00edn De La Vega realiza supervisi\u00f3n de la entrega del primer tramo de mejoramiento en la pista de taxeo del Aeropuerto Internacional La Aurora. #GuatemalaSaleAdelante<\/p>\n","protected":false},"author":4,"featured_media":6584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[81,21,36],"class_list":["post-6580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-civ","tag-noticias","tag-operaciones","category-20","description-off"],"_links":{"self":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/6580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/comments?post=6580"}],"version-history":[{"count":2,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/6580\/revisions"}],"predecessor-version":[{"id":6700,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/posts\/6580\/revisions\/6700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/media\/6584"}],"wp:attachment":[{"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/media?parent=6580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/categories?post=6580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fss.gob.gt\/es\/wp-json\/wp\/v2\/tags?post=6580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}